{"id":2302,"date":"2017-05-26T20:57:34","date_gmt":"2017-05-26T20:57:34","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/ce-approved-ltd6-3-hoist-motorsuspended-platform-hoistgondola-lift.html"},"modified":"2017-05-26T20:57:34","modified_gmt":"2017-05-26T20:57:34","slug":"ce-approved-ltd6-3-hoist-motorsuspended-platform-hoistgondola-lift","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/ce-approved-ltd6-3-hoist-motorsuspended-platform-hoistgondola-lift.html","title":{"rendered":"ce approved LTD6.3 hoist motor,suspended platform hoist\/gondola lift"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale98.jpg\" alt=\"ce approved LTD6.3 hoist motor,suspended platform hoist\/gondola lift\" \/><br \/>\nImage of ce approved LTD6.3 hoist motor,suspended platform hoist\/gondola lift<\/p>\n<h3 class=\"alpha-title\">Quick Details: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Place of Origin:Shanghai, China (Mainland), LTD63\/LTD80A<\/li>\n<li>Brand Name:Success<\/li>\n<li>Model Number:ltd80<\/li>\n<li>Engine Type:Other<\/li>\n<li>Type:Engine Controller<\/li>\n<li>Keywords:Electric Wire Rope Hoist<\/li>\n<li>Frequency:50HZ<\/li>\n<li>Lifting Speed:9.3m\/min<\/li>\n<li>Power:1.8KW 1.5KW<\/li>\n<li>Power Source:Electric<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Related Video: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pZk9Vb0pIWTVBdVk\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Description: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale248.jpg\" alt=\"ce approved LTD6.3 hoist motor,suspended platform hoist\/gondola lift\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale95.jpg\" alt=\"ce approved LTD6.3 hoist motor,suspended platform hoist\/gondola lift\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Related Accessories Show: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale50.jpg\" alt=\"ce approved LTD6.3 hoist motor,suspended platform hoist\/gondola lift Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale40.jpg\" alt=\"ce approved LTD6.3 hoist motor,suspended platform hoist\/gondola lift Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Leave a message: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">You may also like:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale175.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Aluminum\/Steel ZLP Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Place of Origin:Shanghai, China (Mainland)<\/li>\n<li>Brand Name:Success<\/li>\n<li>Model Number:ZLP630<\/li>\n<li>Lift Mechanism:steel wire rope<\/li>\n<li>Lift Drive \/ Actuation:Hoist<\/li>\n<li>Power:1.5kw*2<\/li>\n<li>Rated Loading Capacity:630kg<\/li>\n<li>Min. Lifting Height:10m<\/li>\n<li>Max. Lifting Height:100m<\/li>\n<li>Table Size:6(1+2+3)*0.72*1.3m,7.5(2.5*3)*0.72*1.3m<\/li>\n<li>Overall Dimensions:1850mm*1000mm*950mm<\/li>\n<li>Weight:850kg<\/li>\n<li>Certification:CE ISO<\/li>\n<li>Warranty:1 Year<\/li>\n<li>After-sales Service Provided:Engineers available to service machinery overseas<\/li>\n<li>Application:clean walls decorat maintain<\/li>\n<li>Name:Suspended platform<\/li>\n<li>Lifting height:100m<\/li>\n<li>Lifting speed:8~10m\/min<\/li>\n<li>cable:100m<\/li>\n<li>Voltage:220v\/380v\/50hz<\/li>\n<li>Color:Red sliver<\/li>\n<li>Material:Steel Aluminum Galvanizing<\/li>\n<li>Keywords:cradle<\/li>\n<li>Feature:Easy Operation safety convenience<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Beirut, Ghaziabad, Kenya  etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp Series Suspend Platforms in Beirut, Zlp Suspended Platform Manufacturers<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Leave a message<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale105.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">FACTORY CE passed zlp800 window cleaning suspended platform\/ rope suspended platform\/ window cleaning cradle<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Place of Origin:Shanghai, China (Mainland)<\/li>\n<li>Brand Name:Success-CHINA<\/li>\n<li>Model Number:ZLP630\/ZLP800<\/li>\n<li>Usage:Building facade or glass cleaning<\/li>\n<li>Model:zlp800 window cleaning suspended platform \/ rope suspended platform<\/li>\n<li>Certificates:ISO, GOST, CE<\/li>\n<li>Power Source:Electricity<\/li>\n<li>Drive Type:Wire rope hoisting<\/li>\n<li>Application:Tall Building Maintenance<\/li>\n<li>Origin:China<\/li>\n<li>Lifting Speed:8-10m\/min<\/li>\n<li>Lifting Height and Cable Length:100m<\/li>\n<li>Voltage:380V \/220V\/410V  or according to  customer need<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Poland, Senegal etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Window Cleaning Platform in Ghaziabad, Zlp 630 Cradle Aluminum Suspended Platform in Kenya <\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Leave a message<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale84.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">mast climbing suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Place of Origin:Shanghai, China (Mainland)<\/li>\n<li>Brand Name:Success<\/li>\n<li>Model Number:ZLP630<\/li>\n<li>Name:Suspended Platform<\/li>\n<li>Color:Red<\/li>\n<li>Load capacity:630kg<\/li>\n<li>Height:100m<\/li>\n<li>Speed:8~10m\/min<\/li>\n<li>Hoist:1.5kw x2<\/li>\n<li>Galvanized steel wir rope:8.3mm<\/li>\n<li>Safe lock:2 sets<\/li>\n<li>Suspension Mechanism:Galvanized<\/li>\n<li>Counter weight:1000kgs<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Agra, Milan, Recife, Beirut etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Rolling Work Platform in Poland, Suspended Access Platform With Steel Material in Senegal<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Leave a message<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale194.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Temporary Suspended Scaffold\/Platform 800kg Load\/10m Length<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Place of Origin:Shanghai, China (Mainland)<\/li>\n<li>Brand Name:Success<\/li>\n<li>Model Number:ZLP800<\/li>\n<li>After-sales Service Provided:Engineers available to service machinery overseas<\/li>\n<li>Material:Steel, Aluminum Alloy<\/li>\n<li>Color:Red, Yellow, Blue, etc<\/li>\n<li>Surface treatment:Powder coating, Hot galvanization<\/li>\n<li>Length:2m, 2.5m, 3m, 5m, 6m, 7.5m, etc<\/li>\n<li>Lifing Mechanism:Gear<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Power:1.5kw, 1.8kw, 2kw<\/li>\n<li>Rated Loading Capacity:150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Max. Lifting Height:200m<\/li>\n<li>Voltage:Temporary Suspended Scaffold accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Tijuana, Swaziland, Recife, Agra etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp Suspended Platform Manufacturers, Suspended Access Platform With Steel Material in Senegal<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Leave a message<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale187.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP 630 Suspended Cradle,Suspended Working Platforms<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Place of Origin:China (Mainland)<\/li>\n<li>Brand Name:Suspended Platform Cradle Gondola<\/li>\n<li>Model Number:ZLP500\/630\/800\/1000<\/li>\n<li>Name:Suspended Rope Platform OR Working Platform<\/li>\n<li>Cradle Platform Application:Building maintainence, cleaning,painting<\/li>\n<li>Roof Fixing:1,suspension with counter 2, parapet clamp<\/li>\n<li>Platform Color:Red,Silver,Hot Galvanized<\/li>\n<li>Safety device:safety lock, safe rope etc<\/li>\n<li>Motive Power:Electric Hoist<\/li>\n<li>Platform Shape:cuboid or special design<\/li>\n<li>Platform standard: CE, GOST, ISO<\/li>\n<li>Platform Material:Steel or Aluminum Alloy<\/li>\n<li>Platform Body:free assembled by modular plate<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Beirut, Kenya , Senegal, Milan etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp Series Suspend Platforms in Beirut, Rolling Work Platform in Poland<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Leave a message<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Image of ce approved LTD6.3 hoist motor,suspended platform hoist\/gondola lift Quick Details: Place of Origin:Shanghai, China (Mainland), LTD63\/LTD80A Brand Name:Success Model Number:ltd80 Engine Type:Other Type:Engine <\/p>\n","protected":false},"author":1,"featured_media":236,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[9652,9653,9650,9651,9649,602],"class_list":["post-2302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-rolling-work-platform-in-poland","tag-suspended-access-platform-with-steel-material-in-senegal","tag-window-cleaning-platform-in-ghaziabad","tag-zlp-630-cradle-aluminum-suspended-platform-in-kenya","tag-zlp-series-suspend-platforms-in-beirut","tag-zlp-suspended-platform-manufacturers"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/wp-json\/wp\/v2\/posts\/2302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/wp-json\/wp\/v2\/comments?post=2302"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/wp-json\/wp\/v2\/posts\/2302\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/wp-json\/wp\/v2\/media\/236"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/wp-json\/wp\/v2\/media?parent=2302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/wp-json\/wp\/v2\/categories?post=2302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/wp-json\/wp\/v2\/tags?post=2302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}