{"id":2663,"date":"2017-05-31T07:10:31","date_gmt":"2017-05-31T07:10:31","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zlp-630-zlp-800-electric-suspended-rope-platform.html"},"modified":"2017-05-31T07:10:31","modified_gmt":"2017-05-31T07:10:31","slug":"zlp-630-zlp-800-electric-suspended-rope-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/ur\/zlp-630-zlp-800-electric-suspended-rope-platform.html","title":{"rendered":"ZLP 630 ZLP 800 electric suspended rope platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale1.jpg\" alt=\"ZLP 630 ZLP 800 electric suspended rope platform\" \/><br \/>\nImage of ZLP 630 ZLP 800 electric suspended rope platform<\/p>\n<h3 class=\"alpha-title\">\u0641\u0648\u0631\u06cc \u062a\u0641\u0635\u06cc\u0644\u0627\u062a: <\/h3>\n<ul class=\"alpha-ali\">\n<li>\u0646\u06a9\u0627\u0644\u0646\u06d2 \u06a9\u0627 \u0645\u0642\u0627\u0645: \u0634\u0646\u06af\u06be\u0627\u0626\u06cc\u060c \u0686\u06cc\u0646 (\u0645\u06cc\u0646 \u0644\u06cc\u0646\u0688)<\/li>\n<li>\u0628\u0631\u0627\u0646\u0688 \u06a9\u0627 \u0646\u0627\u0645: \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc<\/li>\n<li>Model Number:ZLP 630 zlp 800<\/li>\n<li>Cable:3*2.5+2*1.5<\/li>\n<li>\u0644\u0641\u0679\u0646\u06af \u06a9\u06cc \u0631\u0641\u062a\u0627\u0631: 8-10m\/\u0645\u0646\u0679<\/li>\n<li>Material:steel or aluminum alloy<\/li>\n<li>Certificates:ISO, GOST, CE<\/li>\n<li>Lifting Height:100m<\/li>\n<li>Platform Cable:100m<\/li>\n<li>Original:China<\/li>\n<li>Application:ZLP 630 ZLP 800 electric suspended rope platform<\/li>\n<li>\u0648\u0648\u0644\u0679\u06cc\u062c: 220V\/380V\/415V<\/li>\n<li>Color:Red or silver<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0645\u062a\u0639\u0644\u0642\u06c1 \u0648\u06cc\u0688\u06cc\u0648: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pYXdPMlBRcnhWNlU\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u062a\u0641\u0635\u06cc\u0644: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale236.jpg\" alt=\"ZLP 630 ZLP 800 electric suspended rope platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale244.jpg\" alt=\"ZLP 630 ZLP 800 electric suspended rope platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0645\u062a\u0639\u0644\u0642\u06c1 \u0644\u0648\u0627\u0632\u0645\u0627\u062a \u062f\u06a9\u06be\u0627\u0626\u06cc\u06ba: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale30.jpg\" alt=\"ZLP 630 ZLP 800 electric suspended rope platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale8.jpg\" alt=\"ZLP 630 ZLP 800 electric suspended rope platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0627\u06cc\u06a9 \u067e\u06cc\u063a\u0627\u0645 \u0686\u06be\u0648\u0691\u06cc\u06ba: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">\u0622\u067e \u06cc\u06c1 \u0628\u06be\u06cc \u067e\u0633\u0646\u062f \u06a9\u0631 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale268.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Advanced zlp630 suspended aerial working platform \/ gondola\/cradle<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0646\u06a9\u0627\u0644\u0646\u06d2 \u06a9\u0627 \u0645\u0642\u0627\u0645: \u0634\u0646\u06af\u06be\u0627\u0626\u06cc\u060c \u0686\u06cc\u0646 (\u0645\u06cc\u0646 \u0644\u06cc\u0646\u0688)<\/li>\n<li>\u0628\u0631\u0627\u0646\u0688 \u06a9\u0627 \u0646\u0627\u0645: \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc<\/li>\n<li>\u0645\u0627\u0688\u0644 \u0646\u0645\u0628\u0631: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>\u0641\u0631\u0648\u062e\u062a \u06a9\u06d2 \u0628\u0639\u062f \u0633\u0631\u0648\u0633 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u06cc \u06af\u0626\u06cc: \u0628\u06cc\u0631\u0648\u0646 \u0645\u0644\u06a9 \u0633\u0631\u0648\u0633 \u0645\u0634\u06cc\u0646\u0631\u06cc \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u0646\u062c\u06cc\u0646\u0626\u0631 \u062f\u0633\u062a\u06cc\u0627\u0628 \u06c1\u06cc\u06ba\u06d4<\/li>\n<li>Name:zlp630 suspended aerial working platform \/ gondola\/cradle<\/li>\n<li>\u0631\u0646\u06af: \u0627\u062e\u062a\u06cc\u0627\u0631\u06cc<\/li>\n<li>\u0628\u062c\u0644\u06cc \u06a9\u06cc \u0641\u0631\u0627\u06c1\u0645\u06cc (V):220,380,415,440<\/li>\n<li>\u0633\u06cc\u0641\u0679\u06cc \u0688\u06cc\u0648\u0627\u0626\u0633: 7 \u0622\u0626\u0679\u0645<\/li>\n<li>\u0645\u0648\u0627\u062f: \u0627\u0633\u0679\u06cc\u0644 \u06cc\u0627 \u0627\u06cc\u0644\u0648\u0645\u06cc\u0646\u06cc\u0645<\/li>\n<li>\u0633\u0637\u062d \u06a9\u0627 \u0639\u0644\u0627\u062c: \u067e\u06cc\u0646\u0679 \u0627\u0633\u067e\u0631\u06d2 \u06cc\u0627 \u06af\u0631\u0645 \u0688\u0650\u067e \u06af\u0627\u0644\u0648\u0627\u0646\u0627\u0626\u0632\u0646\u06af<\/li>\n<li>\u0645\u0641\u062a \u062d\u0635\u06c1: \u0641\u0631\u0627\u06c1\u0645\u06cc<\/li>\n<li>\u0633\u0679\u06cc\u0644 \u06a9\u06cc \u0631\u0633\u06cc: \u06af\u0631\u0645 \u0688\u0650\u067e \u06af\u0627\u0644\u0648\u0627\u0646\u0627\u0626\u0632\u0646\u06af<\/li>\n<li>\u0644\u06c1\u0631\u0627\u0646\u0627: \u0688\u0627\u0626\u06cc \u06a9\u0627\u0633\u0679\u0646\u06af \u0627\u06cc\u0644\u0648\u0645\u06cc\u0646\u06cc\u0645 \u0633\u06d2 \u0628\u0646\u0627<\/li>\n<li>\u0633\u0631\u0679\u06cc\u0641\u06a9\u06cc\u0679: CE\u060c ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Canada, Honduras, Kalyan-Dombivali etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Electric Motor Hoist For Suspended Platform in Canada, Size Suspended Platform For Chimney<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u0627\u06cc\u06a9 \u067e\u06cc\u063a\u0627\u0645 \u0686\u06be\u0648\u0691\u06cc\u06ba\u06d4<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale50.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Electric Hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Feature:Suspended Platform Hoist<\/li>\n<li>\u062d\u0627\u0644\u062a: \u0646\u06cc\u0627<\/li>\n<li>Application:Lifting suspended platform at height site of high-rise building<\/li>\n<li>\u0634\u0631\u062d \u0634\u062f\u06c1 \u0644\u0648\u0688\u0646\u06af \u06a9\u06cc \u0635\u0644\u0627\u062d\u06cc\u062a: 630 \u06a9\u0644\u0648\u06af\u0631\u0627\u0645<\/li>\n<li>Rated Lifting Moment:15Nm<\/li>\n<li>Max. Lifting Load:630kg<\/li>\n<li>Max. Lifting Height:200m<\/li>\n<li>Span:200m<\/li>\n<li>\u0646\u06a9\u0627\u0644\u0646\u06d2 \u06a9\u0627 \u0645\u0642\u0627\u0645: \u0634\u0646\u06af\u06be\u0627\u0626\u06cc\u060c \u0686\u06cc\u0646 (\u0645\u06cc\u0646 \u0644\u06cc\u0646\u0688)<\/li>\n<li>\u0628\u0631\u0627\u0646\u0688 \u06a9\u0627 \u0646\u0627\u0645: \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc<\/li>\n<li>Model Number:LTD6.3<\/li>\n<li>Lifing Mechanism:Gear<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Guilding System:&quot;a&quot; or &quot;s&quot; type<\/li>\n<li>Rated Lifting Capacity:3KN, 5KN, 6.3KN, 8KN<\/li>\n<li>Brake Torque:15Nm<\/li>\n<li>Rotate Speed:1420r\/min<\/li>\n<li>Power:0.75kw, 1.1kw, 1.5kw, 1.8kw, 2kw<\/li>\n<li>Diameter of Wire rope:8.3mm, 8.6mm<\/li>\n<li>Voltage:Electric Hoist accept different voltage: 220V, 380V, 440V, etc<\/li>\n<li>Advantage\/Merit:Light weight, simple structure, easy maintenance, steady operation<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Montreal, Suwon etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Scaffolding Lift Platform in Honduras, Aluminum Zlp 630 Suspended Working Platform in Kalyan-Dombivali<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u0627\u06cc\u06a9 \u067e\u06cc\u063a\u0627\u0645 \u0686\u06be\u0648\u0691\u06cc\u06ba\u06d4<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale48.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Hot sale articulated suspended working platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0646\u06a9\u0627\u0644\u0646\u06d2 \u06a9\u0627 \u0645\u0642\u0627\u0645: \u0634\u0646\u06af\u06be\u0627\u0626\u06cc\u060c \u0686\u06cc\u0646 (\u0645\u06cc\u0646 \u0644\u06cc\u0646\u0688)<\/li>\n<li>\u0628\u0631\u0627\u0646\u0688 \u06a9\u0627 \u0646\u0627\u0645: \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc<\/li>\n<li>\u0645\u0627\u0688\u0644 \u0646\u0645\u0628\u0631: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>\u0641\u0631\u0648\u062e\u062a \u06a9\u06d2 \u0628\u0639\u062f \u0633\u0631\u0648\u0633 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u06cc \u06af\u0626\u06cc: \u0628\u06cc\u0631\u0648\u0646 \u0645\u0644\u06a9 \u0633\u0631\u0648\u0633 \u0645\u0634\u06cc\u0646\u0631\u06cc \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u0646\u062c\u06cc\u0646\u0626\u0631 \u062f\u0633\u062a\u06cc\u0627\u0628 \u06c1\u06cc\u06ba\u06d4<\/li>\n<li>Name:articulated suspended working platform<\/li>\n<li>\u0631\u0646\u06af: \u0627\u062e\u062a\u06cc\u0627\u0631\u06cc<\/li>\n<li>\u0628\u062c\u0644\u06cc \u06a9\u06cc \u0641\u0631\u0627\u06c1\u0645\u06cc (V):220,380,415,440<\/li>\n<li>\u0633\u06cc\u0641\u0679\u06cc \u0688\u06cc\u0648\u0627\u0626\u0633: 7 \u0622\u0626\u0679\u0645<\/li>\n<li>\u0645\u0648\u0627\u062f: \u0627\u0633\u0679\u06cc\u0644 \u06cc\u0627 \u0627\u06cc\u0644\u0648\u0645\u06cc\u0646\u06cc\u0645<\/li>\n<li>\u0633\u0637\u062d \u06a9\u0627 \u0639\u0644\u0627\u062c: \u067e\u06cc\u0646\u0679 \u0627\u0633\u067e\u0631\u06d2 \u06cc\u0627 \u06af\u0631\u0645 \u0688\u0650\u067e \u06af\u0627\u0644\u0648\u0627\u0646\u0627\u0626\u0632\u0646\u06af<\/li>\n<li>\u0645\u0641\u062a \u062d\u0635\u06c1: \u0641\u0631\u0627\u06c1\u0645\u06cc<\/li>\n<li>\u0633\u0679\u06cc\u0644 \u06a9\u06cc \u0631\u0633\u06cc: \u06af\u0631\u0645 \u0688\u0650\u067e \u06af\u0627\u0644\u0648\u0627\u0646\u0627\u0626\u0632\u0646\u06af<\/li>\n<li>\u0644\u06c1\u0631\u0627\u0646\u0627: \u0688\u0627\u0626\u06cc \u06a9\u0627\u0633\u0679\u0646\u06af \u0627\u06cc\u0644\u0648\u0645\u06cc\u0646\u06cc\u0645 \u0633\u06d2 \u0628\u0646\u0627<\/li>\n<li>\u0633\u0631\u0679\u06cc\u0641\u06a9\u06cc\u0679: CE\u060c ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Allahabad, Bruges, Brescia, Canada etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Wire Rope Suspended Working Platform Equipment in Montreal, Steel Rope Facade Cleaning Platform in Suwon<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u0627\u06cc\u06a9 \u067e\u06cc\u063a\u0627\u0645 \u0686\u06be\u0648\u0691\u06cc\u06ba\u06d4<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale115.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">suspended work platforms cleaning equipment\/ rope suspended platform\/window cleaning cradle<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0646\u06a9\u0627\u0644\u0646\u06d2 \u06a9\u0627 \u0645\u0642\u0627\u0645: \u0634\u0646\u06af\u06be\u0627\u0626\u06cc\u060c \u0686\u06cc\u0646 (\u0645\u06cc\u0646 \u0644\u06cc\u0646\u0688)<\/li>\n<li>\u0628\u0631\u0627\u0646\u0688 \u06a9\u0627 \u0646\u0627\u0645: \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc<\/li>\n<li>\u0645\u0627\u0688\u0644 \u0646\u0645\u0628\u0631: ZLP500\/630\/800\/1000<\/li>\n<li>\u0646\u0627\u0645: \u0645\u0639\u0637\u0644 \u0634\u062f\u06c1 \u0631\u0633\u06cc \u067e\u0644\u06cc\u0679 \u0641\u0627\u0631\u0645 \u06cc\u0627 \u0648\u0631\u06a9\u0646\u06af \u067e\u0644\u06cc\u0679 \u0641\u0627\u0631\u0645<\/li>\n<li>\u06a9\u0631\u06cc\u0688\u0644 \u067e\u0644\u06cc\u0679 \u0641\u0627\u0631\u0645 \u0627\u06cc\u067e\u0644\u06cc \u06a9\u06cc\u0634\u0646: \u0639\u0645\u0627\u0631\u062a \u06a9\u06cc \u062f\u06cc\u06a9\u06be \u0628\u06be\u0627\u0644\u060c \u0635\u0641\u0627\u0626\u06cc\u060c \u067e\u06cc\u0646\u0679\u0646\u06af<\/li>\n<li>\u0686\u06be\u062a \u06a9\u06cc \u0641\u06a9\u0633\u0646\u06af: 1\u060c \u06a9\u0627\u0624\u0646\u0679\u0631 2 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u0639\u0637\u0644\u06cc\u060c \u067e\u06cc\u0631\u0627\u067e\u06cc\u0679 \u06a9\u0644\u06cc\u0645\u067e<\/li>\n<li>\u067e\u0644\u06cc\u0679 \u0641\u0627\u0631\u0645 \u06a9\u0627 \u0631\u0646\u06af: \u0633\u0631\u062e\u060c \u0686\u0627\u0646\u062f\u06cc\u060c \u06af\u0631\u0645 \u062c\u0633\u062a\u06cc<\/li>\n<li>\u062d\u0641\u0627\u0638\u062a\u06cc \u0622\u0644\u06c1: \u062d\u0641\u0627\u0638\u062a\u06cc \u062a\u0627\u0644\u0627\u060c \u0645\u062d\u0641\u0648\u0638 \u0631\u0633\u06cc \u0648\u063a\u06cc\u0631\u06c1<\/li>\n<li>\u0645\u0648\u0679\u06cc\u0648 \u067e\u0627\u0648\u0631: \u0628\u0631\u0642\u06cc \u0644\u06c1\u0631\u0627\u0646\u0627<\/li>\n<li>\u067e\u0644\u06cc\u0679 \u0641\u0627\u0631\u0645 \u06a9\u06cc \u0634\u06a9\u0644: \u06a9\u06cc\u0648\u0628\u0627\u0626\u0688 \u06cc\u0627 \u062e\u0635\u0648\u0635\u06cc \u0688\u06cc\u0632\u0627\u0626\u0646<\/li>\n<li>\u067e\u0644\u06cc\u0679 \u0641\u0627\u0631\u0645 \u06a9\u0627 \u0645\u0639\u06cc\u0627\u0631: CE\u060c GOST\u060c ISO<\/li>\n<li>\u067e\u0644\u06cc\u0679 \u0641\u0627\u0631\u0645 \u0645\u0648\u0627\u062f: \u0633\u0679\u06cc\u0644 \u06cc\u0627 \u0627\u06cc\u0644\u0648\u0645\u06cc\u0646\u06cc\u0645 \u06a9\u06be\u0648\u0679<\/li>\n<li>\u067e\u0644\u06cc\u0679 \u0641\u0627\u0631\u0645 \u0628\u0627\u0688\u06cc: \u0645\u0627\u0688\u06cc\u0648\u0644\u0631 \u067e\u0644\u06cc\u0679 \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06c1 \u0645\u0641\u062a \u062c\u0645\u0639<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ulaanbaatar, Conakry, Brescia, Allahabad etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Size Suspended Platform For Chimney, Steel Rope Facade Cleaning Platform in Suwon<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u0627\u06cc\u06a9 \u067e\u06cc\u063a\u0627\u0645 \u0686\u06be\u0648\u0691\u06cc\u06ba\u06d4<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale2.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP Series 6m length,630kg rated load Suspended platform lift scaffolding,rope suspended platform with CE Certificate<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0646\u06a9\u0627\u0644\u0646\u06d2 \u06a9\u0627 \u0645\u0642\u0627\u0645: \u0634\u0646\u06af\u06be\u0627\u0626\u06cc\u060c \u0686\u06cc\u0646 (\u0645\u06cc\u0646 \u0644\u06cc\u0646\u0688)<\/li>\n<li>\u0628\u0631\u0627\u0646\u0688 \u06a9\u0627 \u0646\u0627\u0645: \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc<\/li>\n<li>\u0645\u0627\u0688\u0644 \u0646\u0645\u0628\u0631: ZLP630<\/li>\n<li>\u0644\u0641\u0679 \u0645\u06cc\u06a9\u0627\u0646\u0632\u0645: \u0644\u0641\u0679 \u0686\u06cc\u0646<\/li>\n<li>\u0644\u0641\u0679 \u0688\u0631\u0627\u0626\u06cc\u0648 \/ \u0627\u06cc\u06a9\u0679\u06cc\u0648\u06cc\u0634\u0646: \u0627\u0644\u06cc\u06a9\u0679\u0631\u06a9 \u0645\u0648\u0679\u0631<\/li>\n<li>\u067e\u0627\u0648\u0631: 1.5 \u06a9\u0644\u0648 \u0648\u0627\u0679 * 2<\/li>\n<li>\u0634\u0631\u062d \u0634\u062f\u06c1 \u0644\u0648\u0688\u0646\u06af \u06a9\u06cc \u0635\u0644\u0627\u062d\u06cc\u062a: 630 \u06a9\u0644\u0648\u06af\u0631\u0627\u0645<\/li>\n<li>\u06a9\u0645 \u0627\u0632 \u06a9\u0645 \u0644\u0641\u0679\u0646\u06af \u0627\u0648\u0646\u0686\u0627\u0626\u06cc: 0m<\/li>\n<li>\u0632\u06cc\u0627\u062f\u06c1 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u0644\u0641\u0679\u0646\u06af \u0627\u0648\u0646\u0686\u0627\u0626\u06cc: 100m<\/li>\n<li>Table Size:6000*720*1300mm<\/li>\n<li>\u0645\u062c\u0645\u0648\u0639\u06cc \u0637\u0648\u0644 \u0648 \u0639\u0631\u0636: \u0636\u0631\u0648\u0631\u062a<\/li>\n<li>Weight:630kg<\/li>\n<li>\u0633\u0631\u0679\u06cc\u0641\u06cc\u06a9\u06cc\u0634\u0646: \u0633\u06cc \u0627\u06cc\u060c \u0622\u0626\u06cc \u0627\u06cc\u0633 \u0627\u0648\u060c \u062c\u06cc \u0627\u0648 \u0627\u06cc\u0633 \u0679\u06cc\u06d4 .<\/li>\n<li>\u0648\u0627\u0631\u0646\u0679\u06cc: 1 \u0633\u0627\u0644<\/li>\n<li>After-sales Service Provided:Overseas service center available<\/li>\n<li>Color:as per requirement<\/li>\n<li>\u06a9\u0627\u0624\u0646\u0679\u0631 \u0648\u06cc\u0679: 1000 \u06a9\u0644\u0648\u06af\u0631\u0627\u0645<\/li>\n<li>\u0648\u0648\u0644\u0679\u06cc\u062c: 380v\/50hz<\/li>\n<li>\u06a9\u06cc\u0628\u0644: 100M<\/li>\n<li>\u0632\u0646\u062f\u06af\u06cc \u06af\u0632\u0627\u0631\u0646\u06d2 \u06a9\u06cc \u0631\u0641\u062a\u0627\u0631: 8-10m\/\u0645\u0646\u0679<\/li>\n<li>safety lock:2 pieces<\/li>\n<li>hoist:2sets<\/li>\n<li>eletrical parts:schneider brand<\/li>\n<li>weight of full set:1900kg<\/li>\n<li>Usage:Maintance ,cleaning ,etc<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Canada, Kalyan-Dombivali, Suwon, Bruges etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Electric Motor Hoist For Suspended Platform in Canada, Wire Rope Suspended Working Platform Equipment in Montreal<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u0627\u06cc\u06a9 \u067e\u06cc\u063a\u0627\u0645 \u0686\u06be\u0648\u0691\u06cc\u06ba\u06d4<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of ZLP 630 ZLP 800 electric suspended rope platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP 630 zlp 800 Cable:3*2.5+2*1.5 <\/p>","protected":false},"author":1,"featured_media":99,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11271,11422,11423,2712,11425,11424],"class_list":["post-2663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aluminum-zlp-630-suspended-working-platform-in-kalyan-dombivali","tag-electric-motor-hoist-for-suspended-platform-in-canada","tag-scaffolding-lift-platform-in-honduras","tag-size-suspended-platform-for-chimney","tag-steel-rope-facade-cleaning-platform-in-suwon","tag-wire-rope-suspended-working-platform-equipment-in-montreal"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/ur\/wp-json\/wp\/v2\/posts\/2663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/ur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/ur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/ur\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/ur\/wp-json\/wp\/v2\/comments?post=2663"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/ur\/wp-json\/wp\/v2\/posts\/2663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/ur\/wp-json\/wp\/v2\/media\/99"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/ur\/wp-json\/wp\/v2\/media?parent=2663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/ur\/wp-json\/wp\/v2\/categories?post=2663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/ur\/wp-json\/wp\/v2\/tags?post=2663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}