{"id":518,"date":"2017-05-15T13:49:33","date_gmt":"2017-05-15T13:49:33","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/competitive-price-power-clean-platformwork-platformsuspended-platform.html"},"modified":"2017-05-15T13:49:33","modified_gmt":"2017-05-15T13:49:33","slug":"competitive-price-power-clean-platformwork-platformsuspended-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/sw\/competitive-price-power-clean-platformwork-platformsuspended-platform.html","title":{"rendered":"Competitive Price power clean platform\/work platform\/suspended platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale106.jpg\" alt=\"Competitive Price power clean platform\/work platform\/suspended platform\" \/><br \/>\nImage of Competitive Price power clean platform\/work platform\/suspended platform<\/p>\n<h3 class=\"alpha-title\">Maelezo ya Haraka: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Name:power clean platform\/work platform\/suspended platform<\/li>\n<li>Rangi: hiari<\/li>\n<li>Ugavi wa umeme (V):220,380,415,440<\/li>\n<li>Kifaa cha Usalama:kipengee 7<\/li>\n<li>Nyenzo: chuma au alumini<\/li>\n<li>Matibabu ya uso: Kunyunyizia rangi au mabati ya dip-moto<\/li>\n<li>Sehemu ya Bure: usambazaji<\/li>\n<li>kamba ya chuma: mabati ya kuzamisha moto<\/li>\n<li>Pandisha: Imetengenezwa kwa alumini ya kutupwa<\/li>\n<li>Cheti:CE,ISO9001-2008<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Video inayohusiana: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pX2IxRmRQNzQ3bVE\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Maelezo: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale110.jpg\" alt=\"Competitive Price power clean platform\/work platform\/suspended platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale269.jpg\" alt=\"Competitive Price power clean platform\/work platform\/suspended platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Onyesha Vifaa Vinavyohusiana: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale4.jpg\" alt=\"Competitive Price power clean platform\/work platform\/suspended platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale48.jpg\" alt=\"Competitive Price power clean platform\/work platform\/suspended platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Acha ujumbe: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Unaweza pia kupenda:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale106.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">2017 Shanghai Success Trustable wire rope electric hoist suspended platform cradle<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Model Number:ZLP Series<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>keywords:Trustable wire rope electric hoist suspended platform cradle<\/li>\n<li>Lifting Height:100m<\/li>\n<li>Kebo:100m<\/li>\n<li>Power:380V<\/li>\n<li>Voltage:50Hz<\/li>\n<li>Front beam overhang:1.3~1.5m<\/li>\n<li>Support adjustable height:1.44~2.14m<\/li>\n<li>jukwaa:kinza kutu<\/li>\n<li>Nyenzo: Alumini au chuma<\/li>\n<li>Dimension(L*W*H)::7500*720*1300mm<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Calgary, Hofuf, Medan etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mature-Tech Roof Access Platforms in Calgary, Aluminum Spray Coating Suspended Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale128.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Kiwanda cha ZLP Swing Stage\/ Cradle\/ Gondola\/ Jukwaa Lililosimamishwa (CE,ISO, Imeidhinishwa)<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Brand Name:FTH\/Success<\/li>\n<li>Nambari ya Mfano: ZLP250-1000<\/li>\n<li>Nyenzo: Chuma au Aloi<\/li>\n<li>Nguvu ya Kuinua: 380v\/50 HZ<\/li>\n<li>Kasi ya kuinua: 8-10m \/ min<\/li>\n<li>Uzito wa kukabiliana: 800-1000kg<\/li>\n<li>Urefu wa Juu wa Kuinua: 200m<\/li>\n<li>Uzito uliopimwa: 250-1000 kg<\/li>\n<li>Kebo:100m<\/li>\n<li>Nguzo ya boriti ya mbele: 1.3-1.5m<\/li>\n<li>Urefu wa kuinua: 100 m<\/li>\n<li>Useage:building suspended platform<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Palestine, South Africa etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Affordable Suspended Platform Manufacturers in Hofuf, Suspended Aerial Working Platform in Medan<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale243.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ISO&#038;CE Aluminium suspended access gondola building cleaning equipment<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Uzito uliopimwa: 630kg<\/li>\n<li>Kasi ya kuinua:8~10m\/min<\/li>\n<li>Urefu wa kuinua: 100 m<\/li>\n<li>Kebo:100m<\/li>\n<li>Counterweight:630kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Makassar, Latvia, Montevideo, Calgary etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Scaffolding Access Platforms in Palestine, Electric Construction Platform Gondola Lift in South Africa<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale196.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Suspension Access Equipment 800kg-1000kg<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara:Success-CHINA<\/li>\n<li>Nambari ya Mfano: ZLP<\/li>\n<li>Usage:Suspended Platform for facade cleaning<\/li>\n<li>Colour:Red or other colors<\/li>\n<li>Vyeti: ISO, GOST, CE<\/li>\n<li>Chanzo cha Nguvu:Umeme<\/li>\n<li>Drive Type:Wire rope hoisting<\/li>\n<li>Application:Tall Building Maintenance<\/li>\n<li>Origin:China<\/li>\n<li>Kasi ya Kuinua:8-10m\/min<\/li>\n<li>Lifting Height and Cable Length:100m<\/li>\n<li>Voltage:380V50HZ 3Phases or according to  customer need<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: San Jose, Yaound\u00e9, Montevideo, Makassar etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminum Spray Coating Suspended Platform, Electric Construction Platform Gondola Lift in South Africa<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale268.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP 630KG-800KG Electric Suspended Scaffold\/Suspended Platform\/Cradle\/Gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya mfano: ZLP630<\/li>\n<li>Mbinu ya Kuinua: Umeme<\/li>\n<li>Lift Drive \/ Actuation:Electric Motor<\/li>\n<li>Power:1.5kw, 1.5kw, 1.8kw, 2kw<\/li>\n<li>Rated Loading Capacity:630kg, 150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Dak. Kuinua Urefu: 0m<\/li>\n<li>Max. Kuinua Urefu: 200m, 200m<\/li>\n<li>Table Size:6000*690*1180mm<\/li>\n<li>Overall Dimensions:3CBM<\/li>\n<li>Weight:1700kg<\/li>\n<li>Uthibitisho: ISO, CE<\/li>\n<li>Udhamini: Mwaka 1<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Nyenzo: Chuma, Aloi ya Alumini<\/li>\n<li>Rangi: Nyekundu, Njano, Bluu, nk<\/li>\n<li>Matibabu ya uso:Mipako ya unga, Mabati ya moto<\/li>\n<li>Urefu: 2m, 2.5m, 3m, 5m, 6m, 7.5m, nk.<\/li>\n<li>Utaratibu wa Kuishi: Gia<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Voltage:Suspended Platform\/Cradle\/Gondola accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Calgary, Medan, South Africa, Latvia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mature-Tech Roof Access Platforms in Calgary, Scaffolding Access Platforms in Palestine<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Competitive Price power clean platform\/work platform\/suspended platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000 After-sales Service Provided:Engineers available to <\/p>","protected":false},"author":1,"featured_media":113,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1245,1243,1248,1244,1247,1246],"class_list":["post-518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-affordable-suspended-platform-manufacturers-in-hofuf","tag-aluminum-spray-coating-suspended-platform","tag-electric-construction-platform-gondola-lift-in-south-africa","tag-mature-tech-roof-access-platforms-in-calgary","tag-scaffolding-access-platforms-in-palestine","tag-suspended-aerial-working-platform-in-medan"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/comments?post=518"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media\/113"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media?parent=518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/categories?post=518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/tags?post=518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}