{"id":2377,"date":"2017-05-30T14:08:48","date_gmt":"2017-05-30T14:08:48","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zlp800-personnel-basket-suspended-platform-ce-qualification.html"},"modified":"2017-05-30T14:08:48","modified_gmt":"2017-05-30T14:08:48","slug":"zlp800-personnel-basket-suspended-platform-ce-qualification","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/sw\/zlp800-personnel-basket-suspended-platform-ce-qualification.html","title":{"rendered":"ZLP800 personnel basket\/ suspended platform, CE qualification"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale71.jpg\" alt=\"ZLP800 personnel basket\/ suspended platform, CE qualification\" \/><br \/>\nImage of ZLP800 personnel basket\/ suspended platform, CE qualification<\/p>\n<h3 class=\"alpha-title\">Maelezo ya Haraka: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: FTH<\/li>\n<li>Nambari ya Mfano: ZLP800<\/li>\n<li>Other Model::ZLP1000, ZLP630, ZLP500<\/li>\n<li>Material:steel or A-alloy<\/li>\n<li>Name:personnel basket\/ suspended platform<\/li>\n<li>Usage:as a platform for people&#39;s high rise building maintaining work<\/li>\n<li>Shape:long shape or design as the client&#39;s bulding<\/li>\n<li>Maombi ya Jukwaa:dumisha facade ya jengo, mapambo au kusafisha<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Video inayohusiana: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pUjgzWmxoN3Voc0U\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Maelezo: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale16.jpg\" alt=\"ZLP800 personnel basket\/ suspended platform, CE qualification\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale175.jpg\" alt=\"ZLP800 personnel basket\/ suspended platform, CE qualification\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Onyesha Vifaa Vinavyohusiana: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale4.jpg\" alt=\"ZLP800 personnel basket\/ suspended platform, CE qualification Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale40.jpg\" alt=\"ZLP800 personnel basket\/ suspended platform, CE qualification Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Acha ujumbe: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Unaweza pia kupenda:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale193.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">100kg 250kg 300kg 500kg 630kg 800kg 1000kg lightweight mobile platform\/electric suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Aurangabad, India, Monterrey etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Scissor Platforms in Aurangabad, Zlp630 Suspended Working Platforms<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale33.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">China industrial use personal platform lift<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Name:industrial use personal platform lift<\/li>\n<li>Rangi: hiari<\/li>\n<li>Ugavi wa umeme (V):220,380,415,440<\/li>\n<li>Kifaa cha Usalama:kipengee 7<\/li>\n<li>Nyenzo: chuma au alumini<\/li>\n<li>Matibabu ya uso: Kunyunyizia rangi au mabati ya dip-moto<\/li>\n<li>Sehemu ya Bure: usambazaji<\/li>\n<li>kamba ya chuma: mabati ya kuzamisha moto<\/li>\n<li>Pandisha: Imetengenezwa kwa alumini ya kutupwa<\/li>\n<li>Cheti:CE,ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Poland, Semarang etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Two Corner Suspended Platform in India, Industry Access Suspended Platforms in Monterrey<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale244.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Manufacturer ZLP630 Suspended Platform\/Aluminum Platform\/Scaffold Cradle\/Cleaning Gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara:Success-CHINA<\/li>\n<li>Model Number:ZLP630  ZLP800  ZLP1000<\/li>\n<li>Usage:Building facade or glass cleaning<\/li>\n<li>Model:ZLP630  Suspended Platform\/Aluminum Platform\/Scaffold Cradle<\/li>\n<li>Vyeti: ISO, GOST, CE<\/li>\n<li>Chanzo cha Nguvu:Umeme<\/li>\n<li>Drive Type:Wire rope hoisting<\/li>\n<li>Application:Tall Building Maintenance<\/li>\n<li>Origin:China<\/li>\n<li>Kasi ya Kuinua:8-10m\/min<\/li>\n<li>Lifting Height and Cable Length:100m<\/li>\n<li>Voltage:380V50HZ 3Phases or according to  customer need<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Padang, Bruges, Lima, Aurangabad etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp630 Safety Rope Suspended Platform in Poland, Aerial Work Platform Price in Semarang<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale40.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Steel Gondola Building Maintenance Gondola for Construction<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Rated load:1000kg<\/li>\n<li>Kasi ya kuinua:8~10m\/min<\/li>\n<li>Urefu wa kuinua: 100 m<\/li>\n<li>Kebo:100m<\/li>\n<li>Counterweught:1000kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Saint Petersburg, Oran, Lima, Padang etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp630 Suspended Working Platforms, Aerial Work Platform Price in Semarang<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale86.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP building suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: JH<\/li>\n<li>Nambari ya Mfano: ZLP800<\/li>\n<li>Jina: Jukwaa Lililosimamishwa<\/li>\n<li>Mfano: ZLP800<\/li>\n<li>Chapa: Mafanikio<\/li>\n<li>Nyenzo: Alumini<\/li>\n<li>Ukubwa wa jukwaa: 7.5 * 0.72 * 1.2m<\/li>\n<li>Urefu wa kazi: 100 m<\/li>\n<li>Kamba ya waya ya chuma: 9.1mm<\/li>\n<li>Kebo:3*2.5+2*1.5<\/li>\n<li>Utaratibu wa kusimamishwa:Mabati yenye joto kali<\/li>\n<li>Uzito wa kukabiliana: 1000kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Aurangabad, Monterrey, Semarang, Bruges etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Scissor Platforms in Aurangabad, Zlp630 Safety Rope Suspended Platform in Poland<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of ZLP800 personnel basket\/ suspended platform, CE qualification Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:FTH Model Number:ZLP 800 Other Model::ZLP1000, ZLP630, ZLP500 <\/p>","protected":false},"author":1,"featured_media":229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10006,10004,10002,10003,10005,9847],"class_list":["post-2377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aerial-work-platform-price-in-semarang","tag-industry-access-suspended-platforms-in-monterrey","tag-scissor-platforms-in-aurangabad","tag-two-corner-suspended-platform-in-india","tag-zlp630-safety-rope-suspended-platform-in-poland","tag-zlp630-suspended-working-platforms"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/comments?post=2377"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media\/229"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media?parent=2377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/categories?post=2377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/tags?post=2377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}