{"id":2349,"date":"2017-05-26T02:54:57","date_gmt":"2017-05-26T02:54:57","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zlp-constructionbuildingexternal-wallwindow-cleaning-suspended-platform-cradle-gondola-swing-stage-climber-scaffold.html"},"modified":"2017-05-26T02:54:57","modified_gmt":"2017-05-26T02:54:57","slug":"zlp-constructionbuildingexternal-wallwindow-cleaning-suspended-platform-cradle-gondola-swing-stage-climber-scaffold","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/sw\/zlp-constructionbuildingexternal-wallwindow-cleaning-suspended-platform-cradle-gondola-swing-stage-climber-scaffold.html","title":{"rendered":"ZLP Construction\/Building\/External Wall\/Window Cleaning Suspended Platform\/ Cradle\/ Gondola\/ Swing Stage\/ Climber\/ Scaffold"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale113.jpg\" alt=\"ZLP Construction\/Building\/External Wall\/Window Cleaning Suspended Platform\/ Cradle\/ Gondola\/ Swing Stage\/ Climber\/ Scaffold\" \/><br \/>\nImage of ZLP Construction\/Building\/External Wall\/Window Cleaning Suspended Platform\/ Cradle\/ Gondola\/ Swing Stage\/ Climber\/ Scaffold<\/p>\n<h3 class=\"alpha-title\">Maelezo ya Haraka: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP<\/li>\n<li>Model:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000<\/li>\n<li>Colour:special made as customer&#39;s requirement<\/li>\n<li>Lifting height:standard 100m,max height is 200m<\/li>\n<li>Purpose:window clean,building maintenance and so on<\/li>\n<li>Rated load:300kg&#8212;&#8211;1000kg<\/li>\n<li>Speed:8-10m\/m<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Video inayohusiana: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pUmFuR05NVkdqZnM\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Maelezo: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale177.jpg\" alt=\"ZLP Construction\/Building\/External Wall\/Window Cleaning Suspended Platform\/ Cradle\/ Gondola\/ Swing Stage\/ Climber\/ Scaffold\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale8.jpg\" alt=\"ZLP Construction\/Building\/External Wall\/Window Cleaning Suspended Platform\/ Cradle\/ Gondola\/ Swing Stage\/ Climber\/ Scaffold\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Onyesha Vifaa Vinavyohusiana: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale79.jpg\" alt=\"ZLP Construction\/Building\/External Wall\/Window Cleaning Suspended Platform\/ Cradle\/ Gondola\/ Swing Stage\/ Climber\/ Scaffold Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale26.jpg\" alt=\"ZLP Construction\/Building\/External Wall\/Window Cleaning Suspended Platform\/ Cradle\/ Gondola\/ Swing Stage\/ Climber\/ Scaffold Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Acha ujumbe: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Unaweza pia kupenda:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale224.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">CE Qualification ZLP800 Single Deck Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP500<\/li>\n<li>Nyenzo: Chuma, Aloi ya Alumini<\/li>\n<li>Rangi: Nyekundu, Njano, Bluu, nk<\/li>\n<li>Matibabu ya uso:Mipako ya unga, Mabati ya moto<\/li>\n<li>Urefu: 2m, 2.5m, 3m, 5m, 6m, 7.5m, nk.<\/li>\n<li>Utaratibu wa Kuishi: Gia<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Nguvu: 1.5kw, 1.8kw, 2kw<\/li>\n<li>Uwezo wa Upakiaji uliokadiriwa: 150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Max. Urefu wa Kuinua: 200m<\/li>\n<li>Voltage:ZLP800 Single Deck Suspended Platform accept different voltage:220V<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Calgary, Colombo, Manaus etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Scaffold Suspended Aerial Platform in Calgary, Aluminum Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale245.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Factory electric access building hoist material suspended platform ladder<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Uzito uliopimwa: 800kg<\/li>\n<li>Kasi ya kuinua:8~10m\/min<\/li>\n<li>Urefu wa kuinua: 100 m<\/li>\n<li>Kebo:100m<\/li>\n<li>Uzito wa kukabiliana: 800kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Port Elizabeth, Turkmenistan etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Facade Cleaning Suspended Platform in Colombo, Suspension Swing in Manaus<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale254.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High Rise Maintenance Platform, Motion Suspended Gondola Platforms, Swing Stage<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Model Number:ZLP Series<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Lifting Speed:8~10m\/min<\/li>\n<li>Lifting Height:100m<\/li>\n<li>Kebo:100m<\/li>\n<li>Power:380V<\/li>\n<li>Voltage:50Hz<\/li>\n<li>Front beam overhang:1.3~1.5m<\/li>\n<li>Support adjustable height:1.44~2.14m<\/li>\n<li>jukwaa:kinza kutu<\/li>\n<li>Nyenzo: Alumini au chuma<\/li>\n<li>Dimension(L*W*H)::7500*720*1300mm<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Batam, Ivory Coast, Curitiba, Calgary etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp 630 Cheap Gondola Cradle Suspended Platform in Port Elizabeth, Material Hoist in Turkmenistan<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale12.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Success Hot galvanizing Swing Stage<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Name:Hot galvanizing Swing Stage<\/li>\n<li>Rangi: hiari<\/li>\n<li>Ugavi wa umeme (V):220,380,415,440<\/li>\n<li>Kifaa cha Usalama:kipengee 7<\/li>\n<li>Nyenzo: chuma au alumini<\/li>\n<li>Matibabu ya uso: Kunyunyizia rangi au mabati ya dip-moto<\/li>\n<li>Sehemu ya Bure: usambazaji<\/li>\n<li>kamba ya chuma: mabati ya kuzamisha moto<\/li>\n<li>Pandisha: Imetengenezwa kwa alumini ya kutupwa<\/li>\n<li>Cheti:CE,ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Tijuana, Trinidad and Tobago, Curitiba, Batam etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminum Platform, Material Hoist in Turkmenistan<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale95.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP800 800KG 7.5M in length Machine cleaning glass towers<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP800<\/li>\n<li>Kebo:3*2.5+2*1.5<\/li>\n<li>Kasi ya Kuinua:8-10m\/min<\/li>\n<li>Nyenzo: aloi ya chuma au alumini<\/li>\n<li>Vyeti: ISO, GOST, CE<\/li>\n<li>Name:ZLP800 800KG 7.5M in length Machine cleaning glass towers<\/li>\n<li>Cable ya Jukwaa: 100m<\/li>\n<li>Asili: Uchina<\/li>\n<li>Maombi:ZLP Boom Lift\/ Jukwaa Lililosimamishwa la Angani la Umeme<\/li>\n<li>Voltage:220V\/380V\/415V<\/li>\n<li>Rangi: Nyekundu au fedha<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Calgary, Manaus, Turkmenistan, Ivory Coast etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Scaffold Suspended Aerial Platform in Calgary, Zlp 630 Cheap Gondola Cradle Suspended Platform in Port Elizabeth<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of ZLP Construction\/Building\/External Wall\/Window Cleaning Suspended Platform\/ Cradle\/ Gondola\/ Swing Stage\/ Climber\/ Scaffold Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP <\/p>","protected":false},"author":1,"featured_media":142,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2683,9896,9899,9895,9897,9898],"class_list":["post-2349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aluminum-platform","tag-facade-cleaning-suspended-platform-in-colombo","tag-material-hoist-in-turkmenistan","tag-scaffold-suspended-aerial-platform-in-calgary","tag-suspension-swing-in-manaus","tag-zlp-630-cheap-gondola-cradle-suspended-platform-in-port-elizabeth"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/comments?post=2349"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media\/142"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media?parent=2349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/categories?post=2349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/tags?post=2349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}