{"id":2143,"date":"2017-05-25T02:37:06","date_gmt":"2017-05-25T02:37:06","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/aluminum-suspended-platformgondolacradl-work-benchzlp800factory.html"},"modified":"2017-05-25T02:37:06","modified_gmt":"2017-05-25T02:37:06","slug":"aluminum-suspended-platformgondolacradl-work-benchzlp800factory","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/sw\/aluminum-suspended-platformgondolacradl-work-benchzlp800factory.html","title":{"rendered":"aluminum suspended platform\/Gondola\/Cradl\/ work bench\/ZLP800\/Factory"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale89.jpg\" alt=\"aluminum suspended platform\/Gondola\/Cradl\/ work bench\/ZLP800\/Factory\" \/><br \/>\nImage of aluminum suspended platform\/Gondola\/Cradl\/ work bench\/ZLP800\/Factory<\/p>\n<h3 class=\"alpha-title\">Maelezo ya Haraka: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Hali:Mpya<\/li>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: FTH<\/li>\n<li>Nambari ya Mfano: ZLP800<\/li>\n<li>Rated Loading Capacity(kg):800<\/li>\n<li>Kasi ya Kupandisha:8-10M\/MIN<\/li>\n<li>Urefu wa Juu wa Kuinua: 100M<\/li>\n<li>Kipimo(L*W*H):7500*720*1300mm<\/li>\n<li>Uzito wa Loder: 250-1000kg<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Rangi:kulingana na mahitaji<\/li>\n<li>jukwaa maalum: inaweza kuwa muuzaji<\/li>\n<li>jukwaa:kinza kutu<\/li>\n<li>Nyenzo: Alumini au chuma<\/li>\n<li>mfano:ZLP250,ZLP500,ZLP630,ZLP1000<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Video inayohusiana: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02paUJ3clVNRGxBXzQ\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Maelezo: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale210.jpg\" alt=\"aluminum suspended platform\/Gondola\/Cradl\/ work bench\/ZLP800\/Factory\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale209.jpg\" alt=\"aluminum suspended platform\/Gondola\/Cradl\/ work bench\/ZLP800\/Factory\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Onyesha Vifaa Vinavyohusiana: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale93.jpg\" alt=\"aluminum suspended platform\/Gondola\/Cradl\/ work bench\/ZLP800\/Factory Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale45.jpg\" alt=\"aluminum suspended platform\/Gondola\/Cradl\/ work bench\/ZLP800\/Factory Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Acha ujumbe: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Unaweza pia kupenda:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale258.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Building construction suspended working platform from Shanghai<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Brand Name:Success-Success<\/li>\n<li>Nambari ya Mfano: ZLP500\/630\/800\/1000<\/li>\n<li>Name:ZLP electric suspended platform<\/li>\n<li>Rated load:500kg  630kg  800kg 1000kg<\/li>\n<li>Kasi ya kuinua: 8-10m \/ min<\/li>\n<li>Platform Size(Lwh):6000(1+2+3m)*720*1300<\/li>\n<li>Max. Lifting Height:100 m<\/li>\n<li>Power:1.5KW*2, 1.8KW*2<\/li>\n<li>Voltage:110V,220V,240V,400V,415V,440V are available<\/li>\n<li>Certification:CE, ISO,GOST<\/li>\n<li>Uzito wa kukabiliana: 1000kg<\/li>\n<li>Material:Alloy Steel\/Hot dipping\/steel<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bamako, Cyprus, Lebanon etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Welding Scaffolding Platform in Bamako, Zlp1000 Aluminum Rope Suspended Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale6.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Easy Transfer safety device zlp800 steel window cleaning suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Name:safety device zlp800 steel window cleaning suspended platform<\/li>\n<li>Rangi: hiari<\/li>\n<li>Ugavi wa umeme (V):220,380,415,440<\/li>\n<li>Kifaa cha Usalama:kipengee 7<\/li>\n<li>Nyenzo: chuma au alumini<\/li>\n<li>Matibabu ya uso: Kunyunyizia rangi au mabati ya dip-moto<\/li>\n<li>Sehemu ya Bure: usambazaji<\/li>\n<li>kamba ya chuma: mabati ya kuzamisha moto<\/li>\n<li>Pandisha: Imetengenezwa kwa alumini ya kutupwa<\/li>\n<li>Cheti:CE,ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Puebla, Sudan etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Fixator Suspended Platform in Cyprus, Gondola Cradle in Lebanon<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale15.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High Building External Walls ZLP 630 Aluminum Facade Cleaning Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya mfano: ZLP630<\/li>\n<li>Imekadiriwa Uwezo wa Kupakia: 630kg<\/li>\n<li>Colour:Red,Can be Customized<\/li>\n<li>Motor Power:1.5KW*2<\/li>\n<li>Platform Dimension:6000*0.72*1300<\/li>\n<li>Voltage:220V\/380V\/415V-3Phase\/50hz\/60HZ<\/li>\n<li>Steel Rope Diamter:8.3mm<\/li>\n<li>Lifting Height:100m-120m<\/li>\n<li>Model:ZLP630 Suspended Working Platform<\/li>\n<li>Locking Cable Angel:3-8&deg;<\/li>\n<li>Overhang Length of Front Beam:1.3-1.5m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Varanasi, Barcelona, Adelaide, Bamako etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp800 Series Suspended Platform Working Platform in Puebla, Scaffold Suspended Aerial Platform in Sudan<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale160.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Suspended Wire Rope Platform (SRP), Success Brand New<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP800<\/li>\n<li>Mifano Nyingine::ZLP1000, ZLP630, ZLP500<\/li>\n<li>Name:Suspended Wire Rope Platform<\/li>\n<li>Modular Suspended Platform Application:building maintenance<\/li>\n<li>Kurekebisha paa: 1, kusimamishwa kwa counter 2, clamp ya parapet<\/li>\n<li>Mwili wa Jukwaa:bila malipo iliyokusanywa na moduli<\/li>\n<li>Nyenzo ya Jukwaa: Aloi ya Chuma au Alumini<\/li>\n<li>Rangi ya jukwaa:nyekundu\/fedha\/utengenezo maalum<\/li>\n<li>Sura ya Jukwaa: muundo wa cuboid au maalum<\/li>\n<li>Nguvu ya Nia: Kiingilio cha Umeme<\/li>\n<li>Safety device for cradle platform:safety lock<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Chicago, Luanda, Adelaide, Varanasi etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp1000 Aluminum Rope Suspended Platform, Scaffold Suspended Aerial Platform in Sudan<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale148.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP Gandola, Success Brand New<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Model Number:ZLP  Gandola<\/li>\n<li>Mifano Nyingine::ZLP1000, ZLP630, ZLP500<\/li>\n<li>Name:Gandola<\/li>\n<li>Modular Suspended Platform Application:building maintenance<\/li>\n<li>Kurekebisha paa: 1, kusimamishwa kwa counter 2, clamp ya parapet<\/li>\n<li>Mwili wa Jukwaa:bila malipo iliyokusanywa na moduli<\/li>\n<li>Nyenzo ya Jukwaa: Aloi ya Chuma au Alumini<\/li>\n<li>Rangi ya jukwaa:nyekundu\/fedha\/utengenezo maalum<\/li>\n<li>Sura ya Jukwaa: muundo wa cuboid au maalum<\/li>\n<li>Nguvu ya Nia: Kiingilio cha Umeme<\/li>\n<li>Safety device for cradle platform:safety lock<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bamako, Lebanon, Sudan, Barcelona etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Welding Scaffolding Platform in Bamako, Zlp800 Series Suspended Platform Working Platform in Puebla<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of aluminum suspended platform\/Gondola\/Cradl\/ work bench\/ZLP800\/Factory Quick Details: Condition:New Place of Origin:Shanghai, China (Mainland) Brand Name:FTH Model Number:ZLP800 Rated Loading Capacity(kg):800 Hoisting Speed:8-10M\/MIN Max <\/p>","protected":false},"author":1,"featured_media":187,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[8893,8894,8896,8892,4569,8895],"class_list":["post-2143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-fixator-suspended-platform-in-cyprus","tag-gondola-cradle-in-lebanon","tag-scaffold-suspended-aerial-platform-in-sudan","tag-welding-scaffolding-platform-in-bamako","tag-zlp1000-aluminum-rope-suspended-platform","tag-zlp800-series-suspended-platform-working-platform-in-puebla"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/comments?post=2143"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media\/187"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media?parent=2143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/categories?post=2143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/tags?post=2143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}