{"id":2130,"date":"2017-05-25T17:16:09","date_gmt":"2017-05-25T17:16:09","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zlp-630-circular-platform-window-cleaning-lift-used-suspended-platforms.html"},"modified":"2017-05-25T17:16:09","modified_gmt":"2017-05-25T17:16:09","slug":"zlp-630-circular-platform-window-cleaning-lift-used-suspended-platforms","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/sw\/zlp-630-circular-platform-window-cleaning-lift-used-suspended-platforms.html","title":{"rendered":"ZLP-630 circular platform \/window cleaning lift used suspended platforms"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale201.jpg\" alt=\"ZLP-630 circular platform \/window cleaning lift used suspended platforms\" \/><br \/>\nImage of ZLP-630 circular platform \/window cleaning lift used suspended platforms<\/p>\n<h3 class=\"alpha-title\">Maelezo ya Haraka: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Brand Name:Jinfei Tianhong<\/li>\n<li>Nambari ya Mfano: ZLP800<\/li>\n<li>Supply:Manufacturer<\/li>\n<li>Imeidhinishwa: CE, GOST, ISO<\/li>\n<li>MOQ;:1 Set<\/li>\n<li>Materials:Aluminum<\/li>\n<li>Voltages:220-440v<\/li>\n<li>Color:Red<\/li>\n<li>Lifting heght:100m<\/li>\n<li>Kasi ya kuinua: 8-10m \/ min<\/li>\n<li>Constructurer:Customized<\/li>\n<li>Kifaa cha usalama:Kufuli ya usalama<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Video inayohusiana: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pdU5LQVI0ano3Z1U\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Maelezo: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale32.jpg\" alt=\"ZLP-630 circular platform \/window cleaning lift used suspended platforms\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale95.jpg\" alt=\"ZLP-630 circular platform \/window cleaning lift used suspended platforms\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Onyesha Vifaa Vinavyohusiana: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale46.jpg\" alt=\"ZLP-630 circular platform \/window cleaning lift used suspended platforms Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale68.jpg\" alt=\"ZLP-630 circular platform \/window cleaning lift used suspended platforms Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Acha ujumbe: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Unaweza pia kupenda:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale210.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Advanced ZLP630 Window cleaning equipment<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya mfano: ZLP630<\/li>\n<li>Specification:Manufacturer Zlp630 Suspended Platform<\/li>\n<li>Nyenzo: Chuma au Aloi<\/li>\n<li>Kasi ya kuinua: 8-10m \/ min<\/li>\n<li>Nguvu ya Kuinua: 380v\/50 HZ<\/li>\n<li>Uzito wa kukabiliana: 800-1000kg<\/li>\n<li>Urefu wa Juu wa Kuinua: 200m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Allahabad, Denmark, Lilongwe etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Rope Suspended Platform Window Cleaning Gondola in Allahabad, Suspended Work Platforms<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale235.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Corner Suspend Platform From China Factory, L Shape<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya mfano: ZLP630<\/li>\n<li>Mbinu ya Kuinua: Umeme<\/li>\n<li>Lift Drive \/ Actuation:Electric Motor<\/li>\n<li>Power:1.5kw, 1.5kw, 1.8kw, 2kw<\/li>\n<li>Rated Loading Capacity:630kg, 150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Dak. Kuinua Urefu: 0m<\/li>\n<li>Max. Kuinua Urefu: 200m, 200m<\/li>\n<li>Table Size:6000*690*1180mm<\/li>\n<li>Overall Dimensions:3CBM<\/li>\n<li>Weight:1700kg<\/li>\n<li>Uthibitisho: ISO, CE<\/li>\n<li>Udhamini: Mwaka 1<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Nyenzo: Chuma, Aloi ya Alumini<\/li>\n<li>Rangi: Nyekundu, Njano, Bluu, nk<\/li>\n<li>Matibabu ya uso:Mipako ya unga, Mabati ya moto<\/li>\n<li>Urefu: 2m, 2.5m, 3m, 5m, 6m, 7.5m, nk.<\/li>\n<li>Utaratibu wa Kuishi: Gia<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Voltage:Corner Suspend Platform From China Factory accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Nepal, Tanzania etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Access Platforms in Denmark, Boom Lift Scissor Lift in Lilongwe<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale162.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High Building Cleaning Equipment\/ Special Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya mfano: ZLP630<\/li>\n<li>Nyenzo: Chuma, Aloi ya Alumini<\/li>\n<li>Rangi: Nyekundu, Njano, Bluu, nk<\/li>\n<li>Matibabu ya uso:Mipako ya unga, Mabati ya moto<\/li>\n<li>Urefu: 2m, 2.5m, 3m, 5m, 6m, 7.5m, nk.<\/li>\n<li>Utaratibu wa Kuishi: Gia<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Nguvu: 1.5kw, 1.8kw, 2kw<\/li>\n<li>Uwezo wa Upakiaji uliokadiriwa: 150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Max. Urefu wa Kuinua: 200m<\/li>\n<li>Voltage:Special Suspended Platform accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Honduras, Kharkiv, Campinas, Allahabad etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Swing Stage Scaffold in Nepal, Wire Rope Suspended Platform For Sale in Tanzania<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale68.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Shanghai Success turkey suspended cradles<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP<\/li>\n<li>Name:turkey suspended cradles<\/li>\n<li>Rangi: hiari<\/li>\n<li>Ugavi wa umeme (V):220,380,415,440<\/li>\n<li>Kifaa cha Usalama:kipengee 7<\/li>\n<li>Nyenzo: chuma au alumini<\/li>\n<li>Matibabu ya uso: Kunyunyizia rangi au mabati ya dip-moto<\/li>\n<li>Sehemu ya Bure: usambazaji<\/li>\n<li>kamba ya chuma: mabati ya kuzamisha moto<\/li>\n<li>Pandisha: Imetengenezwa kwa alumini ya kutupwa<\/li>\n<li>Cheti:CE,ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Monterrey, Tangier, Campinas, Honduras etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Work Platforms, Wire Rope Suspended Platform For Sale in Tanzania<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale167.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP 630 Suspended Platform\/Cradle Window Cleaning<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya mfano: ZLP630<\/li>\n<li>Imekadiriwa Uwezo wa Kupakia: 630kg<\/li>\n<li>Colour:Red,Can be Customized<\/li>\n<li>Motor Power:1.5KW*2<\/li>\n<li>Platform Dimension:6000*0.72*1300<\/li>\n<li>Voltage:220V\/380V\/415V-3Phase\/50hz\/60HZ<\/li>\n<li>Steel Rope Diamter:8.3mm<\/li>\n<li>Lifting Height:100m-120m<\/li>\n<li>Model:ZLP630 Suspended Working Platform<\/li>\n<li>Locking Cable Angel:3-8&deg;<\/li>\n<li>Overhang Length of Front Beam:1.3-1.5m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Allahabad, Lilongwe, Tanzania, Kharkiv etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Rope Suspended Platform Window Cleaning Gondola in Allahabad, Swing Stage Scaffold in Nepal<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of ZLP-630 circular platform \/window cleaning lift used suspended platforms Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Jinfei Tianhong Model Number:ZLP800 Supply:Manufacturer Approved:CE, <\/p>","protected":false},"author":1,"featured_media":192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[8824,8822,8823,584,8825,8826],"class_list":["post-2130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-boom-lift-scissor-lift-in-lilongwe","tag-rope-suspended-platform-window-cleaning-gondola-in-allahabad","tag-suspended-access-platforms-in-denmark","tag-suspended-work-platforms","tag-swing-stage-scaffold-in-nepal","tag-wire-rope-suspended-platform-for-sale-in-tanzania"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/comments?post=2130"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media\/192"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media?parent=2130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/categories?post=2130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/tags?post=2130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}