{"id":2113,"date":"2017-05-25T11:25:23","date_gmt":"2017-05-25T11:25:23","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/factory-in-china-zlp500630800-powered-suspended-platformcradlewindow-cleaning-equipment.html"},"modified":"2017-05-25T11:25:23","modified_gmt":"2017-05-25T11:25:23","slug":"factory-in-china-zlp500630800-powered-suspended-platformcradlewindow-cleaning-equipment","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/sw\/factory-in-china-zlp500630800-powered-suspended-platformcradlewindow-cleaning-equipment.html","title":{"rendered":"Factory in China ZLP500\/630\/800 Powered Suspended Platform\/cradle\/window cleaning equipment"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale22.jpg\" alt=\"Factory in China ZLP500\/630\/800 Powered Suspended Platform\/cradle\/window cleaning equipment\" \/><br \/>\nImage of Factory in China ZLP500\/630\/800 Powered Suspended Platform\/cradle\/window cleaning equipment<\/p>\n<h3 class=\"alpha-title\">Maelezo ya Haraka: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP<\/li>\n<li>Steel Rope Diamerter:8.3mm<\/li>\n<li>Rated Power:1.5KW X 2<\/li>\n<li>Voltage: 380V au kulingana na hitaji la mteja<\/li>\n<li>Usage:working plarform<\/li>\n<li>Material:Steel or aluminum alloy<\/li>\n<li>Vyeti: ISO, GOST, CE<\/li>\n<li>Name:ZLP630\/800 Powered Suspended Platform\/cradle\/window cleaning equipment<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Video inayohusiana: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pNURQX2ZoSVNRZUU\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Maelezo: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale87.jpg\" alt=\"Factory in China ZLP500\/630\/800 Powered Suspended Platform\/cradle\/window cleaning equipment\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale8.jpg\" alt=\"Factory in China ZLP500\/630\/800 Powered Suspended Platform\/cradle\/window cleaning equipment\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Onyesha Vifaa Vinavyohusiana: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale11.jpg\" alt=\"Factory in China ZLP500\/630\/800 Powered Suspended Platform\/cradle\/window cleaning equipment Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale27.jpg\" alt=\"Factory in China ZLP500\/630\/800 Powered Suspended Platform\/cradle\/window cleaning equipment Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Acha ujumbe: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Unaweza pia kupenda:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale147.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">800KG suspended scaffolding characteristics<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP<\/li>\n<li>Name:suspended scaffolding characteristics<\/li>\n<li>Rangi: hiari<\/li>\n<li>Ugavi wa umeme (V):220,380,415,440<\/li>\n<li>Kifaa cha Usalama:kipengee 7<\/li>\n<li>Nyenzo: chuma au alumini<\/li>\n<li>Matibabu ya uso: Kunyunyizia rangi au mabati ya dip-moto<\/li>\n<li>Sehemu ya Bure: usambazaji<\/li>\n<li>kamba ya chuma: mabati ya kuzamisha moto<\/li>\n<li>Pandisha: Imetengenezwa kwa alumini ya kutupwa<\/li>\n<li>Cheti:CE,ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bari, Haiphong, Karachi etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Electric Gondola Platforms in Bari, Hanging Scaffold Suspended Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale224.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Custom-Made Suspended Working Platform\/suspended cradle\/gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Uchina (Bara)<\/li>\n<li>Jina la Biashara: Jukwaa Lililosimamishwa Cradle Gondola<\/li>\n<li>Nambari ya Mfano: ZLP500\/630\/800\/1000<\/li>\n<li>Jina: Jukwaa la Kamba Lililosimamishwa AU Jukwaa la Kufanya Kazi<\/li>\n<li>Maombi ya Jukwaa la Cradle: Utunzaji wa jengo, kusafisha, uchoraji<\/li>\n<li>Urekebishaji wa Paa: 1, kusimamishwa kwa counter 2, clamp ya parapet<\/li>\n<li>Rangi ya Jukwaa:Nyekundu,Silver,Moto Imetengenezwa kwa Mabati<\/li>\n<li>Kifaa cha usalama: kufuli ya usalama, kamba salama n.k<\/li>\n<li>Nguvu ya Nia: Kiingilio cha Umeme<\/li>\n<li>Sura ya Jukwaa: muundo wa cuboid au maalum<\/li>\n<li>Kiwango cha jukwaa: CE, GOST, ISO<\/li>\n<li>Nyenzo ya Jukwaa: Aloi ya Chuma au Alumini<\/li>\n<li>Mwili wa Jukwaa:bila malipo iliyokusanywa na sahani ya kawaida<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Omdurman, Singapore etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform For Plastering in Haiphong, Electric Suspended Platform in Karachi<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale267.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">LTD630\/800 hoist for ZLP630\/800 suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Hali:Mpya<\/li>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Model Number:LTD8.O<\/li>\n<li>Imekadiriwa Uwezo wa Kupakia(kg):800Kg<\/li>\n<li>Hoisting Speed:9.0m\/min<\/li>\n<li>Loder Weight:800kg<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Power:1.8kw<\/li>\n<li>Voltage:380V<\/li>\n<li>Rotational speed:1420r\/min<\/li>\n<li>Fequency:50Hz<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Nashik, Warsaw, Morocco, Bari etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Temporary Suspended Access Platform in Omdurman, Powered Access Platforms in Singapore<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale245.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Suspended Working Platform With Wheels<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya mfano: ZLP630<\/li>\n<li>Nyenzo: Chuma, Aloi ya Alumini<\/li>\n<li>Rangi: Nyekundu, Njano, Bluu, nk<\/li>\n<li>Matibabu ya uso:Kupaka poda, mabati ya moto<\/li>\n<li>Urefu: 2m, 2.5m, 3m, 5m, 6m, 7.5m, nk.<\/li>\n<li>Nguvu: 1.5kw, 1.8kw, 2kw<\/li>\n<li>Uwezo wa Upakiaji uliokadiriwa: 150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Voltage:Suspended Working Platform accept different voltages:220V,440V,etc<\/li>\n<li>Maombi:Jengo la juu, tanki kubwa, Chimney, Mabwawa, Madaraja, Derrick, nk<\/li>\n<li>Jukwaa maalum: Inaweza kubinafsishwa na kutolewa<\/li>\n<li>Uthibitisho: ISO, CE<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bangkok, Dakar, Morocco, Nashik etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hanging Scaffold Suspended Platform, Powered Access Platforms in Singapore<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale255.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP250\/ 500 BMU System Suspended Platform For Construction<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Model Number:HJ-SUP-1008<\/li>\n<li>Uwezo wa kupakia: 500kgs;630kgs;800kgs;1000kgs<\/li>\n<li>Nyenzo: Chuma cha Mabati\/Alumini<\/li>\n<li>Matibabu ya uso:Mabati;HDG au kunyunyuzia kwa plastiki<\/li>\n<li>Urefu wa Jukwaa:2m-12m;OEM<\/li>\n<li>Nguvu ya Magari ya Umeme: 1.5KW*2; 1.8KW*2; 2.2KW*2;3.0KW*2<\/li>\n<li>Voltage:380V\/50HZ\/AWAMU TATU 220V\/50HZ\/AWAMU MOJA<\/li>\n<li>MAX Urefu wa kuinua: 200M<\/li>\n<li>Rangi: Bluu, machungwa, nyekundu, fedha au umeboreshwa<\/li>\n<li>Maombi: Ujenzi wa Jengo; Uchoraji, kusafisha madirisha<\/li>\n<li>Udhibitisho: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bari, Karachi, Singapore, Warsaw etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Electric Gondola Platforms in Bari, Temporary Suspended Access Platform in Omdurman<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Factory in China ZLP500\/630\/800 Powered Suspended Platform\/cradle\/window cleaning equipment Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP Steel Rope Diamerter:8.3mm <\/p>","protected":false},"author":1,"featured_media":95,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[8732,8734,2259,8736,8733,8735],"class_list":["post-2113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-electric-gondola-platforms-in-bari","tag-electric-suspended-platform-in-karachi","tag-hanging-scaffold-suspended-platform","tag-powered-access-platforms-in-singapore","tag-suspended-platform-for-plastering-in-haiphong","tag-temporary-suspended-access-platform-in-omdurman"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/comments?post=2113"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media\/95"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media?parent=2113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/categories?post=2113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/tags?post=2113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}