{"id":2106,"date":"2017-05-25T06:20:02","date_gmt":"2017-05-25T06:20:02","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/aluminum-suspended-platform-of-construction-fast-packaged.html"},"modified":"2017-05-25T06:20:02","modified_gmt":"2017-05-25T06:20:02","slug":"aluminum-suspended-platform-of-construction-fast-packaged","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/sw\/aluminum-suspended-platform-of-construction-fast-packaged.html","title":{"rendered":"Aluminum suspended platform of construction fast packaged"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale205.jpg\" alt=\"Aluminum suspended platform of construction fast packaged\" \/><br \/>\nImage of Aluminum suspended platform of construction fast packaged<\/p>\n<h3 class=\"alpha-title\">Maelezo ya Haraka: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP<\/li>\n<li>voltage:380V ,220v etc<\/li>\n<li>Length:assemble any size in the rage of 1m to 30m<\/li>\n<li>safty device:safty lock<\/li>\n<li>roll:vertical ,horizontal<\/li>\n<li>motor:LTD80,LTD1000S,LTD630<\/li>\n<li>automatic levelling system:locating pin<\/li>\n<li>overspeed safety device:certrifugal speed limiter<\/li>\n<li>emergency manual descent:speed reducer<\/li>\n<li>certificates:CE ISO<\/li>\n<li>Warranty: mwaka mmoja<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Video inayohusiana: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pcURWUzR1WldsR3M\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Maelezo: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale150.jpg\" alt=\"Aluminum suspended platform of construction fast packaged\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale98.jpg\" alt=\"Aluminum suspended platform of construction fast packaged\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Onyesha Vifaa Vinavyohusiana: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale98.jpg\" alt=\"Aluminum suspended platform of construction fast packaged Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale84.jpg\" alt=\"Aluminum suspended platform of construction fast packaged Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Acha ujumbe: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Unaweza pia kupenda:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale162.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">(CE &#038; GOST) ZLP630 ventana plataforma de limpieza<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Uchina (Bara)<\/li>\n<li>Jina la Biashara:CHINA-Success<\/li>\n<li>Nambari ya Mfano: ZLP<\/li>\n<li>Usage:Building facade cleaning<\/li>\n<li>Colour:Red or other colors<\/li>\n<li>Vyeti: ISO, GOST, CE<\/li>\n<li>Chanzo cha Nguvu:Umeme<\/li>\n<li>Drive Type:Wire rope hoisting<\/li>\n<li>Application:Tall Building Maintenance<\/li>\n<li>Origin:China<\/li>\n<li>Kasi ya Kuinua:8-10m\/min<\/li>\n<li>Lifting Height and Cable Length:100m<\/li>\n<li>Voltage:380V50HZ 3Phases or according to  customer need<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bogor, Depok, Kalyan-Dombivali etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Hoisting Machine in Bogor, Mature-Tech Access Suspended Platforms Inc<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale112.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Electric Cradle\/Suspended platform\/Gondola for Window Cleaning Machine<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP1000<\/li>\n<li>Utaratibu wa Kuinua: kamba ya waya ya chuma<\/li>\n<li>Inua Hifadhi \/ Utendaji:Pandisha<\/li>\n<li>Nguvu:2.2kw*2<\/li>\n<li>Imekadiriwa Uwezo wa Kupakia:1000kg<\/li>\n<li>Dak. Urefu wa Kuinua: 10m<\/li>\n<li>Max. Urefu wa Kuinua: 100m<\/li>\n<li>Ukubwa wa Jedwali: 7.5 (2.5 * 3) * 0.72 * 1.3m<\/li>\n<li>Vipimo vya jumla: 1850 * 1000 * 950 mm<\/li>\n<li>Uzito: 1200 kg<\/li>\n<li>Uthibitisho: CE ISO<\/li>\n<li>Udhamini: Mwaka Mmoja<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Jina: Jukwaa Lililosimamishwa kwa Kamba<\/li>\n<li>Rangi:Nyekundu, utelezi<\/li>\n<li>Voltage: 220v\/380v\/50hz<\/li>\n<li>Nyenzo: Chuma, Aluminium, Galvanizing<\/li>\n<li>Uzito wa kukabiliana: 1000kg<\/li>\n<li>Kasi ya kuinua:8~10m\/min<\/li>\n<li>Mfano: ZLP1000<\/li>\n<li>Urefu wa kuinua: 100 m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: New Taipei, Taiwan etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Tracked Access Platforms in Depok, Zlp800 Aluminum Lifting Speed Suspended Platform in Kalyan-Dombivali<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale10.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">man basket platform from China (CE\/GOST standard)<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP800<\/li>\n<li>Mifano Nyingine::ZLP1000, ZLP630, ZLP500<\/li>\n<li>Nyenzo ya Jukwaa: Aloi ya Chuma au Alumini<\/li>\n<li>Name:man basket platform<\/li>\n<li>Platform Usage:as a platform for high rise building work<\/li>\n<li>Platform Shape:long shape, fan, circle, round, U shape<\/li>\n<li>Maombi ya Jukwaa:dumisha facade ya jengo, mapambo au kusafisha<\/li>\n<li>Platform Length:1m-8m, can assembly as require<\/li>\n<li>Uwezo wa Jukwaa: kutoka 250kg hadi 1000kg<\/li>\n<li>Platform motor:LTD630\/ 800\/ 1000 Hoist<\/li>\n<li>Safety device:safety lock<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Guatemala, Ivory Coast, La Plata, Bogor etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Sky Climber Platform in New Taipei, Mobile Suspended Platform in Taiwan<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale164.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Special Designed High Building Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya mfano: ZLP630<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Nyenzo: Chuma, Aloi ya Alumini<\/li>\n<li>Rangi: Nyekundu, Njano, Bluu, nk<\/li>\n<li>Matibabu ya uso:Mipako ya unga, Mabati ya moto<\/li>\n<li>Urefu: 2m, 2.5m, 3m, 5m, 6m, 7.5m, nk.<\/li>\n<li>Utaratibu wa Kuishi: Gia<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Nguvu: 1.5kw, 1.8kw, 2kw<\/li>\n<li>Uwezo wa Upakiaji uliokadiriwa: 150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Max. Urefu wa Kuinua: 200m<\/li>\n<li>Voltage:High Building Suspended Platform accept different voltage,220V, 440V.<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Kathmandu, Kumasi, La Plata, Guatemala etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mature-Tech Access Suspended Platforms Inc, Mobile Suspended Platform in Taiwan<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale250.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP glass facade cleaning suspended platform, Success Brand New<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Model Number:elevated suspended platform<\/li>\n<li>Models::ZLP1000, ZLP800, ZLP630, ZLP500<\/li>\n<li>Name: glass facade cleaning  suspended platform<\/li>\n<li>Modular Suspended Platform Application:building maintenance<\/li>\n<li>Kurekebisha paa: 1, kusimamishwa kwa counter 2, clamp ya parapet<\/li>\n<li>Mwili wa Jukwaa:bila malipo iliyokusanywa na moduli<\/li>\n<li>Nyenzo ya Jukwaa: Aloi ya Chuma au Alumini<\/li>\n<li>Rangi ya jukwaa:nyekundu\/fedha\/utengenezo maalum<\/li>\n<li>Sura ya Jukwaa: muundo wa cuboid au maalum<\/li>\n<li>Nguvu ya Nia: Kiingilio cha Umeme<\/li>\n<li>Safety device for cradle platform:safety lock\/ safety rope<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bogor, Kalyan-Dombivali, Taiwan, Ivory Coast etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Hoisting Machine in Bogor, Suspended Sky Climber Platform in New Taipei<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Aluminum suspended platform of construction fast packaged Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP voltage:380V ,220v etc Length:assemble any <\/p>","protected":false},"author":1,"featured_media":259,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1542,8700,8697,8699,568,8698],"class_list":["post-2106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-mature-tech-access-suspended-platforms-inc","tag-mobile-suspended-platform-in-taiwan","tag-suspended-platform-hoisting-machine-in-bogor","tag-suspended-sky-climber-platform-in-new-taipei","tag-tracked-access-platforms-in-depok","tag-zlp800-aluminum-lifting-speed-suspended-platform-in-kalyan-dombivali"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/comments?post=2106"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/2106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media\/259"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media?parent=2106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/categories?post=2106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/tags?post=2106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}