{"id":1755,"date":"2017-05-23T16:38:23","date_gmt":"2017-05-23T16:38:23","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/professional-design-suspended-platform-parapet.html"},"modified":"2017-05-23T16:38:23","modified_gmt":"2017-05-23T16:38:23","slug":"professional-design-suspended-platform-parapet","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/sw\/professional-design-suspended-platform-parapet.html","title":{"rendered":"Professional Design Suspended Platform Parapet"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale225.jpg\" alt=\"Professional Design Suspended Platform Parapet\" \/><br \/>\nImage of Professional Design Suspended Platform Parapet<\/p>\n<h3 class=\"alpha-title\">Maelezo ya Haraka: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Brand Name:JH-Success<\/li>\n<li>Nambari ya Mfano: ZLP500\/630\/800\/1000<\/li>\n<li>Product:ZLP800 Suspended Platform<\/li>\n<li>Rated load:500kg  630kg  800kg 1000kg<\/li>\n<li>Kasi ya kuinua: 8-10m \/ min<\/li>\n<li>Platform Size(Lwh):6000(1+2+3m)*720*1300<\/li>\n<li>Power:1.5KW*2, 1.8KW*2<\/li>\n<li>Voltage:110V,220V,240V,400V,415V,440V are available<\/li>\n<li>Certification:CE, ISO,GOST<\/li>\n<li>Uzito wa kukabiliana: 1000kg<\/li>\n<li>Material:Alloy Steel\/Hot dipping\/steel<\/li>\n<li>Warranty:12 Months<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Video inayohusiana: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pNWw4LUNOb0N3eVE\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Maelezo: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale54.jpg\" alt=\"Professional Design Suspended Platform Parapet\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale90.jpg\" alt=\"Professional Design Suspended Platform Parapet\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Onyesha Vifaa Vinavyohusiana: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale87.jpg\" alt=\"Professional Design Suspended Platform Parapet Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale23.jpg\" alt=\"Professional Design Suspended Platform Parapet Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Acha ujumbe: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Unaweza pia kupenda:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale203.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Approved CE ISO GOST Suspended platform\/Gondola\/Hanging Scaffolds Made in China<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP1000<\/li>\n<li>Utaratibu wa Kuinua: kamba ya waya ya chuma<\/li>\n<li>Inua Hifadhi \/ Utendaji:Pandisha<\/li>\n<li>Nguvu:2.2kw*2<\/li>\n<li>Imekadiriwa Uwezo wa Kupakia:1000kg<\/li>\n<li>Dak. Urefu wa Kuinua: 10m<\/li>\n<li>Max. Urefu wa Kuinua: 100m<\/li>\n<li>Ukubwa wa Jedwali: 7.5 (2.5 * 3) * 0.72 * 1.3m<\/li>\n<li>Vipimo vya jumla: 1850 * 1000 * 950 mm<\/li>\n<li>Uzito: 1200 kg<\/li>\n<li>Uthibitisho: CE ISO<\/li>\n<li>Udhamini: Mwaka Mmoja<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Jina: Jukwaa Lililosimamishwa kwa Kamba<\/li>\n<li>Rangi:Nyekundu, utelezi<\/li>\n<li>Voltage: 220v\/380v\/50hz<\/li>\n<li>Nyenzo: Chuma, Aluminium, Galvanizing<\/li>\n<li>Uzito wa kukabiliana: 1000kg<\/li>\n<li>Kasi ya kuinua:8~10m\/min<\/li>\n<li>Mfano: ZLP1000<\/li>\n<li>Urefu wa kuinua: 100 m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Brasilia, Croatia, Kaohsiung etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Hoist Mini Electric Hoist in Brasilia, Window Cleaning Scaffold<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale198.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">China Manufacturer ZLP Construction\/Wall\/Window Cleaning Suspended Platform\/ Cradle\/ Gondola\/ Scaffold for sale<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara:Jukwaa Lililosimamishwa, Jukwaa Lililosimamishwa la ZLP<\/li>\n<li>Nambari ya Mfano: Jukwaa Lililosimamishwa<\/li>\n<li>Suspended Platform:ZLP 630 Suspended Platform<\/li>\n<li>Material:Steel Suspended Platform<\/li>\n<li>Aina: ZLP630<\/li>\n<li>Urefu wa Jukwaa: 6m<\/li>\n<li>Uliopimwa Mzigo(kg):630kg<\/li>\n<li>Kasi ya Kuinua:8-10m\/min<\/li>\n<li>Matumizi: Jukwaa Lililosimamishwa la ZLP<\/li>\n<li>Muda wa Uwasilishaji: Siku 7- Jukwaa Lililosimamishwa<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Navi Mumbai, United Kingdom etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Lift Scaffolding Platform in Croatia, Zlp1000a Suspended Platform in Kaohsiung<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale252.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">high power electric motor LTD series mainly part of suspended platform electrical power motor<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Hali:Mpya<\/li>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Model Number:LTD6.3\/LTD8.0\/LTD1000S<\/li>\n<li>Usage:Construction Hoist<\/li>\n<li>Power Source:Electric<\/li>\n<li>Sling Type:Wire Rope<\/li>\n<li>Maximum Lifting Weight:800kg<\/li>\n<li>Maximum Lifting Height:100m<\/li>\n<li>Lift Speed:9.0m\/min<\/li>\n<li>Certification:ISO CE<\/li>\n<li>Udhamini: Mwaka 1<\/li>\n<li>After-sales Service Provided:No overseas service provided<\/li>\n<li>Voltage:380v(requirement)<\/li>\n<li>Power:1.8kw<\/li>\n<li>Rotation speed:1420 r\/min<\/li>\n<li>Braking moment:15Nm<\/li>\n<li>Frequency:50 HZ<\/li>\n<li>Size:35cm*30cm*62cm<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Howrah, Macedonia, Guarulhos, Brasilia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aerial Boom Lift in Navi Mumbai, High Quality Electric Suspended Platform in United Kingdom<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale258.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Shanghai High Quality Electric Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Model Number:HJ-SUP161<\/li>\n<li>Product name:Shanghai High Quality Electric Suspended Platform<\/li>\n<li>Ulinzi wa uso: Uchoraji na Galvanize<\/li>\n<li>Keywords:High Quality Electric Suspended Platform<\/li>\n<li>Rangi: Nyekundu, Njano, Nyingine<\/li>\n<li>Udhibitisho: ISO , CE , GOST imeonekana<\/li>\n<li>Aina: majukwaa ya ujenzi<\/li>\n<li>Cheti:ISO , CE , GOST imethibitishwa<\/li>\n<li>Soko: kimataifa, zaidi ya 30contries<\/li>\n<li>Bidhaa:simamisha majukwaa<\/li>\n<li>mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Colombo, South Sudan, Guarulhos, Howrah etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Window Cleaning Scaffold, High Quality Electric Suspended Platform in United Kingdom<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale206.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP630 suspended platforms aluminum building maintenance units<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Model Number:HJ-SUP-295<\/li>\n<li>Uwezo wa kupakia: 500kgs;630kgs;800kgs;1000kgs<\/li>\n<li>Nyenzo: Chuma cha Mabati\/Alumini<\/li>\n<li>Matibabu ya uso:Mabati;HDG au kunyunyuzia kwa plastiki<\/li>\n<li>Urefu wa Jukwaa:2m-12m;OEM<\/li>\n<li>Nguvu ya Magari ya Umeme: 1.5KW*2; 1.8KW*2; 2.2KW*2;3.0KW*2<\/li>\n<li>Lifting Speed:9.3M\/min<\/li>\n<li>Voltage:380V\/50HZ\/AWAMU TATU 220V\/50HZ\/AWAMU MOJA<\/li>\n<li>MAX Urefu wa kuinua: 200M<\/li>\n<li>Maombi: Ujenzi wa Jengo; Uchoraji, kusafisha madirisha<\/li>\n<li>Udhibitisho: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Brasilia, Kaohsiung, United Kingdom, Macedonia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Hoist Mini Electric Hoist in Brasilia, Aerial Boom Lift in Navi Mumbai<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Professional Design Suspended Platform Parapet Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:JH-Success Model Number:ZLP500\/630\/800\/1000 Product:ZLP800 Suspended Platform Rated load:500kg 630kg 800kg <\/p>","protected":false},"author":1,"featured_media":10,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7165,7166,7163,7162,7161,7164],"class_list":["post-1755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aerial-boom-lift-in-navi-mumbai","tag-high-quality-electric-suspended-platform-in-united-kingdom","tag-suspended-lift-scaffolding-platform-in-croatia","tag-suspended-platform-hoist-mini-electric-hoist-in-brasilia","tag-window-cleaning-scaffold","tag-zlp1000a-suspended-platform-in-kaohsiung"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/1755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/comments?post=1755"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/1755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media\/10"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media?parent=1755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/categories?post=1755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/tags?post=1755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}