{"id":1075,"date":"2017-05-18T07:07:18","date_gmt":"2017-05-18T07:07:18","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/china-industrial-use-personal-platform-lift.html"},"modified":"2017-05-18T07:07:18","modified_gmt":"2017-05-18T07:07:18","slug":"china-industrial-use-personal-platform-lift","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/sw\/china-industrial-use-personal-platform-lift.html","title":{"rendered":"China industrial use personal platform lift"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale105.jpg\" alt=\"China industrial use personal platform lift\" \/><br \/>\nImage of China industrial use personal platform lift<\/p>\n<h3 class=\"alpha-title\">Maelezo ya Haraka: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Name:industrial use personal platform lift<\/li>\n<li>Rangi: hiari<\/li>\n<li>Ugavi wa umeme (V):220,380,415,440<\/li>\n<li>Kifaa cha Usalama:kipengee 7<\/li>\n<li>Nyenzo: chuma au alumini<\/li>\n<li>Matibabu ya uso: Kunyunyizia rangi au mabati ya dip-moto<\/li>\n<li>Sehemu ya Bure: usambazaji<\/li>\n<li>kamba ya chuma: mabati ya kuzamisha moto<\/li>\n<li>Pandisha: Imetengenezwa kwa alumini ya kutupwa<\/li>\n<li>Cheti:CE,ISO9001-2008<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Video inayohusiana: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pb05iM2VXbWRkREk\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Maelezo: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale93.jpg\" alt=\"China industrial use personal platform lift\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale11.jpg\" alt=\"China industrial use personal platform lift\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Onyesha Vifaa Vinavyohusiana: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale73.jpg\" alt=\"China industrial use personal platform lift Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale80.jpg\" alt=\"China industrial use personal platform lift Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Acha ujumbe: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Unaweza pia kupenda:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale196.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">200m-height Extremely Safe System Suspended Platform (ZLP-800)<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Uzito uliopimwa: 800kg<\/li>\n<li>Kasi ya kuinua:8~10m\/min<\/li>\n<li>Urefu wa kuinua: 200m<\/li>\n<li>Cable:200m<\/li>\n<li>Counterweight:800kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Caloocan, Howrah, Li\u00e8ge etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminum Stage Platform For Cleaning in Caloocan, Work Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale225.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction building aerial safety electric zlp630 suspended rope platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Nambari ya Mfano: ZLP500\/630\/800\/1000<\/li>\n<li>Uwezo wa kupakia: 500kgs;630kgs;800kgs;1000kgs<\/li>\n<li>Nyenzo: Chuma cha Mabati\/Alumini<\/li>\n<li>Matibabu ya uso:Mabati;HDG au kunyunyuzia kwa plastiki<\/li>\n<li>Urefu wa Jukwaa:2m-12m;OEM<\/li>\n<li>Nguvu ya Magari ya Umeme: 1.5KW*2; 1.8KW*2; 2.2KW*2;3.0KW*2<\/li>\n<li>Voltage:380V\/50HZ\/AWAMU TATU 220V\/50HZ\/AWAMU MOJA<\/li>\n<li>MAX Urefu wa kuinua: 200M<\/li>\n<li>Rangi: Bluu, machungwa, nyekundu, fedha au umeboreshwa<\/li>\n<li>Maombi: Ujenzi wa Jengo; Uchoraji, kusafisha madirisha<\/li>\n<li>Udhibitisho: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Myanmar, Valencia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Economical Suspended Working Platform Safety in Howrah, Suspended Tension Leg Platform in Li\u00e8ge<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale239.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">LTD630\/800 hoist for ZLP630\/800 suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Hali:Mpya<\/li>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: Mafanikio<\/li>\n<li>Model Number:LTD8.O<\/li>\n<li>Imekadiriwa Uwezo wa Kupakia(kg):800Kg<\/li>\n<li>Hoisting Speed:9.0m\/min<\/li>\n<li>Loder Weight:800kg<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Power:1.8kw<\/li>\n<li>Voltage:380V<\/li>\n<li>Rotational speed:1420r\/min<\/li>\n<li>Fequency:50Hz<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: India , Ivory Coast, Auckland, Caloocan etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Crane Loading Platform in Myanmar, Lift Elevated Work Window Cleaning Platform in Valencia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale38.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Stable 220V 50HZ ZLP Building Cleaning Glass Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: JH<\/li>\n<li>Model Number:JH-ZLP-123<\/li>\n<li>Lift Mechanism:Rack &amp; Pinion<\/li>\n<li>Lift Drive \/ Actuation:Electric Motor<\/li>\n<li>Power:50HZ<\/li>\n<li>Rated Loading Capacity:250-1000kg<\/li>\n<li>Min. Lifting Height:100m<\/li>\n<li>Max. Lifting Height:150m<\/li>\n<li>Table Size:1+2+3m \/3*2.5m<\/li>\n<li>Overall Dimensions:6m \/ 7m<\/li>\n<li>Weight:1000kg<\/li>\n<li>Certification:CE. GOST ISO<\/li>\n<li>Warranty: mwaka mmoja<\/li>\n<li>Huduma ya Baada ya Uuzaji Imetolewa: Wahandisi wanaopatikana kwa huduma za mashine nje ya nchi<\/li>\n<li>Suspended Platform:Stable 220V 50HZ ZLP Building Cleaning Glass Suspended Platform<\/li>\n<li>color:red or as clients need<\/li>\n<li>power:220V or 380V etc<\/li>\n<li>material:a-alloy or steel<\/li>\n<li>Website:www.bjfth.com<\/li>\n<li>Model Numbe:ZLP Series suspended platform<\/li>\n<li>platform length:1-7.5m<\/li>\n<li>Main Markets:Australia\/South Asia\/Eastern\/Bazil\/South Africa\/UAE<\/li>\n<li>Rated load:630kg\/800kg\/1000kg<\/li>\n<li>work heighte:30-200m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Nezahualc\u00f3yotl, Thailand, Auckland, India  etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Work Platform, Lift Elevated Work Window Cleaning Platform in Valencia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale141.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP aluminum and steel type suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Mahali pa asili: Shanghai, Uchina (Bara)<\/li>\n<li>Jina la Biashara: JH<\/li>\n<li>Nambari ya Mfano: ZLP800<\/li>\n<li>Jina: Jukwaa Lililosimamishwa<\/li>\n<li>Mfano: ZLP800<\/li>\n<li>Chapa: Mafanikio<\/li>\n<li>Nyenzo: Alumini<\/li>\n<li>Ukubwa wa jukwaa: 7.5 * 0.72 * 1.2m<\/li>\n<li>Urefu wa kazi: 100 m<\/li>\n<li>Kamba ya waya ya chuma: 9.1mm<\/li>\n<li>Kebo:3*2.5+2*1.5<\/li>\n<li>Utaratibu wa kusimamishwa:Mabati yenye joto kali<\/li>\n<li>Uzito wa kukabiliana: 1000kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Caloocan, Li\u00e8ge, Valencia, Ivory Coast etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminum Stage Platform For Cleaning in Caloocan, Crane Loading Platform in Myanmar<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Acha ujumbe<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of China industrial use personal platform lift Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000 After-sales Service Provided:Engineers available to service <\/p>","protected":false},"author":1,"featured_media":183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[4311,4314,4312,4315,4313,4310],"class_list":["post-1075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aluminum-stage-platform-for-cleaning-in-caloocan","tag-crane-loading-platform-in-myanmar","tag-economical-suspended-working-platform-safety-in-howrah","tag-lift-elevated-work-window-cleaning-platform-in-valencia","tag-suspended-tension-leg-platform-in-liege","tag-work-platform"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/1075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/comments?post=1075"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/posts\/1075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media\/183"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/media?parent=1075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/categories?post=1075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/sw\/wp-json\/wp\/v2\/tags?post=1075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}