{"id":642,"date":"2017-05-18T04:40:14","date_gmt":"2017-05-18T04:40:14","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/advanced-zlp-630-cheap-gondola-cradle-suspended-platform.html"},"modified":"2017-05-18T04:40:14","modified_gmt":"2017-05-18T04:40:14","slug":"advanced-zlp-630-cheap-gondola-cradle-suspended-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/advanced-zlp-630-cheap-gondola-cradle-suspended-platform.html","title":{"rendered":"Advanced zlp 630 cheap gondola cradle suspended platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale145.jpg\" alt=\"Advanced zlp 630 cheap gondola cradle suspended platform\" \/><br \/>\nImage of Advanced zlp 630 cheap gondola cradle suspended platform<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Name:zlp 630 cheap gondola cradle suspended platform<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pMVV5U3pXdzRPT2s\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale52.jpg\" alt=\"Advanced zlp 630 cheap gondola cradle suspended platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale163.jpg\" alt=\"Advanced zlp 630 cheap gondola cradle suspended platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale17.jpg\" alt=\"Advanced zlp 630 cheap gondola cradle suspended platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale27.jpg\" alt=\"Advanced zlp 630 cheap gondola cradle suspended platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale271.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">A single person suspended platform\/Scaffold tower<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Capacidade de carga nominal (kg): 630 kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8-10 m\/min<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 300 m<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>formato da plataforma: longo, leque, c\u00edrculo, formato de U\u2026<\/li>\n<li>Material da plataforma: a\u00e7o ou liga A<\/li>\n<li>capacidade: de 250kg a 1000kg<\/li>\n<li>Carga nominal: 500 kg 630 kg 800 kg 1000 kg<\/li>\n<li>Comprimento da plataforma: 1m-7,5m<\/li>\n<li>boa qualidade:CE, Gost, certificado ISO aprovado<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Basra, Djibouti, \u0130zmir etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mast Working Platform in Basra, Sky Climber Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale51.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">China manufacturer CE approved electric platform lift, Success suspended building work platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Brand Name:JH<\/li>\n<li>Model Number:JH-ZLP-W50<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: cremalheira e pinh\u00e3o<\/li>\n<li>Acionamento\/Atua\u00e7\u00e3o do Elevador: Motor El\u00e9trico<\/li>\n<li>Pot\u00eancia: 50HZ<\/li>\n<li>Capacidade de carga nominal: 250-1000 kg<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: 100 m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150 m<\/li>\n<li>Tamanho da mesa: 1+2+3m \/3*2,5m<\/li>\n<li>Dimens\u00f5es totais: 6m \/ 7m<\/li>\n<li>Peso: 1000 kg<\/li>\n<li>Certifica\u00e7\u00e3o: CE. GOST ISO<\/li>\n<li>Garantia: um ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Success suspended building work platform:China manufacturer CE approved electric platform lift<\/li>\n<li>cor: vermelho ou conforme a necessidade do cliente<\/li>\n<li>pot\u00eancia: 220V ou 380V etc.<\/li>\n<li>material: liga a ou a\u00e7o<\/li>\n<li>Site: www.bjfth.com<\/li>\n<li>Model Numbe:ZLP series CE approved electric platform lift, building work platform<\/li>\n<li>comprimento da plataforma: 1-7,5 m<\/li>\n<li>Carga nominal: 630 kg\/800 kg\/1000 kg<\/li>\n<li>work heighte:100m<\/li>\n<li>Principais mercados: Austr\u00e1lia\/Sul da \u00c1sia\/Leste\/Bahia\/\u00c1frica do Sul\/Emirados \u00c1rabes Unidos<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Morocco, United Kingdom etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Maximum 4 In 1 Work Platform in Djibouti, Suspended Elevated Platform in \u0130zmir<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale256.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High Building Facade Window Cleaning Equipment Suspended platform\/cradle<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Capacidade de carga nominal: 630 kg<\/li>\n<li>Cor: Vermelho, pode ser personalizado<\/li>\n<li>Pot\u00eancia do motor: 1,5 kW*2<\/li>\n<li>Platform Dimension:6000*0.72*1300<\/li>\n<li>Voltagem: 220V\/380V\/415V-Trif\u00e1sico\/50Hz\/60Hz<\/li>\n<li>Di\u00e2metro do cabo de a\u00e7o: 8,3 mm<\/li>\n<li>Altura de eleva\u00e7\u00e3o: 100m-120m<\/li>\n<li>Modelo: Plataforma de trabalho suspensa ZLP630<\/li>\n<li>Cabo de travamento Angel: 3-8\u00b0<\/li>\n<li>Comprimento da sali\u00eancia da viga frontal: 1,3-1,5 m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Nagpur, Li\u00e8ge, Valencia, Basra etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Power Lifting Rope Suspended Platform in Morocco, Facade Glass Cleaning Safety Precautions in United Kingdom<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale117.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Spare Parts LTD 8.0 Electric Hoist For Suspended Platform\/Construction Cradle\/Suspended Gondoal In China<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:LTD8.O<\/li>\n<li>Rated Loading Capacity(kg):800Kg<\/li>\n<li>Hoisting Speed:9.0m\/min<\/li>\n<li>Loder Weight:800kg<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Power:1.8kw<\/li>\n<li>Voltage:380V<\/li>\n<li>Rotational speed:1420r\/min<\/li>\n<li>Fequency:50Hz<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Moscow, Dakar, Valencia, Nagpur etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Sky Climber Platform, Facade Glass Cleaning Safety Precautions in United Kingdom<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale183.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP1000 suspended platform\/Building Cleaning Hoist Scaffolding Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Carga nominal: 1000 kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8~10m\/min<\/li>\n<li>Altura de eleva\u00e7\u00e3o: 100m<\/li>\n<li>Cabo: 100m<\/li>\n<li>Contrapeso: 1000 kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Basra, \u0130zmir, United Kingdom, Li\u00e8ge etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mast Working Platform in Basra, Power Lifting Rope Suspended Platform in Morocco<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Advanced zlp 630 cheap gondola cradle suspended platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000 After-sales Service Provided:Engineers available <\/p>","protected":false},"author":1,"featured_media":211,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1942,1938,1939,1941,1937,1940],"class_list":["post-642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-facade-glass-cleaning-safety-precautions-in-united-kingdom","tag-mast-working-platform-in-basra","tag-maximum-4-in-1-work-platform-in-djibouti","tag-power-lifting-rope-suspended-platform-in-morocco","tag-sky-climber-platform","tag-suspended-elevated-platform-in-izmir"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=642"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/211"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}