{"id":481,"date":"2017-05-15T13:49:24","date_gmt":"2017-05-15T13:49:24","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/constructionexternal-wallwindow-cleaning-suspended-platform-cradle-gondola-scaffold.html"},"modified":"2017-05-15T13:49:24","modified_gmt":"2017-05-15T13:49:24","slug":"constructionexternal-wallwindow-cleaning-suspended-platform-cradle-gondola-scaffold","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/constructionexternal-wallwindow-cleaning-suspended-platform-cradle-gondola-scaffold.html","title":{"rendered":"construction\/external wall\/window cleaning suspended platform\/ cradle\/ gondola\/ scaffold"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale58.jpg\" alt=\"construction\/external wall\/window cleaning suspended platform\/ cradle\/ gondola\/ scaffold\" \/><br \/>\nImage of construction\/external wall\/window cleaning suspended platform\/ cradle\/ gondola\/ scaffold<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Name:zlp800 suspended platform for bridge<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pMldSVC11N0hJNGc\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale215.jpg\" alt=\"construction\/external wall\/window cleaning suspended platform\/ cradle\/ gondola\/ scaffold\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale222.jpg\" alt=\"construction\/external wall\/window cleaning suspended platform\/ cradle\/ gondola\/ scaffold\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale76.jpg\" alt=\"construction\/external wall\/window cleaning suspended platform\/ cradle\/ gondola\/ scaffold Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale17.jpg\" alt=\"construction\/external wall\/window cleaning suspended platform\/ cradle\/ gondola\/ scaffold Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale165.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">CE passed ZLP 800 Suspended Access Platform(100m,800KG)<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: Engrenagem<\/li>\n<li>Acionamento\/atua\u00e7\u00e3o do elevador: motor el\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Capacidade de carga nominal: 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m<\/li>\n<li>Voltage:Suspended Access Platform accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Chile, Guadalajara, Jeddah etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Platform Suspended For Cleaning in Chile, Skylift Suspended Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale12.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Factory electic access building work hoist material loading platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Carga nominal: 800 kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8~10m\/min<\/li>\n<li>Altura de eleva\u00e7\u00e3o: 100m<\/li>\n<li>Cabo: 100m<\/li>\n<li>Contrapesado: 800kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Prague, Shubra El Kheima etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Cradle in Guadalajara, Mature-Tech Industrial Work Platforms in Jeddah<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale91.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">OEM available zlp250\/ 500 manual building gondola\/ suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:HJ-SUP-983<\/li>\n<li>Capacidade de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: A\u00e7o galvanizado\/Alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: galvanizado; HDG ou pulveriza\u00e7\u00e3o de pl\u00e1stico<\/li>\n<li>Comprimento da plataforma: 2m-12m; OEM<\/li>\n<li>Pot\u00eancia do motor el\u00e9trico: 1,5 kW*2; 1,8 kW*2; 2,2 kW*2; 3,0 kW*2<\/li>\n<li>Voltagem: 380V\/50HZ\/TRIF\u00c1SICO 220V\/50HZ\/MONOF\u00c1SICO<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200M<\/li>\n<li>Cor: Azul, laranja, vermelho, prata ou personalizado<\/li>\n<li>Aplica\u00e7\u00e3o: Constru\u00e7\u00e3o civil; Pintura, limpeza de janelas<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Jodhpur, Lithuania, Mexico, Chile etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Painting Manual Platform Lift in Prague, Zlp630 Safety Rope Suspended Platform in Shubra El Kheima<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale126.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Shanghai building facade<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Name:building facade<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Poland, Zimbabwe, Mexico, Jodhpur etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Skylift Suspended Platform, Zlp630 Safety Rope Suspended Platform in Shubra El Kheima<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale240.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP Suspended Platform\/ Electric Powered Access Equipment<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLP Series<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: Engrenagem<\/li>\n<li>Acionamento\/atua\u00e7\u00e3o do elevador: motor el\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Capacidade de carga nominal: 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m<\/li>\n<li>Voltage:ZLP Suspended Platform accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Chile, Jeddah, Shubra El Kheima, Lithuania etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Platform Suspended For Cleaning in Chile, Painting Manual Platform Lift in Prague<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of construction\/external wall\/window cleaning suspended platform\/ cradle\/ gondola\/ scaffold Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP Name:zlp800 suspended platform for <\/p>","protected":false},"author":1,"featured_media":234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1037,1038,1035,1034,1036,1039],"class_list":["post-481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-mature-tech-industrial-work-platforms-in-jeddah","tag-painting-manual-platform-lift-in-prague","tag-platform-suspended-for-cleaning-in-chile","tag-skylift-suspended-platform","tag-suspended-platform-cradle-in-guadalajara","tag-zlp630-safety-rope-suspended-platform-in-shubra-el-kheima"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=481"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/234"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}