{"id":441,"date":"2017-05-15T13:43:21","date_gmt":"2017-05-15T13:43:21","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/630kg-high-rise-roof-suspended-work-platform.html"},"modified":"2017-05-15T13:43:21","modified_gmt":"2017-05-15T13:43:21","slug":"630kg-high-rise-roof-suspended-work-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/630kg-high-rise-roof-suspended-work-platform.html","title":{"rendered":"630kg high-rise roof suspended work platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale188.jpg\" alt=\"630kg high-rise roof suspended work platform\" \/><br \/>\nImage of 630kg high-rise roof suspended work platform<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Hoister:LTD63<\/li>\n<li>Platform:6*0.69m<\/li>\n<li>wire rope:4*31w+NF-8.3<\/li>\n<li>Safety lock:anti-tilted<\/li>\n<li>rated load:630kg<\/li>\n<li>working height:100m<\/li>\n<li>Heavy hammer:10kg per pieces<\/li>\n<li>Concrete counter-weight:25kg\/piece<\/li>\n<li>Condition:100% New<\/li>\n<li>Power Supply:380V\/50Hz<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pZ1pnTU1Zc0sxNkE\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale25.jpg\" alt=\"630kg high-rise roof suspended work platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale225.jpg\" alt=\"630kg high-rise roof suspended work platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale81.jpg\" alt=\"630kg high-rise roof suspended work platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale10.jpg\" alt=\"630kg high-rise roof suspended work platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale83.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">800KG suspended working platform product guide<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Name:suspended working platform product guide<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bangladesh, Guayaquil, Moldova etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Manlift Work Platform in Bangladesh, Zlp 630 Cheap Gondola Suspended Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale203.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">electric hoist of suspended platform from a famous brand for sale<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Usage:Construction Hoist<\/li>\n<li>Power Source:Electric<\/li>\n<li>Sling Type:Wire Rope<\/li>\n<li>Maximum Lifting Weight:8KG<\/li>\n<li>Lift Speed:8.3m\/min<\/li>\n<li>Certification:CE<\/li>\n<li>Warranty:1YEAR<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>COLOR:BLACK<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Naypyidaw, Switzerland etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aerial Suspended Scaffold \/Work Platform in Guayaquil, Mobile Elevated Work Platform in Moldova<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale115.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High quality modular platform made from durable materials<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Nome: plataforma suspensa<\/li>\n<li>Rated load:500kg  630kg  800kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8-10 m\/min<\/li>\n<li>Dimension:6000(1+2+3m)*720*1300<\/li>\n<li>Lifting Height:100 m<\/li>\n<li>Power:1.5KW*2<\/li>\n<li>Voltage:380V\/50Hz<\/li>\n<li>Color:Required<\/li>\n<li>20&#39;ft container:9sets<\/li>\n<li>Material:Aluminum Alloy\/hot dipping\/steel<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ludhiana, Ankara, Santo Domingo, Bangladesh etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Wire Rope Cable Suspended Platform in Naypyidaw, Max Load Capacity 800kg Hoist Suspended Platform in Switzerland<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale240.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Shanghai China ZLP series Success brand zlp630 suspended working platforms<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Name:Success brand zlp630 suspended working platforms<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Quezon, Turkey, Santo Domingo, Ludhiana etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp 630 Cheap Gondola Suspended Platform, Max Load Capacity 800kg Hoist Suspended Platform in Switzerland<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale84.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP630 Suspended Access Equipment \/ SUSPENDED PLATFORM<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca: Sucesso, Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Material:Steel<\/li>\n<li>Type:ZLP630<\/li>\n<li>Platform Length:6m<\/li>\n<li>Rated Load(kg):630kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8-10 m\/min<\/li>\n<li>Useage:ZLP630 Suspended Access Equipment<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bangladesh, Moldova, Switzerland, Ankara etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Manlift Work Platform in Bangladesh, Wire Rope Cable Suspended Platform in Naypyidaw<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of 630kg high-rise roof suspended work platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP630 Hoister:LTD63 Platform:6*0.69m wire rope:4*31w+NF-8.3 Safety lock:anti-tilted <\/p>","protected":false},"author":1,"featured_media":42,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[841,840,844,842,843,839],"class_list":["post-441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aerial-suspended-scaffold-work-platform-in-guayaquil","tag-manlift-work-platform-in-bangladesh","tag-max-load-capacity-800kg-hoist-suspended-platform-in-switzerland","tag-mobile-elevated-work-platform-in-moldova","tag-wire-rope-cable-suspended-platform-in-naypyidaw","tag-zlp-630-cheap-gondola-suspended-platform"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=441"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/42"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}