{"id":3462,"date":"2017-06-08T04:06:15","date_gmt":"2017-06-08T04:06:15","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/high-rise-building-facade-zlp-800-suspended-platform-for-window-cleaning.html"},"modified":"2017-06-08T04:06:15","modified_gmt":"2017-06-08T04:06:15","slug":"high-rise-building-facade-zlp-800-suspended-platform-for-window-cleaning","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/high-rise-building-facade-zlp-800-suspended-platform-for-window-cleaning.html","title":{"rendered":"High rise building facade zlp 800 suspended platform for window cleaning"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale95.jpg\" alt=\"High rise building facade zlp 800 suspended platform for window cleaning\" \/><br \/>\nImage of High rise building facade zlp 800 suspended platform for window cleaning<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP800<\/li>\n<li>Capacidade de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: A\u00e7o galvanizado\/Alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: galvanizado; HDG ou pulveriza\u00e7\u00e3o de pl\u00e1stico<\/li>\n<li>Comprimento da plataforma: 2m-12m; OEM<\/li>\n<li>Pot\u00eancia do motor el\u00e9trico: 1,5 kW*2; 1,8 kW*2; 2,2 kW*2; 3,0 kW*2<\/li>\n<li>Voltagem: 380V\/50HZ\/TRIF\u00c1SICO 220V\/50HZ\/MONOF\u00c1SICO<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200M<\/li>\n<li>Cor: Azul, laranja, vermelho, prata ou personalizado<\/li>\n<li>Aplica\u00e7\u00e3o: Constru\u00e7\u00e3o civil; Pintura, limpeza de janelas<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pTjRMb3pCTk9RX28\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale221.jpg\" alt=\"High rise building facade zlp 800 suspended platform for window cleaning\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale188.jpg\" alt=\"High rise building facade zlp 800 suspended platform for window cleaning\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale24.jpg\" alt=\"High rise building facade zlp 800 suspended platform for window cleaning Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale100.jpg\" alt=\"High rise building facade zlp 800 suspended platform for window cleaning Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale67.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">100% new suspended scaffold \/work platform,suspended platform\/ gondola\/ swing stage<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLP63<\/li>\n<li>Lift Mechanism:Other<\/li>\n<li>Lift Drive \/ Actuation:LTD63<\/li>\n<li>Capacidade de carga nominal: 630 kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 100 m<\/li>\n<li>Table Size:1.5*0.69+2*0.69+2.5*0.69(m)<\/li>\n<li>Overall Dimensions:6*0.69(M)<\/li>\n<li>Certification:CE&amp;ISO<\/li>\n<li>Warranty:1year<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>safety lock:swing-arm type used to prevent tilting(2set)<\/li>\n<li>wire rope:4*31w+NF-8.3<\/li>\n<li>HEAVY HAMMER:10KG PER PIECES (2PIECES)<\/li>\n<li>concrete counter- weight:25kg\/piece<\/li>\n<li>material:galvanized<\/li>\n<li>condition:100% new<\/li>\n<li>suspended mechanism:adjustable height range:1.15-1.75m<\/li>\n<li>the length stretching out of the wall::the length stretching out of the wall:1.1-1.7m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Accra, Gujranwala, Jaipur etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hoist Suspended Platform in Accra, Hot Sale Access Suspended Platforms<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale208.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction lifting scaffolding gondola, pedal type suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Capacidade de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: A\u00e7o galvanizado\/Alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: galvanizado; HDG ou pulveriza\u00e7\u00e3o de pl\u00e1stico<\/li>\n<li>Comprimento da plataforma: 2m-12m; OEM<\/li>\n<li>Pot\u00eancia do motor el\u00e9trico: 1,5 kW*2; 1,8 kW*2; 2,2 kW*2; 3,0 kW*2<\/li>\n<li>Voltagem: 380V\/50HZ\/TRIF\u00c1SICO 220V\/50HZ\/MONOF\u00c1SICO<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200M<\/li>\n<li>Cor: Azul, laranja, vermelho, prata ou personalizado<\/li>\n<li>Aplica\u00e7\u00e3o: Constru\u00e7\u00e3o civil; Pintura, limpeza de janelas<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Papua New Guinea, Yekaterinburg etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Economical Zlp1000 Suspended Working Platforms in Gujranwala, Mature-Tech Zlp630 Suspended Working Platforms in Jaipur<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale55.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High Standard zlp 630 electric gondola\/rope suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Name:zlp 630 electric gondola\/rope suspended platform<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ghaziabad, Berlin, Santiago, Accra etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mec Aerial Work Platforms in Papua New Guinea, Zlp 630 Suspended Working Platform in Yekaterinburg<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale146.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Shanghai China ZLP series Mature-tech working platform safety<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Name:Mature-tech working platform safety<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Palestine, Swaziland, Santiago, Ghaziabad etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hot Sale Access Suspended Platforms, Zlp 630 Suspended Working Platform in Yekaterinburg<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale10.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP Personal and Material Gondola Lift<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca: JH-Success<\/li>\n<li>N\u00famero do modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Produto: Plataforma suspensa ZLP800<\/li>\n<li>Carga nominal: 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8-10 m\/min<\/li>\n<li>Tamanho da plataforma (Lwh):6000(1+2+3m)*720*1300<\/li>\n<li>Pot\u00eancia: 1,5 kW * 2, 1,8 kW * 2<\/li>\n<li>Voltagem: 110V, 220V, 240V, 400V, 415V, 440V dispon\u00edveis<\/li>\n<li>Certifica\u00e7\u00f5es: CE, ISO, GOST<\/li>\n<li>Contrapeso: 1000 kg<\/li>\n<li>Material: A\u00e7o Liga\/Imers\u00e3o a Quente\/A\u00e7o<\/li>\n<li>Garantia: 12 meses<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Accra, Jaipur, Yekaterinburg, Berlin etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hoist Suspended Platform in Accra, Mec Aerial Work Platforms in Papua New Guinea<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of High rise building facade zlp 800 suspended platform for window cleaning Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP800 Loading <\/p>","protected":false},"author":1,"featured_media":93,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[15335,15334,4472,15336,15337,15338],"class_list":["post-3462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-economical-zlp1000-suspended-working-platforms-in-gujranwala","tag-hoist-suspended-platform-in-accra","tag-hot-sale-access-suspended-platforms","tag-mature-tech-zlp630-suspended-working-platforms-in-jaipur","tag-mec-aerial-work-platforms-in-papua-new-guinea","tag-zlp-630-suspended-working-platform-in-yekaterinburg"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/3462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=3462"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/3462\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/93"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=3462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=3462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=3462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}