{"id":3437,"date":"2017-06-08T02:41:07","date_gmt":"2017-06-08T02:41:07","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/success-electric-wire-rope-hoist-aerial-building-maintenance-units-suspended-platform.html"},"modified":"2017-06-08T02:41:07","modified_gmt":"2017-06-08T02:41:07","slug":"success-electric-wire-rope-hoist-aerial-building-maintenance-units-suspended-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/success-electric-wire-rope-hoist-aerial-building-maintenance-units-suspended-platform.html","title":{"rendered":"Success Electric wire rope hoist aerial building maintenance units suspended platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale229.jpg\" alt=\"Success Electric wire rope hoist aerial building maintenance units suspended platform\" \/><br \/>\nImage of Success Electric wire rope hoist aerial building maintenance units suspended platform<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Capacidade de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: A\u00e7o galvanizado\/Alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: galvanizado; HDG ou pulveriza\u00e7\u00e3o de pl\u00e1stico<\/li>\n<li>Comprimento da plataforma: 2m-12m; OEM<\/li>\n<li>Pot\u00eancia do motor el\u00e9trico: 1,5 kW*2; 1,8 kW*2; 2,2 kW*2; 3,0 kW*2<\/li>\n<li>Voltagem: 380V\/50HZ\/TRIF\u00c1SICO 220V\/50HZ\/MONOF\u00c1SICO<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200M<\/li>\n<li>Cor: Azul, laranja, vermelho, prata ou personalizado<\/li>\n<li>Aplica\u00e7\u00e3o: Constru\u00e7\u00e3o civil; Pintura, limpeza de janelas<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pRUNaekVuaF9fN1E\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale42.jpg\" alt=\"Success Electric wire rope hoist aerial building maintenance units suspended platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale88.jpg\" alt=\"Success Electric wire rope hoist aerial building maintenance units suspended platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale64.jpg\" alt=\"Success Electric wire rope hoist aerial building maintenance units suspended platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale107.jpg\" alt=\"Success Electric wire rope hoist aerial building maintenance units suspended platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale233.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">2017 NEW ZLP Cradle Gondola Swing Stage Scaffolding Electric Powered Access Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP800<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: el\u00e9trico<\/li>\n<li>Acionamento\/Atua\u00e7\u00e3o do Elevador: Motor El\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,8 kW, 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Capacidade de carga nominal: 800 kg, 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: 0 m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m, 200 m<\/li>\n<li>Tamanho da mesa: 7500*690*1180mm<\/li>\n<li>Overall Dimensions:4CBM<\/li>\n<li>Weight:2000kg<\/li>\n<li>Certifica\u00e7\u00e3o: ISO, CE<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: Engrenagem<\/li>\n<li>Acionamento\/atua\u00e7\u00e3o do elevador: motor el\u00e9trico<\/li>\n<li>Voltage:Cradle\/Gondola\/Swing Stage\/Scaffold Platform accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Calgary, Czech Republic, Maceio etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Painting Manual Platform Lift in Calgary, Mini Scissor Lift<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale15.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">electrical control box of suspended working platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Rio de Janeiro, Toronto etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Model Srp Suspended Platform in Czech Republic, Electric Lift Suspended Platform in Maceio<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale259.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">power climber\/suspended working platform\/suspended access platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP800<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: cabo de a\u00e7o<\/li>\n<li>Acionamento\/Acionamento do Elevador: Guindaste<\/li>\n<li>Pot\u00eancia: 1,5 kW*2<\/li>\n<li>Rated Loading Capacity:800kg<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: 10 m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 100 m<\/li>\n<li>Table Size:6(1+2+3)*0.72*1.3m,7.5(2.5*3)*0.72*1.3m<\/li>\n<li>Dimens\u00f5es totais: 1850 mm * 1000 mm * 950 mm<\/li>\n<li>Peso: 850 kg<\/li>\n<li>Certification:CE ISO<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Application:clean walls decorat maintain<\/li>\n<li>Name:Suspended platform<\/li>\n<li>Altura de eleva\u00e7\u00e3o: 100m<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8~10m\/min<\/li>\n<li>cable:100m<\/li>\n<li>Voltagem: 220V\/380V\/50Hz<\/li>\n<li>Color:Red sliver<\/li>\n<li>Material:Steel Aluminum Galvanizing<\/li>\n<li>Keywords:cradle<\/li>\n<li>Feature:Easy Operation safety convenience<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Vasai-Virar, Korea, Brasilia, Calgary etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mature-Tech Scaffolding Stage Platform in Rio de Janeiro, Aerial Work Platform For Sale in Toronto<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale204.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Suspended Electric Elevated Work Platform\/ Platform Lift<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP800<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: Engrenagem<\/li>\n<li>Acionamento\/atua\u00e7\u00e3o do elevador: motor el\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Capacidade de carga nominal: 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m<\/li>\n<li>Voltage:Platform Lift accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: San Antonio, Kumasi, Brasilia, Vasai-Virar etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mini Scissor Lift, Aerial Work Platform For Sale in Toronto<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale50.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Window cleaning suspended platform,Electric scaffold platform,zlp630 suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Nome: Plataforma de corda suspensa OU plataforma de trabalho<\/li>\n<li>Aplica\u00e7\u00e3o da plataforma Cradle: Manuten\u00e7\u00e3o, limpeza ou revestimento de edif\u00edcios<\/li>\n<li>Fixa\u00e7\u00e3o do telhado: 1, suspens\u00e3o com balc\u00e3o 2, bra\u00e7adeira de parapeito<\/li>\n<li>Corpo da plataforma: montado livremente por placa modular<\/li>\n<li>Formato da plataforma: cuboide ou design especial<\/li>\n<li>Material da plataforma: a\u00e7o ou liga de alum\u00ednio<\/li>\n<li>Cor da plataforma: vermelho, prata, marca especial<\/li>\n<li>Padr\u00e3o de plataforma: CE, GOST, ISO<\/li>\n<li>For\u00e7a motriz: talha el\u00e9trica<\/li>\n<li>Dispositivo de seguran\u00e7a: trava de seguran\u00e7a, corda de seguran\u00e7a etc.<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Calgary, Maceio, Toronto, Korea etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Painting Manual Platform Lift in Calgary, Mature-Tech Scaffolding Stage Platform in Rio de Janeiro<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Success Electric wire rope hoist aerial building maintenance units suspended platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP500\/630\/800\/1000 Loading <\/p>","protected":false},"author":1,"featured_media":93,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[15214,15212,15213,2235,15211,15210],"class_list":["post-3437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aerial-work-platform-for-sale-in-toronto","tag-electric-lift-suspended-platform-in-maceio","tag-mature-tech-scaffolding-stage-platform-in-rio-de-janeiro","tag-mini-scissor-lift","tag-model-srp-suspended-platform-in-czech-republic","tag-painting-manual-platform-lift-in-calgary"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/3437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=3437"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/3437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/93"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=3437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=3437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=3437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}