{"id":3200,"date":"2017-06-05T01:06:02","date_gmt":"2017-06-05T01:06:02","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/manufacturer-zlp630-gondola-lift-with-good-quality-at-good-price.html"},"modified":"2017-06-05T01:06:02","modified_gmt":"2017-06-05T01:06:02","slug":"manufacturer-zlp630-gondola-lift-with-good-quality-at-good-price","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/manufacturer-zlp630-gondola-lift-with-good-quality-at-good-price.html","title":{"rendered":"Manufacturer ZLP630 Gondola Lift with Good Quality at Good Price"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale119.jpg\" alt=\"Manufacturer ZLP630 Gondola Lift with Good Quality at Good Price\" \/><br \/>\nImage of Manufacturer ZLP630 Gondola Lift with Good Quality at Good Price<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca: Success-CHINA<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Usage:Building facade cleaning<\/li>\n<li>Cor: Vermelho ou outras cores<\/li>\n<li>Certificados: ISO, GOST, CE<\/li>\n<li>Fonte de energia: Eletricidade<\/li>\n<li>Tipo de acionamento: i\u00e7amento por cabo de a\u00e7o<\/li>\n<li>Aplica\u00e7\u00e3o: Manuten\u00e7\u00e3o de edif\u00edcios altos<\/li>\n<li>Origem: China<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8-10 m\/min<\/li>\n<li>Altura de eleva\u00e7\u00e3o e comprimento do cabo: 100 m<\/li>\n<li>Voltage:380V50HZ 3Phases or according to  customer need<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pVXZSUWJRSC1QX0E\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale151.jpg\" alt=\"Manufacturer ZLP630 Gondola Lift with Good Quality at Good Price\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale23.jpg\" alt=\"Manufacturer ZLP630 Gondola Lift with Good Quality at Good Price\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale13.jpg\" alt=\"Manufacturer ZLP630 Gondola Lift with Good Quality at Good Price Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale99.jpg\" alt=\"Manufacturer ZLP630 Gondola Lift with Good Quality at Good Price Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale222.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Aluminum ZLP800B Suspended Working Platform \/ facade cleaning equipment<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP800<\/li>\n<li>Modelo: ZLP800<\/li>\n<li>Loading capacity:800kg<\/li>\n<li>Material:aluminium<\/li>\n<li>style:general<\/li>\n<li>suspended mechanism:galvanized<\/li>\n<li>counter weight:25kg\/pcs<\/li>\n<li>size platform:7.5m<\/li>\n<li>Power:380V-480v\/50Hz-60Hz<\/li>\n<li>certification:Gost,CE,CCC<\/li>\n<li>keywords:construction platform<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bogot\u00e1, Guyana, Kuwait etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Stage Scaffolding in Bogot\u00e1, Suspended Platform Structure<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale162.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Plataforma suspensa de canto de f\u00e1cil instala\u00e7\u00e3o<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Name:corner suspend platform<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Poland, Tijuana etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mobile Scaffolding Platform in Guyana, Zlp800 Suspended Platform For Bridge in Kuwait<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale261.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High efficiency Mast Climbing Work Platform, CE approved<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP 800<\/li>\n<li>Matrial:steel, A-alloy is available<\/li>\n<li>Name:platform<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Chelyabinsk, Lebanon, Auckland, Bogot\u00e1 etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mobile Suspended Platform in Poland, Function Of Scaffold Platform in Tijuana<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale184.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">safety lock for electric suspended platform\/cradle\/gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP800<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: cabo de a\u00e7o<\/li>\n<li>Acionamento\/Acionamento do Elevador: Guindaste<\/li>\n<li>Pot\u00eancia: 1,5 kW*2<\/li>\n<li>Rated Loading Capacity:800kg<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: 10 m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 100 m<\/li>\n<li>Table Size:6(1+2+3)*0.72*1.3m,7.5(2.5*3)*0.72*1.3m<\/li>\n<li>Dimens\u00f5es totais: 1850 mm * 1000 mm * 950 mm<\/li>\n<li>Peso: 850 kg<\/li>\n<li>Certification:CE ISO<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Application:clean walls decorat maintain<\/li>\n<li>Name:Suspended platform<\/li>\n<li>Altura de eleva\u00e7\u00e3o: 100m<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8~10m\/min<\/li>\n<li>cable:100m<\/li>\n<li>Voltagem: 220V\/380V\/50Hz<\/li>\n<li>Color:Red sliver<\/li>\n<li>Material:Steel Aluminum Galvanizing<\/li>\n<li>Keywords:cradle<\/li>\n<li>Feature:Easy Operation safety convenience<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Dubai, Mombasa, Auckland, Chelyabinsk etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Structure, Function Of Scaffold Platform in Tijuana<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale266.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP Series Special Cradle\/Suspended Platform\/High building cleaning equipment<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: China (continental)<\/li>\n<li>Marca: G\u00f4ndola com plataforma suspensa<\/li>\n<li>N\u00famero do modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Nome: Plataforma de corda suspensa OU plataforma de trabalho<\/li>\n<li>Aplica\u00e7\u00e3o da plataforma Cradle: Manuten\u00e7\u00e3o de edif\u00edcios, limpeza, pintura<\/li>\n<li>Fixa\u00e7\u00e3o do telhado: 1, suspens\u00e3o com balc\u00e3o 2, bra\u00e7adeira de parapeito<\/li>\n<li>Cor da plataforma: vermelho, prata, galvanizado a quente<\/li>\n<li>Dispositivo de seguran\u00e7a: trava de seguran\u00e7a, corda de seguran\u00e7a etc.<\/li>\n<li>For\u00e7a motriz: talha el\u00e9trica<\/li>\n<li>Formato da plataforma: cuboide ou design especial<\/li>\n<li>Padr\u00e3o de plataforma: CE, GOST, ISO<\/li>\n<li>Material da plataforma: a\u00e7o ou liga de alum\u00ednio<\/li>\n<li>Corpo da plataforma: montado livremente por placa modular<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bogot\u00e1, Kuwait, Tijuana, Lebanon etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Stage Scaffolding in Bogot\u00e1, Mobile Suspended Platform in Poland<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Manufacturer ZLP630 Gondola Lift with Good Quality at Good Price Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success-CHINA Model Number:ZLP630 Usage:Building facade <\/p>","protected":false},"author":1,"featured_media":144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14071,14068,14070,14067,12645,14069],"class_list":["post-3200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-function-of-scaffold-platform-in-tijuana","tag-mobile-scaffolding-platform-in-guyana","tag-mobile-suspended-platform-in-poland","tag-stage-scaffolding-in-bogota","tag-suspended-platform-structure","tag-zlp800-suspended-platform-for-bridge-in-kuwait"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/3200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=3200"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/3200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/144"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=3200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=3200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=3200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}