{"id":3134,"date":"2017-06-05T09:09:28","date_gmt":"2017-06-05T09:09:28","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zlp1000-1000kg-loading-7-5m-in-length-high-building-cleaning-equipment-electric-scaffolding.html"},"modified":"2017-06-05T09:09:28","modified_gmt":"2017-06-05T09:09:28","slug":"zlp1000-1000kg-loading-7-5m-in-length-high-building-cleaning-equipment-electric-scaffolding","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/zlp1000-1000kg-loading-7-5m-in-length-high-building-cleaning-equipment-electric-scaffolding.html","title":{"rendered":"ZLP1000 1000kg Loading 7.5m in length High Building Cleaning Equipment electric scaffolding"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale13.jpg\" alt=\"ZLP1000 1000kg Loading 7.5m in length High Building Cleaning Equipment electric scaffolding\" \/><br \/>\nImage of ZLP1000 1000kg Loading 7.5m in length High Building Cleaning Equipment electric scaffolding<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLP1000<\/li>\n<li>Cabo: 3*2,5+2*1,5<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8-10 m\/min<\/li>\n<li>Material:steel or aluminum alloy<\/li>\n<li>Certificados: ISO, GOST, CE<\/li>\n<li>Product name:ZLP1000 High Building Cleaning Equipment electric scaffolding<\/li>\n<li>Platform Cable:100m<\/li>\n<li>Original:China<\/li>\n<li>Application:ZLP Boom Lift\/ Electric Aerial Suspended Platform<\/li>\n<li>Voltage:220V\/380V\/415V<\/li>\n<li>Color:Red or silver<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pX1UwRktERk41T0E\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale259.jpg\" alt=\"ZLP1000 1000kg Loading 7.5m in length High Building Cleaning Equipment electric scaffolding\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale20.jpg\" alt=\"ZLP1000 1000kg Loading 7.5m in length High Building Cleaning Equipment electric scaffolding\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale49.jpg\" alt=\"ZLP1000 1000kg Loading 7.5m in length High Building Cleaning Equipment electric scaffolding Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale14.jpg\" alt=\"ZLP1000 1000kg Loading 7.5m in length High Building Cleaning Equipment electric scaffolding Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale79.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Building Construction Suspended Work Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:HJ-SUP152<\/li>\n<li>Product name:Building Construction Suspended Work Platform<\/li>\n<li>Surface Protection: Painting and Galvanize<\/li>\n<li>Keywords:Building Construction Suspended Work Platform<\/li>\n<li>Color: Red , Yellow , Other<\/li>\n<li>Certification: ISO , CE , GOST proved<\/li>\n<li>Type:construction platforms<\/li>\n<li>Certificate:ISO , CE , GOST proved<\/li>\n<li>Market:global, over 30contries<\/li>\n<li>Item:suspend platforms<\/li>\n<li>place of origin:Shanghai, China (Mainland)<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Brazil, Indore, Liberia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Ladder Platform in Brazil, Suspended Elevated Work Scaffolding Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale204.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Custom Aluminum \/ Steel Suspended Working Platform Hanging Scaffold Systems<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLPSuspended Working Platform<\/li>\n<li>Machine Type:High Pressure Cleaner<\/li>\n<li>Cleaning Type:Manual<\/li>\n<li>Industry Used:Pharmaceutical Cleaning<\/li>\n<li>Use:Burnishing<\/li>\n<li>Fuel:Electric<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Feature:Rust \/ Corrosion Inhibitor<\/li>\n<li>Certification:CE<\/li>\n<li>Cleaning Process:Acid Cleaning \/ Pickling<\/li>\n<li>Material:Glass \/ Ceramic<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Santo Domingo, Sapporo etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Model Srp Suspended Platform in Indore, Gondola System in Liberia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale19.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Manufacturer Directory Aluminum Rope Suspended Work Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:HJ-SUP209<\/li>\n<li>Product name:Manufacturer Directory Aluminum Rope Suspended Work Platform<\/li>\n<li>Surface Protection: Painting and Galvanize<\/li>\n<li>Keywords:Aluminum Rope Suspended Work Platform<\/li>\n<li>Color: Red , Yellow , Other<\/li>\n<li>Certification: ISO , CE , GOST proved<\/li>\n<li>Type:construction platforms<\/li>\n<li>Certificate:ISO , CE , GOST proved<\/li>\n<li>Market:global, over 30contries<\/li>\n<li>Item:suspend platforms<\/li>\n<li>place of origin:Shanghai, China (Mainland)<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: South Tangerang, Rome, Mali, Brazil etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminum Lift Electric Suspended Work Platform in Santo Domingo, Manual Suspended Platform in Sapporo<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale254.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Swinging Steel Wire Rope Suspended Platform, Adjustable Height Construction Work Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLP250<\/li>\n<li>Lift Mechanism:Gear<\/li>\n<li>Acionamento\/Atua\u00e7\u00e3o do Elevador: Motor El\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,5 kW, 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Rated Loading Capacity:200kg, 150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: 0 m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m<\/li>\n<li>Table Size:2500*690*1180mm(W*H)<\/li>\n<li>Dimens\u00f5es totais: 3 CBM<\/li>\n<li>Weight:1600kg<\/li>\n<li>Certification:CE, ISO, ISO, CE<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Voltage:Adjustable Height Construction Work Platform accept different voltage<\/li>\n<li>Aplica\u00e7\u00e3o: Pr\u00e9dios altos, tanques grandes, chamin\u00e9s, barragens, pontes, torres de perfura\u00e7\u00e3o, etc.<\/li>\n<li>Plataforma especial: pode ser personalizada e fornecida<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Panama, Johannesburg, Mali, South Tangerang etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Elevated Work Scaffolding Platform, Manual Suspended Platform in Sapporo<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale102.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">zlp800 suspended platform 800kg 8m length<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca: G\u00f4ndola com plataforma suspensa<\/li>\n<li>N\u00famero do modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Nome: Plataforma de corda suspensa OU plataforma de trabalho<\/li>\n<li>Aplica\u00e7\u00e3o da plataforma Cradle: Manuten\u00e7\u00e3o de edif\u00edcios, limpeza, pintura<\/li>\n<li>Fixa\u00e7\u00e3o do telhado: 1, suspens\u00e3o com balc\u00e3o 2, bra\u00e7adeira de parapeito<\/li>\n<li>Cor da plataforma: vermelho, prata, galvanizado a quente<\/li>\n<li>Dispositivo de seguran\u00e7a: trava de seguran\u00e7a, corda de seguran\u00e7a etc.<\/li>\n<li>For\u00e7a motriz: talha el\u00e9trica<\/li>\n<li>Formato da plataforma: cuboide ou design especial<\/li>\n<li>Padr\u00e3o de plataforma: CE, GOST, ISO<\/li>\n<li>Material da plataforma: a\u00e7o ou liga de alum\u00ednio<\/li>\n<li>Corpo da plataforma: montado livremente por placa modular<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Brazil, Liberia, Sapporo, Rome etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Ladder Platform in Brazil, Aluminum Lift Electric Suspended Work Platform in Santo Domingo<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of ZLP1000 1000kg Loading 7.5m in length High Building Cleaning Equipment electric scaffolding Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP1000 <\/p>","protected":false},"author":1,"featured_media":162,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[13743,13742,13740,13744,13741,1572],"class_list":["post-3134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aluminum-lift-electric-suspended-work-platform-in-santo-domingo","tag-gondola-system-in-liberia","tag-ladder-platform-in-brazil","tag-manual-suspended-platform-in-sapporo","tag-model-srp-suspended-platform-in-indore","tag-suspended-elevated-work-scaffolding-platform"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/3134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=3134"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/3134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/162"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=3134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=3134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=3134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}