{"id":3017,"date":"2017-06-04T19:53:17","date_gmt":"2017-06-04T19:53:17","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zlp-2-person-folding-working-platform.html"},"modified":"2017-06-04T19:53:17","modified_gmt":"2017-06-04T19:53:17","slug":"zlp-2-person-folding-working-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/zlp-2-person-folding-working-platform.html","title":{"rendered":"ZLP 2 person Folding Working Platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale238.jpg\" alt=\"ZLP 2 person Folding Working Platform\" \/><br \/>\nImage of ZLP 2 person Folding Working Platform<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP800<\/li>\n<li>Certification::ISO, CE, GOST<\/li>\n<li>Color::red<\/li>\n<li>Voltage::380V\/50Hz<\/li>\n<li>Basic lifting height::100m<\/li>\n<li>Counter weight::1000kg<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pcjhQd24xaWVkb1k\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale220.jpg\" alt=\"ZLP 2 person Folding Working Platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale146.jpg\" alt=\"ZLP 2 person Folding Working Platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale97.jpg\" alt=\"ZLP 2 person Folding Working Platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale14.jpg\" alt=\"ZLP 2 person Folding Working Platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale262.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">(CE,GOST,ISO) China Manufacturer ZLP 500 Suspended Platform for Cleaning Windows<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:zlp500<\/li>\n<li>Rated loading:630kg<\/li>\n<li>Mterial:steel\/galvanized\/aluminum<\/li>\n<li>voltage:220-480v<\/li>\n<li>Frequency:50HZ-60Hz<\/li>\n<li>Working height:100m<\/li>\n<li>Hoist power:1.5kwx2<\/li>\n<li>total weight:2T with counter weight<\/li>\n<li>size:3*1.2*1.3<\/li>\n<li>Certification:ISO9001\/CE\/EAC<\/li>\n<li>keywords:suspended platform<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Charleroi, Georgia, Kathmandu etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Affordable Scaffolding Stage Platform in Charleroi, Zlp Manual Suspended Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale66.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Economic electric suspended hanging scaffold\/wire rope suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Name:electric suspended hanging scaffold\/wire rope suspended platform<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Perth, Vietnam etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Permanent Suspended Platforms in Georgia, Crowd Working Platform in Kathmandu<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale47.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High Rise Building Cleaning Wire Rope Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Model:Wire Rope Suspended Platform<\/li>\n<li>Rated Load:630kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8-10 m\/min<\/li>\n<li>Platform Dimension:(1-7.5m)*0.72*1.3m<\/li>\n<li>Lifting Height:100m<\/li>\n<li>Cabo: 100m<\/li>\n<li>Hoist Power 1:1.5KW*2<\/li>\n<li>Locking Cable Angel:3-8 degree<\/li>\n<li>Contrapeso: 1000 kg<\/li>\n<li>20 HQ Container:10 Sets<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Varanasi, Berlin, Santo Domingo, Charleroi etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Steel Suspended Platform Hoist in Perth, Aluminum Work Platform With Adjustable Legs in Vietnam<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale54.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Shanghai China ZLP series Affordable electric platform lift<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Name:Affordable electric platform lift<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Philadelphia, Turkey, Santo Domingo, Varanasi etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp Manual Suspended Platform, Aluminum Work Platform With Adjustable Legs in Vietnam<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale89.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP Series india suspended platform\/hoist suspended platform\/Special Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Brand Name:China Success<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Power:1.5KW X 2<\/li>\n<li>Steel Rope Diamerter:8.3mm<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Charleroi, Kathmandu, Vietnam, Berlin etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Affordable Scaffolding Stage Platform in Charleroi, Steel Suspended Platform Hoist in Perth<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of ZLP 2 person Folding Working Platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP800 Certification::ISO, CE, GOST Color::red Voltage::380V\/50Hz Basic <\/p>","protected":false},"author":1,"featured_media":117,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[13158,3701,13160,13159,13161,8147],"class_list":["post-3017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-affordable-scaffolding-stage-platform-in-charleroi","tag-aluminum-work-platform-with-adjustable-legs-in-vietnam","tag-crowd-working-platform-in-kathmandu","tag-permanent-suspended-platforms-in-georgia","tag-steel-suspended-platform-hoist-in-perth","tag-zlp-manual-suspended-platform"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/3017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=3017"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/3017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/117"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=3017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=3017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=3017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}