{"id":2592,"date":"2017-05-31T14:51:02","date_gmt":"2017-05-31T14:51:02","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/ltd80-hoist-success-steel-materials-suspended-working-platform.html"},"modified":"2017-05-31T14:51:02","modified_gmt":"2017-05-31T14:51:02","slug":"ltd80-hoist-success-steel-materials-suspended-working-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/ltd80-hoist-success-steel-materials-suspended-working-platform.html","title":{"rendered":"LTD80 Hoist Success Steel materials suspended working platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale112.jpg\" alt=\"LTD80 Hoist Success Steel materials suspended working platform\" \/><br \/>\nImage of LTD80 Hoist Success Steel materials suspended working platform<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:Success-ZLP-124<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: cremalheira e pinh\u00e3o<\/li>\n<li>Acionamento\/Atua\u00e7\u00e3o do Elevador: Motor El\u00e9trico<\/li>\n<li>Pot\u00eancia: 50HZ<\/li>\n<li>Capacidade de carga nominal: 250-1000 kg<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: 100 m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150 m<\/li>\n<li>Tamanho da mesa: 1+2+3m \/3*2,5m<\/li>\n<li>Dimens\u00f5es totais: 6m \/ 7m<\/li>\n<li>Peso: 1000 kg<\/li>\n<li>Certifica\u00e7\u00e3o: CE. GOST ISO<\/li>\n<li>Garantia: um ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Suspended Platform:LTD80 Hoist Success Steel materials suspended working platform<\/li>\n<li>cor: vermelho ou conforme a necessidade do cliente<\/li>\n<li>pot\u00eancia: 220V ou 380V etc.<\/li>\n<li>material: liga a ou a\u00e7o<\/li>\n<li>Site: www.bjfth.com<\/li>\n<li>N\u00famero do modelo: plataforma suspensa da s\u00e9rie ZLP<\/li>\n<li>comprimento da plataforma: 1-7,5 m<\/li>\n<li>Principais mercados: Austr\u00e1lia\/Sul da \u00c1sia\/Leste\/Bahia\/\u00c1frica do Sul\/Emirados \u00c1rabes Unidos<\/li>\n<li>Carga nominal: 630 kg\/800 kg\/1000 kg<\/li>\n<li>altura de trabalho: 30-200m<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pMUpLQl92bklzWDQ\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale8.jpg\" alt=\"LTD80 Hoist Success Steel materials suspended working platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale140.jpg\" alt=\"LTD80 Hoist Success Steel materials suspended working platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale35.jpg\" alt=\"LTD80 Hoist Success Steel materials suspended working platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale84.jpg\" alt=\"LTD80 Hoist Success Steel materials suspended working platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale7.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">2017 China ZLP series Affordable work platform lift<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Name:Affordable work platform lift<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Canada, Incheon, Lusaka  etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Ladder Access Platform in Canada, Construction Platform Lift<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale124.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">China Manufacturer and Supplier HGY series Concrete Spreader<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:HGY<\/li>\n<li>Voltage:380V\/50HZ<\/li>\n<li>Power(W):2.5-5.5W<\/li>\n<li>Dimension(L*W*H):8900mm*4000mm*2585mm<\/li>\n<li>Weight:1300-1700kg<\/li>\n<li>Certification:ISO9001<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Rotation mode:Manual<\/li>\n<li>Max Turning radius:12-18m<\/li>\n<li>Effective height:5.4\\6.4<\/li>\n<li>Counterweight(self-provide):1200-1800kg<\/li>\n<li>Landingleg max span:3.4&#215;3.4\/5.8&#215;5.8<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Puebla, Turkey etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminum Fitting Rope Suspended Platform in Incheon, Mature-Tech Powered Access Platforms in Lusaka <\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale180.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High rise building cleaning suspended electric gondola platforms<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:HJ-SUP-998<\/li>\n<li>Capacidade de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: A\u00e7o galvanizado\/Alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: galvanizado; HDG ou pulveriza\u00e7\u00e3o de pl\u00e1stico<\/li>\n<li>Comprimento da plataforma: 2m-12m; OEM<\/li>\n<li>Pot\u00eancia do motor el\u00e9trico: 1,5 kW*2; 1,8 kW*2; 2,2 kW*2; 3,0 kW*2<\/li>\n<li>Voltagem: 380V\/50HZ\/TRIF\u00c1SICO 220V\/50HZ\/MONOF\u00c1SICO<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200M<\/li>\n<li>Cor: Azul, laranja, vermelho, prata ou personalizado<\/li>\n<li>Aplica\u00e7\u00e3o: Constru\u00e7\u00e3o civil; Pintura, limpeza de janelas<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ireland, Liberia, Valencia, Canada etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Durable Industrial Access Platforms in Puebla, Zlp 630 Suspended Working Platform in Turkey<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale71.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">suspension scaffold lift machine,equipment,suspended platform, suspension gondola,lift stage<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLP630\/ZLP800<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: corrente de eleva\u00e7\u00e3o<\/li>\n<li>Acionamento\/Atua\u00e7\u00e3o do Elevador: Motor El\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,5 kW*2\/1,8 kW*2<\/li>\n<li>Capacidade de carga nominal: 630 kg<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: 0 m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 100 m<\/li>\n<li>Tamanho da mesa: 6000*720*1300mm\/7500*720*1300mm<\/li>\n<li>Dimens\u00f5es gerais:requisito<\/li>\n<li>Peso: 800 kg<\/li>\n<li>Certifica\u00e7\u00e3o: CE, ISO, GOST.<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Nenhum servi\u00e7o no exterior fornecido<\/li>\n<li>Cor: Prateado<\/li>\n<li>Contrapeso: 800 kg<\/li>\n<li>Voltagem: 380v\/50hz<\/li>\n<li>Cabo: 100M<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8-10 m\/min<\/li>\n<li>Name: Suspended Scaffolding<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Senegal, Uzbekistan, Valencia, Ireland etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Construction Platform Lift, Zlp 630 Suspended Working Platform in Turkey<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale216.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP800 safety Temporary Suspended Access Platforms and Accessories<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP800<\/li>\n<li>Application:Constrution,maintenance, renovation,cleaning,painting etc<\/li>\n<li>Name:aerial work platform<\/li>\n<li>Carga nominal: 800 kg<\/li>\n<li>Voltage:380V\/50HZ\/3Phase<\/li>\n<li>platfrom dimension(L*W*H)mm:7500(2.5*3)*720*1300mm<\/li>\n<li>cable:100m<\/li>\n<li>altura de eleva\u00e7\u00e3o: 100m<\/li>\n<li>Erection &amp; dismantle:Quick assembly without any special tools<\/li>\n<li>Business type:manufactuer direct supplying<\/li>\n<li>Certificate:ISO,CE,GOST<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Canada, Lusaka , Turkey, Liberia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Ladder Access Platform in Canada, Durable Industrial Access Platforms in Puebla<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of LTD80 Hoist Success Steel materials suspended working platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:Success-ZLP-124 Lift Mechanism:Rack &amp; Pinion <\/p>","protected":false},"author":1,"featured_media":42,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11067,10091,11069,6644,11068,11070],"class_list":["post-2592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aluminum-fitting-rope-suspended-platform-in-incheon","tag-construction-platform-lift","tag-durable-industrial-access-platforms-in-puebla","tag-ladder-access-platform-in-canada","tag-mature-tech-powered-access-platforms-in-lusaka","tag-zlp-630-suspended-working-platform-in-turkey"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/2592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=2592"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/2592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/42"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=2592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=2592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=2592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}