{"id":2337,"date":"2017-05-26T07:50:34","date_gmt":"2017-05-26T07:50:34","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/hoist-suspended-platform.html"},"modified":"2017-05-26T07:50:34","modified_gmt":"2017-05-26T07:50:34","slug":"hoist-suspended-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/hoist-suspended-platform.html","title":{"rendered":"hoist suspended platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale99.jpg\" alt=\"hoist suspended platform\" \/><br \/>\nImage of hoist suspended platform<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Jinfei Tianhong<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>voltage:380V ,220v etc<\/li>\n<li>Length:assemble any size in the rage of 1m to 30m<\/li>\n<li>safty device:safty lock<\/li>\n<li>roll:vertical ,horizontal<\/li>\n<li>motor:LTD80,LTD1000S,LTD630<\/li>\n<li>automatic levelling system:locating pin<\/li>\n<li>overspeed safety device:certrifugal speed limiter<\/li>\n<li>emergency manual descent:speed reducer<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pbXZXb3VNemdkclk\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale227.jpg\" alt=\"hoist suspended platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale252.jpg\" alt=\"hoist suspended platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale7.jpg\" alt=\"hoist suspended platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale58.jpg\" alt=\"hoist suspended platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale191.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">(CE,ISO Approved) Facade Construction ZLP Suspended Working Platform|Cradle|Gondola|Window Cleaning Machine<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Peso: 1700 kg<\/li>\n<li>Certifica\u00e7\u00e3o: ISO, CE<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: Engrenagem<\/li>\n<li>Acionamento\/atua\u00e7\u00e3o do elevador: motor el\u00e9trico<\/li>\n<li>Voltage:Window Cleaning Machine accept different voltage<\/li>\n<li>Capacidade de carga nominal: 630 kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Cambodia, Czech Republic, Jodhpur etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Temporary Access Platforms in Cambodia, Access Equipment<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale93.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Factory direct supply outdoor window wall clearning Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:Success-ZLP-220<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: cremalheira e pinh\u00e3o<\/li>\n<li>Acionamento\/Atua\u00e7\u00e3o do Elevador: Motor El\u00e9trico<\/li>\n<li>Power:50HZ\/60HZ<\/li>\n<li>Capacidade de carga nominal: 250-1000 kg<\/li>\n<li>Min. Lifting Height:50m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m<\/li>\n<li>Tamanho da mesa: 1+2+3m \/3*2,5m<\/li>\n<li>Dimens\u00f5es totais: 6m \/ 7m<\/li>\n<li>Peso: 1000 kg<\/li>\n<li>Certifica\u00e7\u00e3o: CE. GOST ISO<\/li>\n<li>Garantia: 12 meses<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Suspended Platform:Factory direct supply outdoor window wall clearning Suspended Platform<\/li>\n<li>cor: vermelho ou conforme a necessidade do cliente<\/li>\n<li>pot\u00eancia: 220V ou 380V etc.<\/li>\n<li>material: liga a ou a\u00e7o<\/li>\n<li>Site: www.bjfth.com<\/li>\n<li>N\u00famero do modelo: plataforma suspensa da s\u00e9rie ZLP<\/li>\n<li>comprimento da plataforma: 1-7,5 m<\/li>\n<li>Principais mercados: Austr\u00e1lia\/Sul da \u00c1sia\/Leste\/Bahia\/\u00c1frica do Sul\/Emirados \u00c1rabes Unidos<\/li>\n<li>Carga nominal: 630 kg\/800 kg\/1000 kg<\/li>\n<li>altura de trabalho: 30-200m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Patna, Sydney etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mode Electric Hoist For Suspended Platform in Czech Republic, Suspended Scaffording\/Suspended Platform\/Cradle in Jodhpur<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale70.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Hot sale new designed working platform\/building cleaning basket<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Name:new designed working platform\/building cleaning basket<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Pimpri-Chinchwad, Jamaica, Rosario, Cambodia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Specifications in Patna, Scaffolding Working Platform in Sydney<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale120.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Success ZLP1000 Building Construction Aluminum Lift Rope Suspended Stage Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Capacidade de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: A\u00e7o galvanizado\/Alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: galvanizado; HDG ou pulveriza\u00e7\u00e3o de pl\u00e1stico<\/li>\n<li>Comprimento da plataforma: 2m-12m; OEM<\/li>\n<li>Pot\u00eancia do motor el\u00e9trico: 1,5 kW*2; 1,8 kW*2; 2,2 kW*2; 3,0 kW*2<\/li>\n<li>Voltagem: 380V\/50HZ\/TRIF\u00c1SICO 220V\/50HZ\/MONOF\u00c1SICO<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200M<\/li>\n<li>Cor: Azul, laranja, vermelho, prata ou personalizado<\/li>\n<li>Aplica\u00e7\u00e3o: Constru\u00e7\u00e3o civil; Pintura, limpeza de janelas<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Qatar, Bamako, Rosario, Pimpri-Chinchwad etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Access Equipment, Scaffolding Working Platform in Sydney<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale113.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP250 250kg 1 person lift platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLP250<\/li>\n<li>voltage:380V\/50HZ<\/li>\n<li>Usage:Construction,Maintenance,Renovation,Painting, etc<\/li>\n<li>LENGTH OF PLATFORM:1.2M<\/li>\n<li>Rated load:250kg<\/li>\n<li>Surface treatment:Hot-dip galvanized or Aluminum<\/li>\n<li>Main export market:Southeast Asia,south America, Middle East,Russia<\/li>\n<li>Certificate:ISO, CE, GOST<\/li>\n<li>Feature:super light, surface can be rust-proof,anti-corrosion<\/li>\n<li>Buisiness type:manufacturer direct supplying<\/li>\n<li>Marca:Sucesso<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Cambodia, Jodhpur, Sydney, Jamaica etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Temporary Access Platforms in Cambodia, Suspended Platform Specifications in Patna<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of hoist suspended platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Jinfei Tianhong Model Number:ZLP voltage:380V ,220v etc Length:assemble any size in the <\/p>","protected":false},"author":1,"featured_media":8,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5868,9833,9836,9835,9834,9832],"class_list":["post-2337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-access-equipment","tag-mode-electric-hoist-for-suspended-platform-in-czech-republic","tag-scaffolding-working-platform-in-sydney","tag-suspended-platform-specifications-in-patna","tag-suspended-scaffordingsuspended-platformcradle-in-jodhpur","tag-temporary-access-platforms-in-cambodia"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/2337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=2337"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/2337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/8"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=2337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=2337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=2337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}