{"id":2184,"date":"2017-05-25T21:03:28","date_gmt":"2017-05-25T21:03:28","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zlp6308001000-rope-suspended-platform-for-high-rise-building.html"},"modified":"2017-05-25T21:03:28","modified_gmt":"2017-05-25T21:03:28","slug":"zlp6308001000-rope-suspended-platform-for-high-rise-building","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/zlp6308001000-rope-suspended-platform-for-high-rise-building.html","title":{"rendered":"ZLP630\/800\/1000 rope Suspended Platform for high rise building"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale122.jpg\" alt=\"ZLP630\/800\/1000 rope Suspended Platform for high rise building\" \/><br \/>\nImage of ZLP630\/800\/1000 rope Suspended Platform for high rise building<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLP500.630.800.1000<\/li>\n<li>Name:susended platform<\/li>\n<li>color:red<\/li>\n<li>lifting weight:1000kg<\/li>\n<li>altura de eleva\u00e7\u00e3o: 100m<\/li>\n<li>velocidade de eleva\u00e7\u00e3o: 10m\/min<\/li>\n<li>voltagem: 380v, pode ajustar<\/li>\n<li>pre\u00e7o:pre\u00e7o de f\u00e1brica<\/li>\n<li>quality:welcome by customers from world<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pX3ZkcTFRQ2xRM1E\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale145.jpg\" alt=\"ZLP630\/800\/1000 rope Suspended Platform for high rise building\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale138.jpg\" alt=\"ZLP630\/800\/1000 rope Suspended Platform for high rise building\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale72.jpg\" alt=\"ZLP630\/800\/1000 rope Suspended Platform for high rise building Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale62.jpg\" alt=\"ZLP630\/800\/1000 rope Suspended Platform for high rise building Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale254.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Brand Corner Suspended Platform, 500kg Load<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: el\u00e9trico<\/li>\n<li>Acionamento\/Atua\u00e7\u00e3o do Elevador: Motor El\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,5 kW, 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Capacidade de carga nominal: 630 kg, 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: 0 m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m, 200 m<\/li>\n<li>Tamanho da mesa: 6000*690*1180mm<\/li>\n<li>Dimens\u00f5es totais: 3 CBM<\/li>\n<li>Peso: 1700 kg<\/li>\n<li>Certifica\u00e7\u00e3o: ISO, CE<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: Engrenagem<\/li>\n<li>Acionamento\/atua\u00e7\u00e3o do elevador: motor el\u00e9trico<\/li>\n<li>Voltage:Brand Corner Suspended Platform 500kg Load accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Albania, Germany, Kharkiv etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hybrid Access Platforms in Albania, Aerial Work Platform For Sale<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale161.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">easy scaffoldings\/ Suspended platform, ZLP800, Success brand<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP 800<\/li>\n<li>Outros modelos::ZLP1000, ZLP630, ZLP500<\/li>\n<li>Suspension Mechanism:Galvanized<\/li>\n<li>Material da plataforma: a\u00e7o ou liga A<\/li>\n<li>Name:easy scaffoldings\/ Suspended Platform<\/li>\n<li>Usage:as a platform for people&#39;s high rise building maintaining work<\/li>\n<li>Shape:long shape or design as the client&#39;s bulding<\/li>\n<li>Aplica\u00e7\u00e3o da plataforma: manuten\u00e7\u00e3o, decora\u00e7\u00e3o ou limpeza de fachadas de edif\u00edcios<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Pune, Toronto etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mobile Scissor Lift in Germany, Zlp-630 Suspended Platforms in Kharkiv<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale154.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High-Rise Roof Suspended Work Platform Made in China<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP800<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: Engrenagem<\/li>\n<li>Acionamento\/atua\u00e7\u00e3o do elevador: motor el\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Capacidade de carga nominal: 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m<\/li>\n<li>Voltage:High-Rise Roof Suspended Work Platform accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Haiti, Ghent, Cali, Albania etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Manufacturer Zlp800 Suspended Platform in Pune, Mast Climbing Work Platform in Toronto<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale89.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Shanghai Success ZLP rope suspended platform\/window cleaning quipment\/swing stage with wall roller<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Usage:Other<\/li>\n<li>Power Source:Electric<\/li>\n<li>Sling Type:Wire Rope<\/li>\n<li>Maximum Lifting Weight:1000KG<\/li>\n<li>Maximum Lifting Height:300M<\/li>\n<li>Lift Speed:10M\/MIN<\/li>\n<li>Certification:CE,ISO,GOST<\/li>\n<li>Warranty:ONE YEAR<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: centro de servi\u00e7o no exterior dispon\u00edvel<\/li>\n<li>Name:susended platform<\/li>\n<li>color:red<\/li>\n<li>lifting weight:1000kg<\/li>\n<li>altura de eleva\u00e7\u00e3o: 100m<\/li>\n<li>velocidade de eleva\u00e7\u00e3o: 10m\/min<\/li>\n<li>voltagem: 380v, pode ajustar<\/li>\n<li>pre\u00e7o:pre\u00e7o de f\u00e1brica<\/li>\n<li>quality:welcome by customers from world<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Senegal, Lusaka , Cali, Haiti etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aerial Work Platform For Sale, Mast Climbing Work Platform in Toronto<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale100.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP1000 Electric Suspended Platform from China Manufacturer, CE\/ ISO standard<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLP1000<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: Engrenagem<\/li>\n<li>Acionamento\/atua\u00e7\u00e3o do elevador: motor el\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Capacidade de carga nominal: 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m<\/li>\n<li>Voltage:Electric Suspended Platform accept different voltage:220V,380V,etc<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Albania, Kharkiv, Toronto, Ghent etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hybrid Access Platforms in Albania, Manufacturer Zlp800 Suspended Platform in Pune<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of ZLP630\/800\/1000 rope Suspended Platform for high rise building Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP500.630.800.1000 Name:susended platform color:red lifting <\/p>","protected":false},"author":1,"featured_media":127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2999,9102,9105,9106,9103,9104],"class_list":["post-2184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aerial-work-platform-for-sale","tag-hybrid-access-platforms-in-albania","tag-manufacturer-zlp800-suspended-platform-in-pune","tag-mast-climbing-work-platform-in-toronto","tag-mobile-scissor-lift-in-germany","tag-zlp-630-suspended-platforms-in-kharkiv"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/2184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=2184"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/2184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/127"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=2184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=2184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=2184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}