{"id":2106,"date":"2017-05-25T06:20:02","date_gmt":"2017-05-25T06:20:02","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/aluminum-suspended-platform-of-construction-fast-packaged.html"},"modified":"2017-05-25T06:20:02","modified_gmt":"2017-05-25T06:20:02","slug":"aluminum-suspended-platform-of-construction-fast-packaged","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/aluminum-suspended-platform-of-construction-fast-packaged.html","title":{"rendered":"Aluminum suspended platform of construction fast packaged"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale205.jpg\" alt=\"Aluminum suspended platform of construction fast packaged\" \/><br \/>\nImage of Aluminum suspended platform of construction fast packaged<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>voltage:380V ,220v etc<\/li>\n<li>Length:assemble any size in the rage of 1m to 30m<\/li>\n<li>safty device:safty lock<\/li>\n<li>roll:vertical ,horizontal<\/li>\n<li>motor:LTD80,LTD1000S,LTD630<\/li>\n<li>automatic levelling system:locating pin<\/li>\n<li>overspeed safety device:certrifugal speed limiter<\/li>\n<li>emergency manual descent:speed reducer<\/li>\n<li>certificates:CE ISO<\/li>\n<li>Garantia: um ano<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pcURWUzR1WldsR3M\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale150.jpg\" alt=\"Aluminum suspended platform of construction fast packaged\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale98.jpg\" alt=\"Aluminum suspended platform of construction fast packaged\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale98.jpg\" alt=\"Aluminum suspended platform of construction fast packaged Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale84.jpg\" alt=\"Aluminum suspended platform of construction fast packaged Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale162.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">(CE &#038; GOST) ZLP630 ventana plataforma de limpieza<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: China (continental)<\/li>\n<li>Brand Name:CHINA-Success<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Usage:Building facade cleaning<\/li>\n<li>Cor: Vermelho ou outras cores<\/li>\n<li>Certificados: ISO, GOST, CE<\/li>\n<li>Fonte de energia: Eletricidade<\/li>\n<li>Tipo de acionamento: i\u00e7amento por cabo de a\u00e7o<\/li>\n<li>Aplica\u00e7\u00e3o: Manuten\u00e7\u00e3o de edif\u00edcios altos<\/li>\n<li>Origem: China<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8-10 m\/min<\/li>\n<li>Altura de eleva\u00e7\u00e3o e comprimento do cabo: 100 m<\/li>\n<li>Voltage:380V50HZ 3Phases or according to  customer need<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bogor, Depok, Kalyan-Dombivali etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Hoisting Machine in Bogor, Mature-Tech Access Suspended Platforms Inc<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale112.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Electric Cradle\/Suspended platform\/Gondola for Window Cleaning Machine<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLP1000<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: cabo de a\u00e7o<\/li>\n<li>Acionamento\/Acionamento do Elevador: Guindaste<\/li>\n<li>Power:2.2kw*2<\/li>\n<li>Capacidade de carga nominal: 1000 kg<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: 10 m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 100 m<\/li>\n<li>Table Size:7.5(2.5*3)*0.72*1.3m<\/li>\n<li>Dimens\u00f5es totais: 1850 mm * 1000 mm * 950 mm<\/li>\n<li>Weight:1200kg<\/li>\n<li>Certification:CE ISO<\/li>\n<li>Garantia: Um ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Name:Rope Suspended Platform<\/li>\n<li>Cor: Vermelho, prateado<\/li>\n<li>Voltagem: 220V\/380V\/50Hz<\/li>\n<li>Material: A\u00e7o, Alum\u00ednio, Galvanizado<\/li>\n<li>Contrapeso: 1000 kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8~10m\/min<\/li>\n<li>Model:ZLP1000<\/li>\n<li>Altura de eleva\u00e7\u00e3o: 100m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: New Taipei, Taiwan etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Tracked Access Platforms in Depok, Zlp800 Aluminum Lifting Speed Suspended Platform in Kalyan-Dombivali<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale10.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">man basket platform from China (CE\/GOST standard)<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP 800<\/li>\n<li>Outros modelos::ZLP1000, ZLP630, ZLP500<\/li>\n<li>Material da plataforma: a\u00e7o ou liga de alum\u00ednio<\/li>\n<li>Name:man basket platform<\/li>\n<li>Uso da plataforma: como plataforma para obras de constru\u00e7\u00e3o de edif\u00edcios altos<\/li>\n<li>Formato da plataforma: formato longo, leque, c\u00edrculo, redondo, formato U<\/li>\n<li>Aplica\u00e7\u00e3o da plataforma: manuten\u00e7\u00e3o, decora\u00e7\u00e3o ou limpeza de fachadas de edif\u00edcios<\/li>\n<li>Comprimento da plataforma: 1m-8m, pode ser montada conforme necess\u00e1rio<\/li>\n<li>Capacidade da plataforma: de 250 kg a 1000 kg<\/li>\n<li>Motor de plataforma: LTD630\/ 800\/ 1000 Talha<\/li>\n<li>Dispositivo de seguran\u00e7a: trava de seguran\u00e7a<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Guatemala, Ivory Coast, La Plata, Bogor etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Sky Climber Platform in New Taipei, Mobile Suspended Platform in Taiwan<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale164.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Special Designed High Building Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: Engrenagem<\/li>\n<li>Acionamento\/atua\u00e7\u00e3o do elevador: motor el\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Capacidade de carga nominal: 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m<\/li>\n<li>Voltage:High Building Suspended Platform accept different voltage,220V, 440V.<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Kathmandu, Kumasi, La Plata, Guatemala etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mature-Tech Access Suspended Platforms Inc, Mobile Suspended Platform in Taiwan<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale250.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP glass facade cleaning suspended platform, Success Brand New<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:elevated suspended platform<\/li>\n<li>Models::ZLP1000, ZLP800, ZLP630, ZLP500<\/li>\n<li>Name: glass facade cleaning  suspended platform<\/li>\n<li>Aplica\u00e7\u00e3o de plataforma suspensa modular: manuten\u00e7\u00e3o de edif\u00edcios<\/li>\n<li>Fixa\u00e7\u00e3o do telhado: 1, suspens\u00e3o com balc\u00e3o 2, bra\u00e7adeira de parapeito<\/li>\n<li>Plataforma Corpo: livre montado por modular<\/li>\n<li>Material da plataforma: a\u00e7o ou liga de alum\u00ednio<\/li>\n<li>Cor da plataforma: vermelho\/prata\/marca especial<\/li>\n<li>Formato da plataforma: cuboide ou design especial<\/li>\n<li>For\u00e7a motriz: talha el\u00e9trica<\/li>\n<li>Safety device for cradle platform:safety lock\/ safety rope<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bogor, Kalyan-Dombivali, Taiwan, Ivory Coast etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Hoisting Machine in Bogor, Suspended Sky Climber Platform in New Taipei<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Aluminum suspended platform of construction fast packaged Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP voltage:380V ,220v etc Length:assemble any <\/p>","protected":false},"author":1,"featured_media":259,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1542,8700,8697,8699,568,8698],"class_list":["post-2106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-mature-tech-access-suspended-platforms-inc","tag-mobile-suspended-platform-in-taiwan","tag-suspended-platform-hoisting-machine-in-bogor","tag-suspended-sky-climber-platform-in-new-taipei","tag-tracked-access-platforms-in-depok","tag-zlp800-aluminum-lifting-speed-suspended-platform-in-kalyan-dombivali"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/2106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=2106"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/2106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/259"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=2106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=2106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=2106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}