{"id":1958,"date":"2017-05-24T18:56:37","date_gmt":"2017-05-24T18:56:37","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/parapet-clamp-type-zlp630-suspended-platform.html"},"modified":"2017-05-24T18:56:37","modified_gmt":"2017-05-24T18:56:37","slug":"parapet-clamp-type-zlp630-suspended-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/parapet-clamp-type-zlp630-suspended-platform.html","title":{"rendered":"Parapet clamp type zlp630 suspended platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale229.jpg\" alt=\"Parapet clamp type zlp630 suspended platform\" \/><br \/>\nImage of Parapet clamp type zlp630 suspended platform<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Item:zlp630 suspended platform<\/li>\n<li>material:aluminum\/steel\/galvanized<\/li>\n<li>Voltage:220v\/380v\/480v<\/li>\n<li>frequency:50Hz\/60Hz<\/li>\n<li>Electric cable:100m<\/li>\n<li>wire rope:8.6mm<\/li>\n<li>altura de eleva\u00e7\u00e3o: 100m<\/li>\n<li>Certificates:CE, ISO, GOST<\/li>\n<li>how many year exported:more than 8 years<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pR1FiQllMbEJISUk\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale232.jpg\" alt=\"Parapet clamp type zlp630 suspended platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale43.jpg\" alt=\"Parapet clamp type zlp630 suspended platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale80.jpg\" alt=\"Parapet clamp type zlp630 suspended platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale47.jpg\" alt=\"Parapet clamp type zlp630 suspended platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale112.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">CE Marked Suspended Platform (ZLP Rope Suspended Platform)<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP800<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: el\u00e9trico<\/li>\n<li>Acionamento\/Atua\u00e7\u00e3o do Elevador: Motor El\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,8 kW, 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Capacidade de carga nominal: 800 kg, 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: 0 m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m, 200 m<\/li>\n<li>Tamanho da mesa: 7500*690*1180mm<\/li>\n<li>Overall Dimensions:4CBM<\/li>\n<li>Weight:2000kg<\/li>\n<li>Certifica\u00e7\u00e3o: ISO, CE<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: Engrenagem<\/li>\n<li>Acionamento\/atua\u00e7\u00e3o do elevador: motor el\u00e9trico<\/li>\n<li>Voltage:Suspended Platform (Rope Suspended Platform) accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bandung, Egypt, Jeddah etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mode Electric Hoist For Suspended Platform in Bandung, Industrial Scissor Lift<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale225.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Factory price zlp250\/ 500 suspended platforms gondola motor hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:HJ-SUP-290<\/li>\n<li>Capacidade de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: A\u00e7o galvanizado\/Alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: galvanizado; HDG ou pulveriza\u00e7\u00e3o de pl\u00e1stico<\/li>\n<li>Comprimento da plataforma: 2m-12m; OEM<\/li>\n<li>Pot\u00eancia do motor el\u00e9trico: 1,5 kW*2; 1,8 kW*2; 2,2 kW*2; 3,0 kW*2<\/li>\n<li>Lifting Speed:9.3M\/min<\/li>\n<li>Voltagem: 380V\/50HZ\/TRIF\u00c1SICO 220V\/50HZ\/MONOF\u00c1SICO<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200M<\/li>\n<li>Aplica\u00e7\u00e3o: Constru\u00e7\u00e3o civil; Pintura, limpeza de janelas<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Panama, South Africa etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Platform Access in Egypt, Zlp800 Aluminum Suspended Platform Building Facade in Jeddah<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale241.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Hoist For ZLP Series Suspended Platform,Electrial Suspended Scaffolds<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:LTD8.O<\/li>\n<li>Rated Loading Capacity(kg):800Kg<\/li>\n<li>Hoisting Speed:9.0m\/min<\/li>\n<li>Loder Weight:800kg<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Power:1.8kw<\/li>\n<li>Voltage:380V<\/li>\n<li>Rotational speed:1420r\/min<\/li>\n<li>Fequency:50Hz<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Vadodara, Lebanon, Norway, Bandung etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hosit Rope Suspended Platform in Panama, Crane Loading Platform in South Africa<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale55.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Window cleaning equipment electric suspended scaffolding<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Name: suspended platform<\/li>\n<li>Carga nominal: 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8-10 m\/min<\/li>\n<li>Dimension:6000(1+2+3m)*720*1300<\/li>\n<li>Lifting Height:100 m<\/li>\n<li>Pot\u00eancia: 1,5 kW * 2, 1,8 kW * 2<\/li>\n<li>Voltagem: 110V, 220V, 240V, 400V, 415V, 440V dispon\u00edveis<\/li>\n<li>Color:red,silver,orange,or as Required<\/li>\n<li>20&#39;ft container:9sets<\/li>\n<li>Certifica\u00e7\u00f5es: CE, ISO, GOST<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Hanoi, Ukraine, Norway, Vadodara etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Industrial Scissor Lift, Crane Loading Platform in South Africa<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale149.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">zlp series window cleaning suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP800<\/li>\n<li>Nome: Plataforma Suspensa<\/li>\n<li>Modelo: ZLP800<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Material:Aluminum<\/li>\n<li>Platform size:7.5*0.72*1.2m<\/li>\n<li>Altura de trabalho: 100m<\/li>\n<li>Cabo de a\u00e7o: 9,1 mm<\/li>\n<li>Cabo: 3*2,5+2*1,5<\/li>\n<li>Mecanismo de suspens\u00e3o: galvanizado a quente<\/li>\n<li>Counter weight:1000kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bandung, Jeddah, South Africa, Lebanon etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mode Electric Hoist For Suspended Platform in Bandung, Hosit Rope Suspended Platform in Panama<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Parapet clamp type zlp630 suspended platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP630 Item:zlp630 suspended platform material:aluminum\/steel\/galvanized Voltage:220v\/380v\/480v frequency:50Hz\/60Hz <\/p>","protected":false},"author":1,"featured_media":113,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[8028,8027,8023,8024,8025,8026],"class_list":["post-1958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-crane-loading-platform-in-south-africa","tag-hosit-rope-suspended-platform-in-panama","tag-industrial-scissor-lift","tag-mode-electric-hoist-for-suspended-platform-in-bandung","tag-platform-access-in-egypt","tag-zlp800-aluminum-suspended-platform-building-facade-in-jeddah"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/1958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=1958"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/1958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/113"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=1958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=1958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=1958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}