{"id":1916,"date":"2017-05-24T01:16:47","date_gmt":"2017-05-24T01:16:47","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/success-brand-zlp630-suspended-platform-hoist-ltd630.html"},"modified":"2017-05-24T01:16:47","modified_gmt":"2017-05-24T01:16:47","slug":"success-brand-zlp630-suspended-platform-hoist-ltd630","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/success-brand-zlp630-suspended-platform-hoist-ltd630.html","title":{"rendered":"Success brand zlp630 suspended platform hoist ltd630"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale217.jpg\" alt=\"Success brand zlp630 suspended platform hoist ltd630\" \/><br \/>\nImage of Success brand zlp630 suspended platform hoist ltd630<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:LTD630<\/li>\n<li>Usage:Construction Hoist<\/li>\n<li>Power Source:Electric<\/li>\n<li>Sling Type:Wire Rope<\/li>\n<li>Maximum Lifting Weight:630kg<\/li>\n<li>Maximum Lifting Height:100m<\/li>\n<li>Lift Speed:8-10m\/min<\/li>\n<li>Certification:CCC,CE,ISO,SGS<\/li>\n<li>Warranty:half year<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: centro de servi\u00e7o no exterior dispon\u00edvel<\/li>\n<li>Power supply:1.5kw<\/li>\n<li>Voltage:220V-440V<\/li>\n<li>Phase:single,three<\/li>\n<li>frequency:50Hz,60Hz<\/li>\n<li>lifting speed:8-10m\/min<\/li>\n<li>Rotational speed:1420r\/min<\/li>\n<li>wire rope:8.3mm<\/li>\n<li>usage:for zlp630 suspended platform<\/li>\n<li>keywords:hoist<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pME9aWk9kWDM5UWc\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale10.jpg\" alt=\"Success brand zlp630 suspended platform hoist ltd630\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale124.jpg\" alt=\"Success brand zlp630 suspended platform hoist ltd630\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale109.jpg\" alt=\"Success brand zlp630 suspended platform hoist ltd630 Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale90.jpg\" alt=\"Success brand zlp630 suspended platform hoist ltd630 Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale15.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">500KG neon gondola lift apart<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Name:neon gondola lift apart<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Agra, Egypt, Managua etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Electric Control Box For Suspended Platform in Agra, Scaffolding Platforms For Sale<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale79.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Cheap aluminum ladders,Chimney Suspended Access Platform,China Factory ZLP630 Gondola Lift<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Capacidade de carga nominal (kg): 630 kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8-10 m\/min<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 300 m<\/li>\n<li>Dimension(L*W*H):6000*720*1300<\/li>\n<li>Loder Weight:250kg-1000kg<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>formato da plataforma: longo, leque, c\u00edrculo, formato de U\u2026<\/li>\n<li>Material da plataforma: a\u00e7o ou liga A<\/li>\n<li>capacidade: de 250kg a 1000kg<\/li>\n<li>Carga nominal: 500 kg 630 kg 800 kg 1000 kg<\/li>\n<li>Comprimento da plataforma: 1m-7,5m<\/li>\n<li>boa qualidade:CE, Gost, certificado ISO aprovado<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Puebla, Sapporo etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Window Washer Scaffold in Egypt, Stage Lift Suspended Platform in Managua<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale238.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">metal scaffolding platform from factory<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP 800<\/li>\n<li>Outros modelos::ZLP1000, ZLP630, ZLP500<\/li>\n<li>Platform Material:steel or Aluminum alloy<\/li>\n<li>Name:metal scaffolding platform<\/li>\n<li>Formato da plataforma: formato longo, leque, c\u00edrculo, formato U<\/li>\n<li>Aplica\u00e7\u00e3o da plataforma: manuten\u00e7\u00e3o, decora\u00e7\u00e3o ou limpeza de fachadas de edif\u00edcios<\/li>\n<li>Platform Length:1m-7.5m, can assembly free<\/li>\n<li>Capacidade da plataforma: de 250 kg a 1000 kg<\/li>\n<li>Voltage:110V to 440V<\/li>\n<li>Power Source:Electric Hoist<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Howrah, London, Maceio, Agra etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hydraulic Electric Scaffolding Platform in Puebla, Small Access Platforms in Sapporo<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale159.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Southeast Asia Hot Selling Aluminum Fitting Working Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:HJ-SUP187<\/li>\n<li>Product name:Southeast Asia Hot Selling Aluminum Fitting Working Platform<\/li>\n<li>Surface Protection: Painting and Galvanize<\/li>\n<li>Keywords:zlp series suspend platforms<\/li>\n<li>Color: Red , Yellow , Other<\/li>\n<li>Certification: ISO , CE , GOST proved<\/li>\n<li>Type:construction platforms<\/li>\n<li>Certificate:ISO , CE , GOST proved<\/li>\n<li>Market:global, over 30contries<\/li>\n<li>Item:suspend platforms<\/li>\n<li>place of origin:Shanghai, China (Mainland)<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Jeddah, Giza, Maceio, Howrah etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Scaffolding Platforms For Sale, Small Access Platforms in Sapporo<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale202.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP630 Famous Brand Suspended Platform\/Sky Lift\/Gondola From China Manufacture<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Capacidade de carga nominal: 630 kg<\/li>\n<li>Cor: Vermelho, pode ser personalizado<\/li>\n<li>Pot\u00eancia do motor: 1,5 kW*2<\/li>\n<li>Platform Dimension:6000*0.72*1300<\/li>\n<li>Voltagem: 220V\/380V\/415V-Trif\u00e1sico\/50Hz\/60Hz<\/li>\n<li>Di\u00e2metro do cabo de a\u00e7o: 8,3 mm<\/li>\n<li>Altura de eleva\u00e7\u00e3o: 100m-120m<\/li>\n<li>Modelo: Plataforma de trabalho suspensa ZLP630<\/li>\n<li>Cabo de travamento Angel: 3-8\u00b0<\/li>\n<li>Comprimento da sali\u00eancia da viga frontal: 1,3-1,5 m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Agra, Managua, Sapporo, London etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Electric Control Box For Suspended Platform in Agra, Hydraulic Electric Scaffolding Platform in Puebla<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Success brand zlp630 suspended platform hoist ltd630 Quick Details: Condition:New Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:LTD630 Usage:Construction Hoist Power Source:Electric <\/p>","protected":false},"author":1,"featured_media":36,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7801,7804,1690,7805,7803,7802],"class_list":["post-1916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-electric-control-box-for-suspended-platform-in-agra","tag-hydraulic-electric-scaffolding-platform-in-puebla","tag-scaffolding-platforms-for-sale","tag-small-access-platforms-in-sapporo","tag-stage-lift-suspended-platform-in-managua","tag-window-washer-scaffold-in-egypt"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/1916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=1916"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/1916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/36"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=1916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=1916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=1916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}