{"id":1053,"date":"2017-05-18T10:05:34","date_gmt":"2017-05-18T10:05:34","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/shanghai-success-types-of-scaffold-platform.html"},"modified":"2017-05-18T10:05:34","modified_gmt":"2017-05-18T10:05:34","slug":"shanghai-success-types-of-scaffold-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/shanghai-success-types-of-scaffold-platform.html","title":{"rendered":"Shanghai Success types of scaffold platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale248.jpg\" alt=\"Shanghai Success types of scaffold platform\" \/><br \/>\nImage of Shanghai Success types of scaffold platform<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Name:types of scaffold platform<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pUmJweTRjeVk2WUk\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale249.jpg\" alt=\"Shanghai Success types of scaffold platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale260.jpg\" alt=\"Shanghai Success types of scaffold platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale70.jpg\" alt=\"Shanghai Success types of scaffold platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale77.jpg\" alt=\"Shanghai Success types of scaffold platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale96.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">630KG window cleaning cradle system installation dubai<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP<\/li>\n<li>Name:window cleaning cradle system installation dubai<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Antananarivo, Germiston, Kota etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hoist Electric Construction Platform Lift in Antananarivo, Building Main Construction Suspend Platforms<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale90.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">China high-rise window cleaning suspended platform\/glass window cleaning machine<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Name:suspended platform\/ cradle\/ gondola\/ scaffold<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Rosario, Saudi Arabia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Manual Lifting Suspended Platform in Germiston, Scissor Boom Lift in Kota<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale199.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High Safety max load 800kg suspended vertical aerial work platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Name:max load 800kg suspended vertical aerial work platform<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Hong Kong, Donetsk, Santiago, Antananarivo etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Height Adjustable Work Platforms in Rosario, Steel Electric Rope Suspended Platform in Saudi Arabia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale133.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">window cleaning gondola hanging Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Brand Name:JH<\/li>\n<li>Model Number:JH-ZLP-134<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: cremalheira e pinh\u00e3o<\/li>\n<li>Acionamento\/Atua\u00e7\u00e3o do Elevador: Motor El\u00e9trico<\/li>\n<li>Pot\u00eancia: 50HZ<\/li>\n<li>Capacidade de carga nominal: 250-1000 kg<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: 100 m<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150 m<\/li>\n<li>Tamanho da mesa: 1+2+3m \/3*2,5m<\/li>\n<li>Dimens\u00f5es totais: 6m \/ 7m<\/li>\n<li>Peso: 1000 kg<\/li>\n<li>Certifica\u00e7\u00e3o: CE. GOST ISO<\/li>\n<li>Garantia: um ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Suspended Platform:window cleaning gondola hanging Suspended Platform<\/li>\n<li>cor: vermelho ou conforme a necessidade do cliente<\/li>\n<li>pot\u00eancia: 220V ou 380V etc.<\/li>\n<li>material: liga a ou a\u00e7o<\/li>\n<li>Site: www.bjfth.com<\/li>\n<li>N\u00famero do modelo: plataforma suspensa da s\u00e9rie ZLP<\/li>\n<li>comprimento da plataforma: 1-7,5 m<\/li>\n<li>Principais mercados: Austr\u00e1lia\/Sul da \u00c1sia\/Leste\/Bahia\/\u00c1frica do Sul\/Emirados \u00c1rabes Unidos<\/li>\n<li>Carga nominal: 630 kg\/800 kg\/1000 kg<\/li>\n<li>altura de trabalho: 30-200m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Tijuana, Uganda, Santiago, Hong Kong etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Building Main Construction Suspend Platforms, Steel Electric Rope Suspended Platform in Saudi Arabia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale107.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP630 Swing Stage,Suspended Platform,Suspended Scaffolds<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Nome: Plataforma de corda suspensa OU plataforma de trabalho<\/li>\n<li>Aplica\u00e7\u00e3o da plataforma Cradle: Manuten\u00e7\u00e3o de edif\u00edcios, limpeza, pintura<\/li>\n<li>Fixa\u00e7\u00e3o do telhado: 1, suspens\u00e3o com balc\u00e3o 2, bra\u00e7adeira de parapeito<\/li>\n<li>Cor da plataforma: vermelho, prata, galvanizado a quente<\/li>\n<li>Dispositivo de seguran\u00e7a: trava de seguran\u00e7a, corda de seguran\u00e7a etc.<\/li>\n<li>For\u00e7a motriz: talha el\u00e9trica<\/li>\n<li>Formato da plataforma: cuboide ou design especial<\/li>\n<li>Padr\u00e3o de plataforma: CE, GOST, ISO<\/li>\n<li>Material da plataforma: a\u00e7o ou liga de alum\u00ednio<\/li>\n<li>Corpo da plataforma: montado livremente por placa modular<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Antananarivo, Kota, Saudi Arabia, Donetsk etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hoist Electric Construction Platform Lift in Antananarivo, Height Adjustable Work Platforms in Rosario<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Shanghai Success types of scaffold platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP Name:types of scaffold platform Color:optional Power <\/p>","protected":false},"author":1,"featured_media":258,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[4186,4190,4187,4188,4189,4191],"class_list":["post-1053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-building-main-construction-suspend-platforms","tag-height-adjustable-work-platforms-in-rosario","tag-hoist-electric-construction-platform-lift-in-antananarivo","tag-manual-lifting-suspended-platform-in-germiston","tag-scissor-boom-lift-in-kota","tag-steel-electric-rope-suspended-platform-in-saudi-arabia"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/1053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=1053"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/1053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/258"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=1053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=1053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=1053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}