{"id":1046,"date":"2017-05-18T23:52:04","date_gmt":"2017-05-18T23:52:04","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/competitive-price-moving-platform-electric-gondola.html"},"modified":"2017-05-18T23:52:04","modified_gmt":"2017-05-18T23:52:04","slug":"competitive-price-moving-platform-electric-gondola","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/pt\/competitive-price-moving-platform-electric-gondola.html","title":{"rendered":"Competitive Price moving platform electric gondola"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale213.jpg\" alt=\"Competitive Price moving platform electric gondola\" \/><br \/>\nImage of Competitive Price moving platform electric gondola<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Name:moving platform electric gondola<\/li>\n<li>Cor: opcional<\/li>\n<li>Fonte de alimenta\u00e7\u00e3o (V): 220,380,415,440<\/li>\n<li>Dispositivo de seguran\u00e7a: 7 itens<\/li>\n<li>Material: A\u00e7o ou alum\u00ednio<\/li>\n<li>Tratamento de superf\u00edcie: pintura por pulveriza\u00e7\u00e3o ou galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Fornecimento de pe\u00e7as gr\u00e1tis<\/li>\n<li>corda de a\u00e7o: galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Guincho: Feito de alum\u00ednio fundido<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pTi1XWU5KNXp3OHM\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale238.jpg\" alt=\"Competitive Price moving platform electric gondola\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale247.jpg\" alt=\"Competitive Price moving platform electric gondola\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Mostrar acess\u00f3rios relacionados: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale43.jpg\" alt=\"Competitive Price moving platform electric gondola Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale31.jpg\" alt=\"Competitive Price moving platform electric gondola Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale76.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">(CE,ISO) Andaime suspenso\/Plataforma suspensa\/Plataforma de trabalho em constru\u00e7\u00e3o<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLP300<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: Engrenagem<\/li>\n<li>Acionamento\/atua\u00e7\u00e3o do elevador: motor el\u00e9trico<\/li>\n<li>Pot\u00eancia: 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Capacidade de carga nominal: 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 200 m<\/li>\n<li>Voltagem: Plataforma de trabalho de constru\u00e7\u00e3o aceita voltagem diferente<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bangladesh, Iceland, Konya etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Rope Suspended Platform\/Cradle\/Gondola in Bangladesh, Industrial Use Car Platform Lift<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale132.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction equipment for aerial working\/suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Carga nominal: 1000 kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 8~10m\/min<\/li>\n<li>Altura de eleva\u00e7\u00e3o: 100m<\/li>\n<li>Cabo: 100m<\/li>\n<li>Contrapeso: 1000 kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Pune, South Sudan etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Manual Suspended Scaffolding Working Platform in Iceland, Mature-Tech Aerial Work Platforms For Sale in Konya<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale109.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">high rise window cleaning equipment\/suspended working platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:ZLP Series<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Lifting Speed:8~10m\/min<\/li>\n<li>Lifting Height:100m<\/li>\n<li>Cabo: 100m<\/li>\n<li>Power:380V<\/li>\n<li>Voltage:50Hz<\/li>\n<li>Front beam overhang:1.3~1.5m<\/li>\n<li>Support adjustable height:1.44~2.14m<\/li>\n<li>platform:corrosion-resistant<\/li>\n<li>Material:Aluminum or steel<\/li>\n<li>Dimension(L*W*H)::7500*720*1300mm<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Visakhapatnam, Catania, Netherlands, Bangladesh etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminium Step Up Work Platform in Pune, Mc Zlp Electric Cradle And Suspended Platform in South Sudan<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale97.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Plataforma suspensa com guincho el\u00e9trico<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: ZLP630<\/li>\n<li>Material: A\u00e7o, Liga de Alum\u00ednio<\/li>\n<li>Cor: Vermelho, Amarelo, Azul, etc.<\/li>\n<li>Tratamento de superf\u00edcie: Revestimento em p\u00f3, galvaniza\u00e7\u00e3o a quente<\/li>\n<li>Comprimento:2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Pot\u00eancia: 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Capacidade de carga nominal: 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Voltagem: A plataforma suspensa com talha el\u00e9trica aceita diferentes voltagens.<\/li>\n<li>Aplica\u00e7\u00e3o: Pr\u00e9dios altos, tanques grandes, chamin\u00e9s, barragens, pontes, torres de perfura\u00e7\u00e3o, etc.<\/li>\n<li>Plataforma especial: pode ser personalizada e fornecida<\/li>\n<li>Certifica\u00e7\u00e3o: ISO, CE<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ecatepec de Morelos, Mbuji-Mayi, Netherlands, Visakhapatnam etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Industrial Use Car Platform Lift, Mc Zlp Electric Cradle And Suspended Platform in South Sudan<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale124.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP1000 1000 kg Safe Suspended Working Platform Scaffold Systems<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: China (continental)<\/li>\n<li>Brand Name: Window Cleaning Suspended Platform<\/li>\n<li>N\u00famero do modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Name:Steel Suspended Working Platform<\/li>\n<li>Aplica\u00e7\u00e3o da plataforma Cradle: Manuten\u00e7\u00e3o de edif\u00edcios, limpeza, pintura<\/li>\n<li>Fixa\u00e7\u00e3o do telhado: 1, suspens\u00e3o com balc\u00e3o 2, bra\u00e7adeira de parapeito<\/li>\n<li>Cor da plataforma: vermelho, prata, galvanizado a quente<\/li>\n<li>Dispositivo de seguran\u00e7a: trava de seguran\u00e7a, corda de seguran\u00e7a etc.<\/li>\n<li>For\u00e7a motriz: talha el\u00e9trica<\/li>\n<li>Formato da plataforma: cuboide ou design especial<\/li>\n<li>Padr\u00e3o de plataforma: CE, GOST, ISO<\/li>\n<li>Material da plataforma: a\u00e7o ou liga de alum\u00ednio<\/li>\n<li>Corpo da plataforma: montado livremente por placa modular<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bangladesh, Konya, South Sudan, Catania etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Rope Suspended Platform\/Cradle\/Gondola in Bangladesh, Aluminium Step Up Work Platform in Pune<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Competitive Price moving platform electric gondola Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000 After-sales Service Provided:Engineers available to service <\/p>","protected":false},"author":1,"featured_media":166,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[4151,2086,4149,4150,4152,3099],"class_list":["post-1046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aluminium-step-up-work-platform-in-pune","tag-industrial-use-car-platform-lift","tag-manual-suspended-scaffolding-working-platform-in-iceland","tag-mature-tech-aerial-work-platforms-for-sale-in-konya","tag-mc-zlp-electric-cradle-and-suspended-platform-in-south-sudan","tag-rope-suspended-platformcradlegondola-in-bangladesh"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/1046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/comments?post=1046"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/posts\/1046\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media\/166"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/media?parent=1046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/categories?post=1046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/pt\/wp-json\/wp\/v2\/tags?post=1046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}