{"id":2711,"date":"2017-06-01T07:32:13","date_gmt":"2017-06-01T07:32:13","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zlp-suspended-working-platformpower-climbersuspension-platform.html"},"modified":"2017-06-01T07:32:13","modified_gmt":"2017-06-01T07:32:13","slug":"zlp-suspended-working-platformpower-climbersuspension-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/fa\/zlp-suspended-working-platformpower-climbersuspension-platform.html","title":{"rendered":"ZLP Suspended working platform\/power climber\/suspension platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale82.jpg\" alt=\"ZLP Suspended working platform\/power climber\/suspension platform\" \/><br \/>\nImage of ZLP Suspended working platform\/power climber\/suspension platform<\/p>\n<h3 class=\"alpha-title\">\u062c\u0632\u0626\u06cc\u0627\u062a \u0633\u0631\u06cc\u0639: <\/h3>\n<ul class=\"alpha-ali\">\n<li>\u0645\u062d\u0644 \u0645\u0628\u062f\u0627: \u0634\u0627\u0646\u06af\u0647\u0627\u06cc\u060c \u0686\u06cc\u0646 (\u0633\u0631\u0632\u0645\u06cc\u0646 \u0627\u0635\u0644\u06cc)<\/li>\n<li>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc: \u0645\u0648\u0641\u0642\u06cc\u062a<\/li>\n<li>\u0634\u0645\u0627\u0631\u0647 \u0645\u062f\u0644: ZLP630<\/li>\n<li>Rated Loading Capacity:630Kg<\/li>\n<li>Hoisting Speed:8-10m\/min<\/li>\n<li>Max Lifting Height:200m<\/li>\n<li>Platform:Powder painting<\/li>\n<li>Dimension:adjustable<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0648\u06cc\u062f\u06cc\u0648\u06cc \u0645\u0631\u062a\u0628\u0637: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pX2FLNGJDM2kyTlU\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0634\u0631\u062d: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale140.jpg\" alt=\"ZLP Suspended working platform\/power climber\/suspension platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale187.jpg\" alt=\"ZLP Suspended working platform\/power climber\/suspension platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0646\u0645\u0627\u06cc\u0634 \u0644\u0648\u0627\u0632\u0645 \u062c\u0627\u0646\u0628\u06cc \u0645\u0631\u062a\u0628\u0637: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale75.jpg\" alt=\"ZLP Suspended working platform\/power climber\/suspension platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale90.jpg\" alt=\"ZLP Suspended working platform\/power climber\/suspension platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">\u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale64.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Alibaba Best Sellers Scaffolding Lift Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u062d\u0644 \u0645\u0628\u062f\u0627: \u0634\u0627\u0646\u06af\u0647\u0627\u06cc\u060c \u0686\u06cc\u0646 (\u0633\u0631\u0632\u0645\u06cc\u0646 \u0627\u0635\u0644\u06cc)<\/li>\n<li>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc: \u0645\u0648\u0641\u0642\u06cc\u062a<\/li>\n<li>Model Number:HJ-SUP081<\/li>\n<li>Product name:Alibaba Best Sellers Scaffolding Lift Platform<\/li>\n<li>Surface Protection: Painting and Galvanize<\/li>\n<li>Keywords:Scaffolding Lift Platform<\/li>\n<li>Color: Red , Yellow , Other<\/li>\n<li>Certification: ISO , CE , GOST proved<\/li>\n<li>Type:construction platforms<\/li>\n<li>Certificate:ISO , CE , GOST proved<\/li>\n<li>Market:global, over 30contries<\/li>\n<li>Item:suspend platforms<\/li>\n<li>place of origin:Shanghai, China (Mainland)<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bahrain, Fortress, Moldova etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Affordable Temporary Working Platform in Bahrain, Aerial Working Platforms<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale139.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Competitive Price scaffolding for high rise work platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u062d\u0644 \u0645\u0628\u062f\u0627: \u0634\u0627\u0646\u06af\u0647\u0627\u06cc\u060c \u0686\u06cc\u0646 (\u0633\u0631\u0632\u0645\u06cc\u0646 \u0627\u0635\u0644\u06cc)<\/li>\n<li>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc: \u0645\u0648\u0641\u0642\u06cc\u062a<\/li>\n<li>\u0634\u0645\u0627\u0631\u0647 \u0645\u062f\u0644: ZLP250\u060c ZLP500\u060c ZLP630\u060c ZLP800\u060c ZLP1000<\/li>\n<li>\u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634 \u0627\u0631\u0627\u0626\u0647 \u0634\u062f\u0647: \u0645\u0647\u0646\u062f\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062e\u062f\u0645\u0627\u062a \u0645\u0627\u0634\u06cc\u0646 \u0622\u0644\u0627\u062a \u062f\u0631 \u062e\u0627\u0631\u062c \u0627\u0632 \u06a9\u0634\u0648\u0631 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0647\u0633\u062a\u0646\u062f<\/li>\n<li>Name:scaffolding for high rise work platform<\/li>\n<li>\u0631\u0646\u06af: \u0627\u062e\u062a\u06cc\u0627\u0631\u06cc<\/li>\n<li>\u0645\u0646\u0628\u0639 \u062a\u063a\u0630\u06cc\u0647 (\u0648\u0644\u062a): 220\u060c380\u060c415\u060c440<\/li>\n<li>\u062f\u0633\u062a\u06af\u0627\u0647 \u0627\u06cc\u0645\u0646\u06cc: 7 \u0645\u0648\u0631\u062f<\/li>\n<li>\u062c\u0646\u0633: \u0641\u0648\u0644\u0627\u062f \u06cc\u0627 \u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645<\/li>\n<li>\u0639\u0645\u0644\u06cc\u0627\u062a \u0633\u0637\u062d\u06cc: \u0627\u0633\u067e\u0631\u06cc \u0631\u0646\u06af \u06cc\u0627 \u06af\u0627\u0644\u0648\u0627\u0646\u06cc\u0632\u0647 \u06af\u0631\u0645<\/li>\n<li>\u0642\u0633\u0645\u062a \u0631\u0627\u06cc\u06af\u0627\u0646: \u0639\u0631\u0636\u0647<\/li>\n<li>\u0637\u0646\u0627\u0628 \u0641\u0648\u0644\u0627\u062f\u06cc: \u06af\u0627\u0644\u0648\u0627\u0646\u06cc\u0632\u0647 \u06af\u0631\u0645<\/li>\n<li>\u0628\u0627\u0644\u0627\u0628\u0631: \u0633\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0627\u0632 \u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645 \u0631\u06cc\u062e\u062a\u0647 \u06af\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/li>\n<li>\u06af\u0648\u0627\u0647\u06cc: CE\u060c ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Salvador, South Tangerang etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mc Zlp630 Suspended Working Platform in Fortress, Stage Scaffolding in Moldova<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale196.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">LTD630 Suspended Platform Hoist,630kg Hoist,630kg Loading Capacity Hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condition:New<\/li>\n<li>\u0645\u062d\u0644 \u0645\u0628\u062f\u0627: \u0634\u0627\u0646\u06af\u0647\u0627\u06cc\u060c \u0686\u06cc\u0646 (\u0633\u0631\u0632\u0645\u06cc\u0646 \u0627\u0635\u0644\u06cc)<\/li>\n<li>Brand Name:Success\/FTH<\/li>\n<li>Model Number:LTD630 \/800\/1000<\/li>\n<li>Usage:Climb Lifting<\/li>\n<li>Power Source:Electric<\/li>\n<li>Sling Type:Cable<\/li>\n<li>Maximum Lifting Weight:1000KG<\/li>\n<li>Maximum Lifting Height:120M<\/li>\n<li>Lift Speed:9.6M\/MIN<\/li>\n<li>Certification:CE<\/li>\n<li>Warranty:1 Year Warranty<\/li>\n<li>After-sales Service Provided:Overseas third-party support available<\/li>\n<li>Model:LTD100 LTD80 LTD80A LTD63<\/li>\n<li>Rated Lifting Force:10\/8\/8\/6.3kn<\/li>\n<li>Cable Diameter:8.6\/8.6\/9.1\/8.3mm<\/li>\n<li>Overall Dimension:700*370*320mm<\/li>\n<li>Voltage:220v-380v\/480v<\/li>\n<li>Frequency(Hz):50\/60hz<\/li>\n<li>Power:2.2\/1.8\/1.5kw<\/li>\n<li>Braking Torque(N.m):15KN<\/li>\n<li>Rotation Speed(r\/min):1420r<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Agra, Lebanon, Bel\u00e9m, Bahrain etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Spray Paint Aerial Suspended Platform in Salvador, Painting Platform Lifts in South Tangerang<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale229.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">\u0645\u0648\u0641\u0642\u06cc\u062a ZLP630 \u0635\u0641\u062d\u0647 \u0646\u0645\u0627\u06cc\u0634 \u0686\u0631\u062e\u0634\u06cc \u062a\u0645\u06cc\u0632 \u06a9\u0631\u062f\u0646 \u0646\u0645\u0627\u06cc \u0633\u0627\u062e\u062a\u0645\u0627\u0646 \u067e\u0644\u062a \u0641\u0631\u0645 \u0645\u0639\u0644\u0642 \u0628\u0631\u0627\u06cc \u0633\u0627\u062e\u062a \u0648 \u0633\u0627\u0632<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u062d\u0644 \u0645\u0628\u062f\u0627: \u0634\u0627\u0646\u06af\u0647\u0627\u06cc\u060c \u0686\u06cc\u0646 (\u0633\u0631\u0632\u0645\u06cc\u0646 \u0627\u0635\u0644\u06cc)<\/li>\n<li>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc: \u0645\u0648\u0641\u0642\u06cc\u062a<\/li>\n<li>\u0634\u0645\u0627\u0631\u0647 \u0645\u062f\u0644: ZLP500\/630\/800\/1000<\/li>\n<li>\u0638\u0631\u0641\u06cc\u062a \u0628\u0627\u0631\u06af\u06cc\u0631\u06cc: \u06f5\u06f0\u06f0 \u06a9\u06cc\u0644\u0648\u06af\u0631\u0645\u061b \u06f6\u06f3\u06f0 \u06a9\u06cc\u0644\u0648\u06af\u0631\u0645\u061b \u06f8\u06f0\u06f0 \u06a9\u06cc\u0644\u0648\u06af\u0631\u0645\u061b \u06f1\u06f0\u06f0\u06f0 \u06a9\u06cc\u0644\u0648\u06af\u0631\u0645<\/li>\n<li>\u062c\u0646\u0633: \u0641\u0648\u0644\u0627\u062f \u06af\u0627\u0644\u0648\u0627\u0646\u06cc\u0632\u0647\/\u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645<\/li>\n<li>\u0639\u0645\u0644\u06cc\u0627\u062a \u0633\u0637\u062d: \u06af\u0627\u0644\u0648\u0627\u0646\u06cc\u0632\u0647\u061b HDG \u06cc\u0627 \u0627\u0633\u067e\u0631\u06cc \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc<\/li>\n<li>\u0637\u0648\u0644 \u0633\u06a9\u0648: 2 \u062a\u0627 12 \u0645\u062a\u0631\u061b \u0646\u0635\u0628 \u0634\u062f\u0647<\/li>\n<li>\u062a\u0648\u0627\u0646 \u0645\u0648\u062a\u0648\u0631 \u0627\u0644\u06a9\u062a\u0631\u06cc\u06a9\u06cc: 1.5 \u06a9\u06cc\u0644\u0648\u0648\u0627\u062a * 2\u061b 1.8 \u06a9\u06cc\u0644\u0648\u0648\u0627\u062a * 2\u061b 2.2 \u06a9\u06cc\u0644\u0648\u0648\u0627\u062a * 2\u061b 3.0 \u06a9\u06cc\u0644\u0648\u0648\u0627\u062a * 2<\/li>\n<li>\u0648\u0644\u062a\u0627\u0698: \u06f3\u06f8\u06f0 \u0648\u0644\u062a\/\u06f5\u06f0 \u0647\u0631\u062a\u0632\/\u0633\u0647 \u0641\u0627\u0632 \u06f2\u06f2\u06f0 \u0648\u0644\u062a\/\u06f5\u06f0 \u0647\u0631\u062a\u0632\/\u062a\u06a9 \u0641\u0627\u0632<\/li>\n<li>\u062d\u062f\u0627\u06a9\u062b\u0631 \u0627\u0631\u062a\u0641\u0627\u0639 \u0628\u0627\u0644\u0627\u0628\u0631\u06cc: 200 \u0645\u062a\u0631<\/li>\n<li>\u0631\u0646\u06af: \u0622\u0628\u06cc\u060c \u0646\u0627\u0631\u0646\u062c\u06cc\u060c \u0642\u0631\u0645\u0632\u060c \u0646\u0642\u0631\u0647\u200c\u0627\u06cc \u06cc\u0627 \u0633\u0641\u0627\u0631\u0634\u06cc<\/li>\n<li>\u06a9\u0627\u0631\u0628\u0631\u062f: \u0633\u0627\u062e\u062a \u0648 \u0633\u0627\u0632 \u0633\u0627\u062e\u062a\u0645\u0627\u0646\u061b \u0646\u0642\u0627\u0634\u06cc\u060c \u062a\u0645\u06cc\u0632 \u06a9\u0631\u062f\u0646 \u067e\u0646\u062c\u0631\u0647<\/li>\n<li>\u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Jeddah, Port Said, Bel\u00e9m, Agra etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aerial Working Platforms, Painting Platform Lifts in South Tangerang<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale142.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP Electric Construction\/ Building\/ External Wall Suspended Platform\/ Cradle\/ Gondola\/ Swing Stage\/ Climber\/ Scaffold<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u062d\u0644 \u0645\u0628\u062f\u0627: \u0634\u0627\u0646\u06af\u0647\u0627\u06cc\u060c \u0686\u06cc\u0646 (\u0633\u0631\u0632\u0645\u06cc\u0646 \u0627\u0635\u0644\u06cc)<\/li>\n<li>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc: \u0645\u0648\u0641\u0642\u06cc\u062a<\/li>\n<li>\u0634\u0645\u0627\u0631\u0647 \u0645\u062f\u0644: ZLP<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bahrain, Moldova, South Tangerang, Lebanon etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Affordable Temporary Working Platform in Bahrain, Spray Paint Aerial Suspended Platform in Salvador<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of ZLP Suspended working platform\/power climber\/suspension platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP630 Rated Loading Capacity:630Kg Hoisting Speed:8-10m\/min Max <\/p>","protected":false},"author":1,"featured_media":72,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3359,11639,11640,11643,11642,11641],"class_list":["post-2711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aerial-working-platforms","tag-affordable-temporary-working-platform-in-bahrain","tag-mc-zlp630-suspended-working-platform-in-fortress","tag-painting-platform-lifts-in-south-tangerang","tag-spray-paint-aerial-suspended-platform-in-salvador","tag-stage-scaffolding-in-moldova"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/posts\/2711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/comments?post=2711"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/posts\/2711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/media\/72"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/media?parent=2711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/categories?post=2711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/tags?post=2711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}