{"id":1956,"date":"2017-05-24T23:26:27","date_gmt":"2017-05-24T23:26:27","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/shanghai-suspended-platform.html"},"modified":"2017-05-24T23:26:27","modified_gmt":"2017-05-24T23:26:27","slug":"shanghai-suspended-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/fa\/shanghai-suspended-platform.html","title":{"rendered":"Shanghai suspended platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale178.jpg\" alt=\"Shanghai suspended platform\" \/><br \/>\nImage of Shanghai suspended platform<\/p>\n<h3 class=\"alpha-title\">\u062c\u0632\u0626\u06cc\u0627\u062a \u0633\u0631\u06cc\u0639: <\/h3>\n<ul class=\"alpha-ali\">\n<li>\u0645\u062d\u0644 \u0645\u0628\u062f\u0627: \u0634\u0627\u0646\u06af\u0647\u0627\u06cc\u060c \u0686\u06cc\u0646 (\u0633\u0631\u0632\u0645\u06cc\u0646 \u0627\u0635\u0644\u06cc)<\/li>\n<li>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc: \u0645\u0648\u0641\u0642\u06cc\u062a<\/li>\n<li>\u0634\u0645\u0627\u0631\u0647 \u0645\u062f\u0644: ZLP800<\/li>\n<li>Name:Suspended Platform<\/li>\n<li>Model:ZLP800<\/li>\n<li>Brand:Success<\/li>\n<li>Material:Aluminum<\/li>\n<li>Platform size:7.5*0.72*1.2m<\/li>\n<li>Work height:100m<\/li>\n<li>Steel wire rope:9.1mm<\/li>\n<li>Cable:3*2.5+2*1.5<\/li>\n<li>Suspension mechanism:Hot deep galvanized<\/li>\n<li>Counter weight:1000kg<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0648\u06cc\u062f\u06cc\u0648\u06cc \u0645\u0631\u062a\u0628\u0637: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pQ3dXelB1d292ZjA\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0634\u0631\u062d: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale140.jpg\" alt=\"Shanghai suspended platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale20.jpg\" alt=\"Shanghai suspended platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0646\u0645\u0627\u06cc\u0634 \u0644\u0648\u0627\u0632\u0645 \u062c\u0627\u0646\u0628\u06cc \u0645\u0631\u062a\u0628\u0637: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale35.jpg\" alt=\"Shanghai suspended platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale78.jpg\" alt=\"Shanghai suspended platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">\u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale235.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">1000KG tri cable gondola lift wind limit<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u062d\u0644 \u0645\u0628\u062f\u0627: \u0634\u0627\u0646\u06af\u0647\u0627\u06cc\u060c \u0686\u06cc\u0646 (\u0633\u0631\u0632\u0645\u06cc\u0646 \u0627\u0635\u0644\u06cc)<\/li>\n<li>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc: \u0645\u0648\u0641\u0642\u06cc\u062a<\/li>\n<li>\u0634\u0645\u0627\u0631\u0647 \u0645\u062f\u0644: ZLP<\/li>\n<li>Name:tri cable gondola lift wind limit<\/li>\n<li>\u0631\u0646\u06af: \u0627\u062e\u062a\u06cc\u0627\u0631\u06cc<\/li>\n<li>\u0645\u0646\u0628\u0639 \u062a\u063a\u0630\u06cc\u0647 (\u0648\u0644\u062a): 220\u060c380\u060c415\u060c440<\/li>\n<li>\u062f\u0633\u062a\u06af\u0627\u0647 \u0627\u06cc\u0645\u0646\u06cc: 7 \u0645\u0648\u0631\u062f<\/li>\n<li>\u062c\u0646\u0633: \u0641\u0648\u0644\u0627\u062f \u06cc\u0627 \u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645<\/li>\n<li>\u0639\u0645\u0644\u06cc\u0627\u062a \u0633\u0637\u062d\u06cc: \u0627\u0633\u067e\u0631\u06cc \u0631\u0646\u06af \u06cc\u0627 \u06af\u0627\u0644\u0648\u0627\u0646\u06cc\u0632\u0647 \u06af\u0631\u0645<\/li>\n<li>\u0642\u0633\u0645\u062a \u0631\u0627\u06cc\u06af\u0627\u0646: \u0639\u0631\u0636\u0647<\/li>\n<li>\u0637\u0646\u0627\u0628 \u0641\u0648\u0644\u0627\u062f\u06cc: \u06af\u0627\u0644\u0648\u0627\u0646\u06cc\u0632\u0647 \u06af\u0631\u0645<\/li>\n<li>\u0628\u0627\u0644\u0627\u0628\u0631: \u0633\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0627\u0632 \u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645 \u0631\u06cc\u062e\u062a\u0647 \u06af\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/li>\n<li>\u06af\u0648\u0627\u0647\u06cc: CE\u060c ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Berlin, Giza, Malaysia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminum Zlp 630 Suspended Working Platform in Berlin, Manual Working Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale264.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction ZLP Suspended Construction Platform\/Window Cleaning Machine<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u062d\u0644 \u0645\u0628\u062f\u0627: \u0634\u0627\u0646\u06af\u0647\u0627\u06cc\u060c \u0686\u06cc\u0646 (\u0633\u0631\u0632\u0645\u06cc\u0646 \u0627\u0635\u0644\u06cc)<\/li>\n<li>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc: \u0645\u0648\u0641\u0642\u06cc\u062a<\/li>\n<li>Model Number:ZLP500<\/li>\n<li>Lift Mechanism:Gear<\/li>\n<li>\u0646\u06cc\u0631\u0648\u06cc \u0645\u062d\u0631\u06a9\u0647\/\u0639\u0645\u0644\u06a9\u0631\u062f \u0628\u0627\u0644\u0627\u0628\u0631: \u0645\u0648\u062a\u0648\u0631 \u0627\u0644\u06a9\u062a\u0631\u06cc\u06a9\u06cc<\/li>\n<li>Power:1.5kw, 1.5kw, 1.8kw, 2kw<\/li>\n<li>Rated Loading Capacity:200kg, 150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Min. Lifting Height:0m<\/li>\n<li>\u062d\u062f\u0627\u06a9\u062b\u0631 \u0627\u0631\u062a\u0641\u0627\u0639 \u0628\u0627\u0644\u0627\u0628\u0631\u06cc: 200 \u0645\u062a\u0631<\/li>\n<li>Table Size:5000*690*1180mm(W*H)<\/li>\n<li>Overall Dimensions:3CBM<\/li>\n<li>Weight:1600kg<\/li>\n<li>Certification:CE, ISO, ISO, CE<\/li>\n<li>\u06af\u0627\u0631\u0627\u0646\u062a\u06cc: 1 \u0633\u0627\u0644<\/li>\n<li>\u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634 \u0627\u0631\u0627\u0626\u0647 \u0634\u062f\u0647: \u0645\u0647\u0646\u062f\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062e\u062f\u0645\u0627\u062a \u0645\u0627\u0634\u06cc\u0646 \u0622\u0644\u0627\u062a \u062f\u0631 \u062e\u0627\u0631\u062c \u0627\u0632 \u06a9\u0634\u0648\u0631 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0647\u0633\u062a\u0646\u062f<\/li>\n<li>\u062c\u0646\u0633: \u0641\u0648\u0644\u0627\u062f\u060c \u0622\u0644\u06cc\u0627\u0698 \u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645<\/li>\n<li>\u0631\u0646\u06af: \u0642\u0631\u0645\u0632\u060c \u0632\u0631\u062f\u060c \u0622\u0628\u06cc \u0648 \u063a\u06cc\u0631\u0647<\/li>\n<li>Surface Treatment:Powder coating, Hot galvanization<\/li>\n<li>\u0637\u0648\u0644: 2 \u0645\u062a\u0631\u060c 2.5 \u0645\u062a\u0631\u060c 3 \u0645\u062a\u0631\u060c 5 \u0645\u062a\u0631\u060c 6 \u0645\u062a\u0631\u060c 7.5 \u0645\u062a\u0631 \u0648 \u063a\u06cc\u0631\u0647<\/li>\n<li>Voltage:Construction Suspended Construction Platform accept different voltages<\/li>\n<li>Application:High-rise building, Large tank, Chimney, Dams, Bridges, Derrick, etc<\/li>\n<li>Special platform:Can be customized and supplied<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Nicaragua, Thailand etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspension Platform in Giza, Suspended Personnel Platform in Malaysia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale138.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High quality Suspended Platform for Washing Windows,6M,630kg Lifting Capacity<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Place of Origin:China (Mainland)<\/li>\n<li>Brand Name:Platform for Washing Windows<\/li>\n<li>\u0634\u0645\u0627\u0631\u0647 \u0645\u062f\u0644: ZLP500\/630\/800\/1000<\/li>\n<li>Name:Suspended Rope Platform OR Working Platform<\/li>\n<li>Cradle Platform Application:Building maintainence, cleaning,painting<\/li>\n<li>Roof Fixing:1,suspension with counter 2, parapet clamp<\/li>\n<li>Platform Color:Red,Silver,Hot Galvanized<\/li>\n<li>Safety device:safety lock, safe rope etc<\/li>\n<li>Motive Power:Electric Hoist<\/li>\n<li>Platform Shape:cuboid or special design<\/li>\n<li>Platform standard: CE, GOST, ISO<\/li>\n<li>Platform Material:Steel or Aluminum Alloy<\/li>\n<li>Platform Body:free assembled by modular plate<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ghaziabad, Liberia, Quito, Berlin etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminum Lift Suspended Platform in Nicaragua, Sale Access Suspended Platforms in Thailand<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale127.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Shanghai China ZLP series Mature-tech ZLP500 suspended working platforms<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u062d\u0644 \u0645\u0628\u062f\u0627: \u0634\u0627\u0646\u06af\u0647\u0627\u06cc\u060c \u0686\u06cc\u0646 (\u0633\u0631\u0632\u0645\u06cc\u0646 \u0627\u0635\u0644\u06cc)<\/li>\n<li>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc: \u0645\u0648\u0641\u0642\u06cc\u062a<\/li>\n<li>\u0634\u0645\u0627\u0631\u0647 \u0645\u062f\u0644: ZLP<\/li>\n<li>Name:Mature-tech ZLP500 suspended working platforms<\/li>\n<li>\u0631\u0646\u06af: \u0627\u062e\u062a\u06cc\u0627\u0631\u06cc<\/li>\n<li>\u0645\u0646\u0628\u0639 \u062a\u063a\u0630\u06cc\u0647 (\u0648\u0644\u062a): 220\u060c380\u060c415\u060c440<\/li>\n<li>\u062f\u0633\u062a\u06af\u0627\u0647 \u0627\u06cc\u0645\u0646\u06cc: 7 \u0645\u0648\u0631\u062f<\/li>\n<li>\u062c\u0646\u0633: \u0641\u0648\u0644\u0627\u062f \u06cc\u0627 \u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645<\/li>\n<li>\u0639\u0645\u0644\u06cc\u0627\u062a \u0633\u0637\u062d\u06cc: \u0627\u0633\u067e\u0631\u06cc \u0631\u0646\u06af \u06cc\u0627 \u06af\u0627\u0644\u0648\u0627\u0646\u06cc\u0632\u0647 \u06af\u0631\u0645<\/li>\n<li>\u0642\u0633\u0645\u062a \u0631\u0627\u06cc\u06af\u0627\u0646: \u0639\u0631\u0636\u0647<\/li>\n<li>\u0637\u0646\u0627\u0628 \u0641\u0648\u0644\u0627\u062f\u06cc: \u06af\u0627\u0644\u0648\u0627\u0646\u06cc\u0632\u0647 \u06af\u0631\u0645<\/li>\n<li>\u0628\u0627\u0644\u0627\u0628\u0631: \u0633\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0627\u0632 \u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645 \u0631\u06cc\u062e\u062a\u0647 \u06af\u0631\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631<\/li>\n<li>\u06af\u0648\u0627\u0647\u06cc: CE\u060c ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Philadelphia, Niamey, Quito, Ghaziabad etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Manual Working Platform, Sale Access Suspended Platforms in Thailand<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale9.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP Building platform,Suspension access equipment, suspended scaffold,gondola,lift stage<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u062d\u0644 \u0645\u0628\u062f\u0627: \u0634\u0627\u0646\u06af\u0647\u0627\u06cc\u060c \u0686\u06cc\u0646 (\u0633\u0631\u0632\u0645\u06cc\u0646 \u0627\u0635\u0644\u06cc)<\/li>\n<li>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc: \u0645\u0648\u0641\u0642\u06cc\u062a<\/li>\n<li>Model Number:ZLP630\/ZLP800<\/li>\n<li>Lift Mechanism:Lift Chain<\/li>\n<li>\u0646\u06cc\u0631\u0648\u06cc \u0645\u062d\u0631\u06a9\u0647\/\u0639\u0645\u0644\u06a9\u0631\u062f \u0628\u0627\u0644\u0627\u0628\u0631: \u0645\u0648\u062a\u0648\u0631 \u0627\u0644\u06a9\u062a\u0631\u06cc\u06a9\u06cc<\/li>\n<li>Power:1.5kw*2\/1.8kw*2<\/li>\n<li>\u0638\u0631\u0641\u06cc\u062a \u0628\u0627\u0631\u06af\u06cc\u0631\u06cc \u0645\u062c\u0627\u0632: 630 \u06a9\u06cc\u0644\u0648\u06af\u0631\u0645<\/li>\n<li>Min. Lifting Height:0m<\/li>\n<li>\u062d\u062f\u0627\u06a9\u062b\u0631 \u0627\u0631\u062a\u0641\u0627\u0639 \u0628\u0627\u0644\u0627\u0628\u0631\u06cc: \u06f1\u06f0\u06f0 \u0645\u062a\u0631<\/li>\n<li>Table Size:6000*720*1300mm\/7500*720*1300mm<\/li>\n<li>Overall Dimensions:requirement<\/li>\n<li>Weight:800kg<\/li>\n<li>Certification:CE,ISO,GOST .<\/li>\n<li>Warranty:1Year<\/li>\n<li>After-sales Service Provided:No overseas service provided<\/li>\n<li>Color:Silvery<\/li>\n<li>Counterweight:800kg<\/li>\n<li>Voltage:380v\/50hz<\/li>\n<li>Cable:100M<\/li>\n<li>Lifing speed:8-10m\/min<\/li>\n<li>Name: Suspended Scaffolding<\/li>\n<li>Application:Aerial Work<\/li>\n<li>Feature:Easy Operation Safety Convenience<\/li>\n<li>Lifting speed:3-6m\/min<\/li>\n<li>Motor power:380v Etc)<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Berlin, Malaysia, Thailand, Liberia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminum Zlp 630 Suspended Working Platform in Berlin, Aluminum Lift Suspended Platform in Nicaragua<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u067e\u06cc\u0627\u0645 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Shanghai suspended platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP800 Name:Suspended Platform Model:ZLP800 Brand:Success Material:Aluminum Platform size:7.5*0.72*1.2m Work height:100m <\/p>","protected":false},"author":1,"featured_media":258,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[8016,8013,3836,8017,8015,8014],"class_list":["post-1956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aluminum-lift-suspended-platform-in-nicaragua","tag-aluminum-zlp-630-suspended-working-platform-in-berlin","tag-manual-working-platform","tag-sale-access-suspended-platforms-in-thailand","tag-suspended-personnel-platform-in-malaysia","tag-suspension-platform-in-giza"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/posts\/1956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/comments?post=1956"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/posts\/1956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/media\/258"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/media?parent=1956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/categories?post=1956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/fa\/wp-json\/wp\/v2\/tags?post=1956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}