{"id":767,"date":"2017-05-18T03:24:56","date_gmt":"2017-05-18T03:24:56","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/china-suspended-platform-spare-parts.html"},"modified":"2017-05-18T03:24:56","modified_gmt":"2017-05-18T03:24:56","slug":"china-suspended-platform-spare-parts","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/china-suspended-platform-spare-parts.html","title":{"rendered":"China suspended platform spare parts"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale87.jpg\" alt=\"China suspended platform spare parts\" \/><br \/>\nImage of China suspended platform spare parts<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:suspended platform spare parts<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pUHNDTGU2bHBXTm8\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale210.jpg\" alt=\"China suspended platform spare parts\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale150.jpg\" alt=\"China suspended platform spare parts\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale56.jpg\" alt=\"China suspended platform spare parts Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale21.jpg\" alt=\"China suspended platform spare parts Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale169.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">2014 new aluminium climber ZLP800 ZLP630 low price steel construction cradle\/suspended platform for high building<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:ZLP round work platform<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bengaluru, Dallas, Mendoza etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Work Platforms For Sale in Bengaluru, Movable Scaffolding Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale233.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Electric cradle platform hanging work gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Carga nominal: 630 kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8~10 m\/min<\/li>\n<li>Altura de elevaci\u00f3n: 100 m<\/li>\n<li>Cable: 100 m<\/li>\n<li>Counterweight:630kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Nairobi, Tashkent etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Facade Construction Suspended Platform in Dallas, Mature-Tech Roof Access Platforms in Mendoza<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale256.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Hot ZLP500 Series Aluminum Rope Suspended Platform Construction<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Capacidad de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: acero galvanizado\/aluminio<\/li>\n<li>Tratamiento de superficie: galvanizado; HDG o pulverizaci\u00f3n de pl\u00e1stico<\/li>\n<li>Longitud de la plataforma: 2 m-12 m; OEM<\/li>\n<li>Potencia del motor el\u00e9ctrico: 1,5 KW*2; 1,8 KW*2; 2,2 KW*2; 3,0 KW*2<\/li>\n<li>Voltaje: 380 V\/50 Hz\/trif\u00e1sico 220 V\/50 Hz\/monof\u00e1sico<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 200 m<\/li>\n<li>Color: azul, naranja, rojo, plateado o personalizado.<\/li>\n<li>Aplicaci\u00f3n: Construcci\u00f3n de edificios, pintura, limpieza de ventanas.<\/li>\n<li>Certificaci\u00f3n: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Jabalpur, Libya, Malta, Bengaluru etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Work Platform Lifts in Nairobi, Zlp Cheap Gondola Suspended Building Platform in Tashkent<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale102.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Saftey Lock for ZLP 630 electric scaffold<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:Jinfei Tianhong<\/li>\n<li>Model Number:LSB 30\/SAL 30<\/li>\n<li>Useage:Safty Lock for ZLP 630 electric scaffold<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ecatepec de Morelos, Lusaka , Malta, Jabalpur etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Movable Scaffolding Platform, Zlp Cheap Gondola Suspended Building Platform in Tashkent<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale99.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">window cleaning hanging scaffold construction gondola equipment<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Carga nominal: 500 kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8~10 m\/min<\/li>\n<li>Altura de elevaci\u00f3n: 100 m<\/li>\n<li>Cable: 100 m<\/li>\n<li>Contrapeso: 500 kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bengaluru, Mendoza, Tashkent, Libya etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Work Platforms For Sale in Bengaluru, Work Platform Lifts in Nairobi<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of China suspended platform spare parts Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000 After-sales Service Provided:Engineers available to service machinery <\/p>","protected":false},"author":1,"featured_media":119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2650,2651,1764,2652,2649,2653],"class_list":["post-767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-facade-construction-suspended-platform-in-dallas","tag-mature-tech-roof-access-platforms-in-mendoza","tag-movable-scaffolding-platform","tag-work-platform-lifts-in-nairobi","tag-work-platforms-for-sale-in-bengaluru","tag-zlp-cheap-gondola-suspended-building-platform-in-tashkent"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=767"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/119"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}