{"id":3176,"date":"2017-06-05T12:26:30","date_gmt":"2017-06-05T12:26:30","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zlp800-800kg-7-5m-in-length-facadehighrise-cleaning-cradle.html"},"modified":"2017-06-05T12:26:30","modified_gmt":"2017-06-05T12:26:30","slug":"zlp800-800kg-7-5m-in-length-facadehighrise-cleaning-cradle","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/zlp800-800kg-7-5m-in-length-facadehighrise-cleaning-cradle.html","title":{"rendered":"ZLP800 800KG 7.5M in length Facade\/Highrise cleaning cradle"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale56.jpg\" alt=\"ZLP800 800KG 7.5M in length Facade\/Highrise cleaning cradle\" \/><br \/>\nImage of ZLP800 800KG 7.5M in length Facade\/Highrise cleaning cradle<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP800<\/li>\n<li>Cable: 3*2,5+2*1,5<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Material: acero o aleaci\u00f3n de aluminio.<\/li>\n<li>Certificados: ISO, GOST, CE<\/li>\n<li>Altura de elevaci\u00f3n: 100 m<\/li>\n<li>Name:ZLP800 800KG 7.5M in length Facade\/Highrise cleaning cradle<\/li>\n<li>Original: China<\/li>\n<li>Application:ZLP Boom Lift\/ Electric Aerial Suspended Platform<\/li>\n<li>Voltage:220V\/380V\/415V<\/li>\n<li>Color:Red or silver<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pTHJwdWF3ZmJUTnc\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale216.jpg\" alt=\"ZLP800 800KG 7.5M in length Facade\/Highrise cleaning cradle\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale200.jpg\" alt=\"ZLP800 800KG 7.5M in length Facade\/Highrise cleaning cradle\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale8.jpg\" alt=\"ZLP800 800KG 7.5M in length Facade\/Highrise cleaning cradle Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale14.jpg\" alt=\"ZLP800 800KG 7.5M in length Facade\/Highrise cleaning cradle Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale228.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Aluminium machine roof suspension system electric suspended scaffold<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Carga nominal: 630 kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8~10 m\/min<\/li>\n<li>Altura de elevaci\u00f3n: 100 m<\/li>\n<li>Cable: 100 m<\/li>\n<li>Counterweight:630kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ankara, Coimbatore, Malaysia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Motorized Suspended Rope Platform in Ankara, Scaffolding Platform Safety<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale179.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Easy Installation zlp800 construction gondola\/suspended platform made in china<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:zlp800 construction gondola\/suspended platform made in china<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Patna, Thane etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: All Models Suspended Platform\/Cradle\/Gondola in Coimbatore, Suspended Platform Bed in Malaysia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale182.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Hot sale walking platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:walking platform<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Srinagar, Raipur, Havana, Ankara etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Inspection Suspended Platform in Patna, Motorized Suspended Rope Platform in Thane<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale40.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">rope suspended platform\/swing stage,high-rise roof suspended work platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:ZLP Series<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Lifting Speed:8~10m\/min<\/li>\n<li>Altura de elevaci\u00f3n: 100 m<\/li>\n<li>Cable: 100 m<\/li>\n<li>Power:380V<\/li>\n<li>Voltage:50Hz<\/li>\n<li>Front beam overhang:1.3~1.5m<\/li>\n<li>Support adjustable height:1.44~2.14m<\/li>\n<li>platform:corrosion-resistant<\/li>\n<li>Material:Aluminum or steel<\/li>\n<li>Dimension(L*W*H)::7500*720*1300mm<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Dallas, Fez, Havana, Srinagar etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Scaffolding Platform Safety, Motorized Suspended Rope Platform in Thane<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale35.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP500 zlp 630 Temporary Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>Lift Mechanism:Electric<\/li>\n<li>Accionamiento\/actuaci\u00f3n del ascensor: motor el\u00e9ctrico<\/li>\n<li>Power:1.5kw, 1.5kw, 1.8kw, 2kw<\/li>\n<li>Rated Loading Capacity:630kg, 150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Altura m\u00ednima de elevaci\u00f3n: 0 m<\/li>\n<li>Max. Lifting Height:200m, 200m<\/li>\n<li>Table Size:6000*690*1180mm<\/li>\n<li>Overall Dimensions:3CBM<\/li>\n<li>Weight:1700kg<\/li>\n<li>Certification:ISO, CE<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Material: acero, aleaci\u00f3n de aluminio<\/li>\n<li>Color: rojo, amarillo, azul, etc.<\/li>\n<li>Surface treatment:Powder coating, Hot galvanization<\/li>\n<li>Longitud: 2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Lifing Mechanism:Gear<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Voltage:ZLP500 zlp 630 Temporary Suspended Platform accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ankara, Malaysia, Thane, Raipur etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Motorized Suspended Rope Platform in Ankara, Inspection Suspended Platform in Patna<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of ZLP800 800KG 7.5M in length Facade\/Highrise cleaning cradle Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP800 Cable:3*2.5+2*1.5 Lifting Speed:8-10m\/min Material:steel <\/p>","protected":false},"author":1,"featured_media":258,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[13947,13949,13946,13950,1479,13948],"class_list":["post-3176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-all-models-suspended-platformcradlegondola-in-coimbatore","tag-inspection-suspended-platform-in-patna","tag-motorized-suspended-rope-platform-in-ankara","tag-motorized-suspended-rope-platform-in-thane","tag-scaffolding-platform-safety","tag-suspended-platform-bed-in-malaysia"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/3176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=3176"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/3176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/258"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=3176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=3176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=3176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}