{"id":3083,"date":"2017-06-04T03:11:32","date_gmt":"2017-06-04T03:11:32","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zpl-series-steel-scaffold-for-construction.html"},"modified":"2017-06-04T03:11:32","modified_gmt":"2017-06-04T03:11:32","slug":"zpl-series-steel-scaffold-for-construction","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/zpl-series-steel-scaffold-for-construction.html","title":{"rendered":"ZPL series steel scaffold for construction"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale99.jpg\" alt=\"ZPL series steel scaffold for construction\" \/><br \/>\nImage of ZPL series steel scaffold for construction<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Product name:ZLP service basket<\/li>\n<li>Material:Aluminum Alloy or steel<\/li>\n<li>Voltage:110\/220\/380\/415 Optional<\/li>\n<li>Rated load:500\/630\/800\/1000kg<\/li>\n<li>Usage:People&#39;s High Rise Building Maintaining Work<\/li>\n<li>Type:Suspended Working Platform Equipment<\/li>\n<li>Application:Tall Building Maintenance<\/li>\n<li>Color:Black\\gray\\red or customize<\/li>\n<li>Certificate:CE ISO SQS GOST<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pSmhkRU40bEM5N3c\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale114.jpg\" alt=\"ZPL series steel scaffold for construction\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale207.jpg\" alt=\"ZPL series steel scaffold for construction\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale102.jpg\" alt=\"ZPL series steel scaffold for construction Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale57.jpg\" alt=\"ZPL series steel scaffold for construction Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale77.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Automatic 1000,800,630kg Suspended Platform\/High rise window cleaning machine\/Good outlook gondola\/Cradle\/working platforms\/Lift<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca: Success-CHINA<\/li>\n<li>Model Number:ZLP630 ZLP800<\/li>\n<li>Usage:Suspended Platform for Window Cleaning Solutions<\/li>\n<li>Colour:Red or other colors<\/li>\n<li>Certificados: ISO, GOST, CE<\/li>\n<li>Power Source:Electricity<\/li>\n<li>Drive Type:Wire rope hoisting<\/li>\n<li>Application:Tall Building Maintenance<\/li>\n<li>Origin:China<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Lifting Height and Cable Length:100m<\/li>\n<li>Voltage:380V50HZ 3Phases or according to  customer need<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Amman, Coimbatore, Meerut etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Zlp in Amman, Portable Man Lift<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale171.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction building lifting power gondola zlp 800 suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP800<\/li>\n<li>Capacidad de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: acero galvanizado\/aluminio<\/li>\n<li>Tratamiento de superficie: galvanizado; HDG o pulverizaci\u00f3n de pl\u00e1stico<\/li>\n<li>Longitud de la plataforma: 2 m-12 m; OEM<\/li>\n<li>Potencia del motor el\u00e9ctrico: 1,5 KW*2; 1,8 KW*2; 2,2 KW*2; 3,0 KW*2<\/li>\n<li>Voltaje: 380 V\/50 Hz\/trif\u00e1sico 220 V\/50 Hz\/monof\u00e1sico<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 200 m<\/li>\n<li>Color: azul, naranja, rojo, plateado o personalizado.<\/li>\n<li>Aplicaci\u00f3n: Construcci\u00f3n de edificios, pintura, limpieza de ventanas.<\/li>\n<li>Certificaci\u00f3n: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Palembang, Swaziland etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Lift Access Platforms in Coimbatore, Rope Suspended Platform Construction in Meerut<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale131.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Mobile electric platform lift suspended wire rope platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Rated load:1000kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8~10 m\/min<\/li>\n<li>Altura de elevaci\u00f3n: 100 m<\/li>\n<li>Cable: 100 m<\/li>\n<li>Counterweight:1000kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Srinagar, Turin, Bel\u00e9m, Amman etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Construction Aluminum Lift Platform in Palembang, Mobile Access Platforms in Swaziland<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale236.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Wall Painting Elevated Work Platform Swing Stage For Construction<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:HJ-SUP-010<\/li>\n<li>Material:Galvanized steel or Aluminum<\/li>\n<li>Tratamiento de superficie: galvanizado; HDG o pulverizaci\u00f3n de pl\u00e1stico<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Color: azul, naranja, rojo, plateado o personalizado.<\/li>\n<li>Certification: ISO , CE , GOST proved<\/li>\n<li>Platform Length:2m-12m<\/li>\n<li>Market:global, over 30contries<\/li>\n<li>Function\/Usage:People&#39;s High Rise Building Main Construction<\/li>\n<li>Type:Aluminum Suspended\/Suspended working platform<\/li>\n<li>OEM service:Accept<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Karachi, Ouagadougou, Bel\u00e9m, Srinagar etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Portable Man Lift, Mobile Access Platforms in Swaziland<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale91.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP630 Suspended Gondola For Glass Curtain Walls Installation<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>Rated Loading Capacity:630kg<\/li>\n<li>Colour:Red,Can be Customized<\/li>\n<li>Motor Power:1.5KW*2<\/li>\n<li>Platform Dimension:6000*0.72*1300<\/li>\n<li>Voltaje: 220 V\/380 V\/415 V-trif\u00e1sico\/50 Hz\/60 Hz<\/li>\n<li>Steel Rope Diamter:8.3mm<\/li>\n<li>Lifting Height:100m-120m<\/li>\n<li>Model:ZLP630 Suspended Working Platform<\/li>\n<li>Locking Cable Angel:3-8&deg;<\/li>\n<li>Overhang Length of Front Beam:1.3-1.5m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Amman, Meerut, Swaziland, Turin etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Zlp in Amman, Construction Aluminum Lift Platform in Palembang<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of ZPL series steel scaffold for construction Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP500\/630\/800\/1000 Product name:ZLP service basket Material:Aluminum Alloy <\/p>","protected":false},"author":1,"featured_media":270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[13491,13492,7145,13490,13489,13488],"class_list":["post-3083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-construction-aluminum-lift-platform-in-palembang","tag-mobile-access-platforms-in-swaziland","tag-portable-man-lift","tag-rope-suspended-platform-construction-in-meerut","tag-suspended-lift-access-platforms-in-coimbatore","tag-suspended-platform-zlp-in-amman"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/3083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=3083"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/3083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/270"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=3083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=3083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=3083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}