{"id":3061,"date":"2017-06-04T02:20:07","date_gmt":"2017-06-04T02:20:07","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zpl-electric-hoist-powered-gondola-bmu-with-high-quality.html"},"modified":"2017-06-04T02:20:07","modified_gmt":"2017-06-04T02:20:07","slug":"zpl-electric-hoist-powered-gondola-bmu-with-high-quality","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/zpl-electric-hoist-powered-gondola-bmu-with-high-quality.html","title":{"rendered":"ZPL Electric Hoist Powered Gondola bmu With High Quality"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale135.jpg\" alt=\"ZPL Electric Hoist Powered Gondola bmu With High Quality\" \/><br \/>\nImage of ZPL Electric Hoist Powered Gondola bmu With High Quality<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP<\/li>\n<li>Product name:suspended electric hoist<\/li>\n<li>Material:Aluminum Alloy<\/li>\n<li>Certificate:CE ISO SQS GOST<\/li>\n<li>Voltage:110\/220\/380\/415 Optional<\/li>\n<li>Rated load:500kg\/ 630kg\/ 800kg\/ 1000kg<\/li>\n<li>Usage:People&#39;s High Rise Building Maintaining Work<\/li>\n<li>Type:Suspended Working Platform Equipment<\/li>\n<li>Application:Tall Building Maintenance<\/li>\n<li>Color:Black\\gray\\red or customize<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pQUwxeV8tc0F2dDA\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale195.jpg\" alt=\"ZPL Electric Hoist Powered Gondola bmu With High Quality\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale245.jpg\" alt=\"ZPL Electric Hoist Powered Gondola bmu With High Quality\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale2.jpg\" alt=\"ZPL Electric Hoist Powered Gondola bmu With High Quality Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale33.jpg\" alt=\"ZPL Electric Hoist Powered Gondola bmu With High Quality Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale129.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">380V Suspended working Platform ZLP800 for windows cleaning<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca: JH<\/li>\n<li>Model Number:JH-ZLP-116<\/li>\n<li>Mecanismo de elevaci\u00f3n: cremallera y pi\u00f1\u00f3n<\/li>\n<li>Accionamiento\/actuaci\u00f3n del ascensor: motor el\u00e9ctrico<\/li>\n<li>Potencia: 50 Hz<\/li>\n<li>Capacidad de carga nominal: 250-1000 kg<\/li>\n<li>Altura m\u00ednima de elevaci\u00f3n: 100 m<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 150 m<\/li>\n<li>Tama\u00f1o de la mesa: 1+2+3m \/ 3*2,5m<\/li>\n<li>Dimensiones generales: 6 m \/ 7 m<\/li>\n<li>Peso: 1000 kg<\/li>\n<li>Certificaci\u00f3n: CE, GOST e ISO<\/li>\n<li>Garant\u00eda: un a\u00f1o<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Suspended Platform:380V Suspended working Platform ZLP800 for windows cleaning<\/li>\n<li>Color: rojo o seg\u00fan las necesidades del cliente.<\/li>\n<li>Potencia: 220 V o 380 V, etc.<\/li>\n<li>Material: aleaci\u00f3n A o acero.<\/li>\n<li>Sitio web: www.bjSuccess.com<\/li>\n<li>N\u00famero de modelo: Plataforma suspendida serie ZLP<\/li>\n<li>Longitud de la plataforma: 1-7,5 m<\/li>\n<li>Mercados principales: Australia, Sur de Asia, Este, Brasil, Sud\u00e1frica y Emiratos \u00c1rabes Unidos<\/li>\n<li>Carga nominal: 630 kg\/800 kg\/1000 kg<\/li>\n<li>Altura de trabajo: 30-200 m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Catania, Finland, Johor etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platforms Electric Welding Machine in Catania, Suspended Platform Manufacturers<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale210.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Economic adjustable aluminum suspended working platform prices<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:adjustable aluminum suspended working platform prices<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Quetta, Yemen etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: 4 In 1 Work Platform in Finland, Mature-Tech Temporary Working Platform in Johor<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale180.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Provide oem maintainence suspended working platform supplier<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:maintainence suspended working platform supplier<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bhopal, Lebanon, Quito, Catania etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Durable Suspended Platforms in Quetta, Economical Work Platform Lift in Yemen<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale67.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Safety building cradle hoisting scaffolding zlp facade suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Capacidad de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: acero galvanizado\/aluminio<\/li>\n<li>Tratamiento de superficie: galvanizado; HDG o pulverizaci\u00f3n de pl\u00e1stico<\/li>\n<li>Longitud de la plataforma: 2 m-12 m; OEM<\/li>\n<li>Potencia del motor el\u00e9ctrico: 1,5 KW*2; 1,8 KW*2; 2,2 KW*2; 3,0 KW*2<\/li>\n<li>Voltaje: 380 V\/50 Hz\/trif\u00e1sico 220 V\/50 Hz\/monof\u00e1sico<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 200 m<\/li>\n<li>Color: azul, naranja, rojo, plateado o personalizado.<\/li>\n<li>Aplicaci\u00f3n: Construcci\u00f3n de edificios, pintura, limpieza de ventanas.<\/li>\n<li>Certificaci\u00f3n: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Monterrey, Syria, Quito, Bhopal etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Manufacturers, Economical Work Platform Lift in Yemen<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale71.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Plataforma de trabajo el\u00e9ctrica ZLP630 Plataforma de suspensi\u00f3n de cuna Plataforma suspendida<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca: JH<\/li>\n<li>N\u00famero de modelo: JH-ZLP-132<\/li>\n<li>Mecanismo de elevaci\u00f3n: cremallera y pi\u00f1\u00f3n<\/li>\n<li>Accionamiento\/actuaci\u00f3n del ascensor: motor el\u00e9ctrico<\/li>\n<li>Potencia: 50 Hz<\/li>\n<li>Capacidad de carga nominal: 250-1000 kg<\/li>\n<li>Altura m\u00ednima de elevaci\u00f3n: 100 m<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 150 m<\/li>\n<li>Tama\u00f1o de la mesa: 1+2+3m \/ 3*2,5m<\/li>\n<li>Dimensiones generales: 6 m \/ 7 m<\/li>\n<li>Peso: 1000 kg<\/li>\n<li>Certificaci\u00f3n: CE, GOST e ISO<\/li>\n<li>Garant\u00eda: un a\u00f1o<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Plataforma suspendida: Plataforma de trabajo el\u00e9ctrica ZLP Plataforma suspendida Plataforma suspendida<\/li>\n<li>Color: rojo o seg\u00fan las necesidades del cliente.<\/li>\n<li>Potencia: 220 V o 380 V, etc.<\/li>\n<li>Material: aleaci\u00f3n A o acero.<\/li>\n<li>Sitio web: www.bjSuccess.com<\/li>\n<li>N\u00famero de modelo: Plataforma suspendida serie ZLP<\/li>\n<li>Longitud de la plataforma: 1-7,5 m<\/li>\n<li>Mercados principales: Australia, Sur de Asia, Este, Brasil, Sud\u00e1frica y Emiratos \u00c1rabes Unidos<\/li>\n<li>Carga nominal: 630 kg\/800 kg\/1000 kg<\/li>\n<li>Altura de trabajo: 30-200 m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Catania, Johor, Yemen, Lebanon etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platforms Electric Welding Machine in Catania, Durable Suspended Platforms in Quetta<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of ZPL Electric Hoist Powered Gondola bmu With High Quality Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP Product name:suspended electric <\/p>","protected":false},"author":1,"featured_media":47,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[13377,13379,13380,13378,2632,13376],"class_list":["post-3061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-4-in-1-work-platform-in-finland","tag-durable-suspended-platforms-in-quetta","tag-economical-work-platform-lift-in-yemen","tag-mature-tech-temporary-working-platform-in-johor","tag-suspended-platform-manufacturers","tag-suspended-platforms-electric-welding-machine-in-catania"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/3061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=3061"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/3061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/47"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=3061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=3061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=3061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}