{"id":2979,"date":"2017-06-04T09:16:34","date_gmt":"2017-06-04T09:16:34","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/construction-platform-zlp800-building-decoration-gondola.html"},"modified":"2017-06-04T09:16:34","modified_gmt":"2017-06-04T09:16:34","slug":"construction-platform-zlp800-building-decoration-gondola","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/construction-platform-zlp800-building-decoration-gondola.html","title":{"rendered":"Construction platform ZLP800 building decoration gondola"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale259.jpg\" alt=\"Construction platform ZLP800 building decoration gondola\" \/><br \/>\nImage of Construction platform ZLP800 building decoration gondola<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP800<\/li>\n<li>ZLP-800 Construction platform:Quality Certification:CE, GOST, ISO<\/li>\n<li>Hoist Voltage;:380V\/50HZ (can adjust for your condition)<\/li>\n<li>Lifting Speed::8~10m\/min<\/li>\n<li>Cable::3*2.5+2*1.5<\/li>\n<li>Hoist Power::1.8KW*2<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pSGV1Q0F6ZGMxOTg\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale268.jpg\" alt=\"Construction platform ZLP800 building decoration gondola\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale130.jpg\" alt=\"Construction platform ZLP800 building decoration gondola\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale95.jpg\" alt=\"Construction platform ZLP800 building decoration gondola Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale86.jpg\" alt=\"Construction platform ZLP800 building decoration gondola Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale252.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">6m Length, 630kg Capacity ZLP630 Cradle\/ Gondola Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca: Success-CHINA<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>Steel Rope Diamerter:8.3mm<\/li>\n<li>Certificados: ISO, GOST, CE<\/li>\n<li>Rated Power:1.5KW X 2<\/li>\n<li>Voltage:380V or according to  customer need<\/li>\n<li>Counterweight:1000KG<\/li>\n<li>20&#39;ft container:9 sets<\/li>\n<li>Usage:working plarform<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ankara, Iceland, Kinshasa etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Galvanized Suspended Platform in Ankara, Lifting Working Platform Suspended<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale220.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Easy To Move gondola construction machinery<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:gondola construction machinery<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Pekanbaru, Yemen etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp Series Suspend Platforms in Iceland, Suspension Platform in Kinshasa<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale75.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">MODEL ZLP Aluminum Alloy Suspended Platform|Cradle|Gondola MANUFACTURER<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:ZLP150<\/li>\n<li>Material: acero, aleaci\u00f3n de aluminio<\/li>\n<li>Color: rojo, amarillo, azul, etc.<\/li>\n<li>Surface treatment:Powder coating, Hot galvanization<\/li>\n<li>Longitud: 2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Lifing Mechanism:Gear<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Power:1.5kw, 1.8kw, 2kw<\/li>\n<li>Rated Loading Capacity:150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 200 m<\/li>\n<li>Voltage:Cradle|Gondola MANUFACTURER accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Agra, Minsk, Norway, Ankara etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hanging Scaffolding in Pekanbaru, Steel Work Platform in Yemen<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale133.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Shanghai (ce\/gost) zlp 630 temporary suspended platform\/work platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:(ce\/gost) zlp 630 temporary suspended platform\/work platform<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Naucalpan, Blantyre, Norway, Agra etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Lifting Working Platform Suspended, Steel Work Platform in Yemen<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale154.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP800 Window Facade Cleaning Suspended Scaffolds,Gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Name:Suspended Rope Platform OR Working Platform<\/li>\n<li>Cradle Platform Application:Building maintainence, cleaning,painting<\/li>\n<li>Roof Fixing:1,suspension with counter 2, parapet clamp<\/li>\n<li>Platform Color:Red,Silver,Hot Galvanized<\/li>\n<li>Safety device:safety lock, safe rope etc<\/li>\n<li>Motive Power:Electric Hoist<\/li>\n<li>Platform Shape:cuboid or special design<\/li>\n<li>Platform standard: CE, GOST, ISO<\/li>\n<li>Platform Material:Steel or Aluminum Alloy<\/li>\n<li>Platform Body:free assembled by modular plate<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ankara, Kinshasa, Yemen, Minsk etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Galvanized Suspended Platform in Ankara, Hanging Scaffolding in Pekanbaru<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Construction platform ZLP800 building decoration gondola Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP800 ZLP-800 Construction platform:Quality Certification:CE, GOST, ISO <\/p>","protected":false},"author":1,"featured_media":211,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[12969,12972,6277,12973,12971,12970],"class_list":["post-2979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-galvanized-suspended-platform-in-ankara","tag-hanging-scaffolding-in-pekanbaru","tag-lifting-working-platform-suspended","tag-steel-work-platform-in-yemen","tag-suspension-platform-in-kinshasa","tag-zlp-series-suspend-platforms-in-iceland"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=2979"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/211"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=2979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=2979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=2979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}