{"id":2855,"date":"2017-06-01T11:30:04","date_gmt":"2017-06-01T11:30:04","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/construction-platform-zlp630-windows-cleaning-machine.html"},"modified":"2017-06-01T11:30:04","modified_gmt":"2017-06-01T11:30:04","slug":"construction-platform-zlp630-windows-cleaning-machine","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/construction-platform-zlp630-windows-cleaning-machine.html","title":{"rendered":"Construction platform ZLP630 windows cleaning machine"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale113.jpg\" alt=\"Construction platform ZLP630 windows cleaning machine\" \/><br \/>\nImage of Construction platform ZLP630 windows cleaning machine<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca: FTH<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>ZLP-630 Construction platform:Quality:CE, GOST, ISO<\/li>\n<li>Equiped with Safety Steel Ropes:Voltage:380V\/50HZ (Adjustable)<\/li>\n<li>Working height: 100m:length of platform:6m (can adjust for ruquire)<\/li>\n<li>Lifting speed:8~10m\/min:Color: Silvery\/Red<\/li>\n<li>Product name:Construction platform ZLP630 windows cleaning machine<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pRmJmeDd5SzFNaFU\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale191.jpg\" alt=\"Construction platform ZLP630 windows cleaning machine\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale229.jpg\" alt=\"Construction platform ZLP630 windows cleaning machine\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale36.jpg\" alt=\"Construction platform ZLP630 windows cleaning machine Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale16.jpg\" alt=\"Construction platform ZLP630 windows cleaning machine Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale139.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Approved CE ISO hanging scaffolds,suspended working platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP800<\/li>\n<li>Lift Mechanism:steel wire rope<\/li>\n<li>Lift Drive \/ Actuation:Hoist<\/li>\n<li>Power:1.5kw*2<\/li>\n<li>Rated Loading Capacity:800kg<\/li>\n<li>Min. Lifting Height:10m<\/li>\n<li>Max. Lifting Height:100m<\/li>\n<li>Table Size:6(1+2+3)*0.72*1.3m,7.5(2.5*3)*0.72*1.3m<\/li>\n<li>Overall Dimensions:1850mm*1000mm*950mm<\/li>\n<li>Weight:850kg<\/li>\n<li>Certification:CE ISO<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Application:clean walls decorat maintain<\/li>\n<li>Name:Suspended platform<\/li>\n<li>Altura de elevaci\u00f3n: 100 m<\/li>\n<li>Velocidad de elevaci\u00f3n: 8~10 m\/min<\/li>\n<li>cable:100m<\/li>\n<li>Voltage:220v\/380v\/50hz<\/li>\n<li>Color:Red sliver<\/li>\n<li>Material:Steel Aluminum Galvanizing<\/li>\n<li>Keywords:cradle<\/li>\n<li>Feature:Easy Operation safety convenience<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Chile, Hyderabad, Luanda etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mature-Tech Powered Access Platforms in Chile, Scaffold Platform For Construction<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale141.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Electric suspended platform\/ cradle\/ gondola for high-rise building cleaning<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:HJ-SUP-808<\/li>\n<li>Capacidad de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: acero galvanizado\/aluminio<\/li>\n<li>Tratamiento de superficie: galvanizado; HDG o pulverizaci\u00f3n de pl\u00e1stico<\/li>\n<li>Longitud de la plataforma: 2 m-12 m; OEM<\/li>\n<li>Potencia del motor el\u00e9ctrico: 1,5 KW*2; 1,8 KW*2; 2,2 KW*2; 3,0 KW*2<\/li>\n<li>Voltaje: 380 V\/50 Hz\/trif\u00e1sico 220 V\/50 Hz\/monof\u00e1sico<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 200 m<\/li>\n<li>Color: azul, naranja, rojo, plateado o personalizado.<\/li>\n<li>Aplicaci\u00f3n: Construcci\u00f3n de edificios, pintura, limpieza de ventanas.<\/li>\n<li>Certificaci\u00f3n: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Rio de Janeiro, UAE etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Ltd Series Suspended Platform Hoist in Hyderabad, Zlp-630 Suspended Platforms in Luanda<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale45.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Parts LTD Hoist 800kg For Suspended Platform,Working platform,Cradle<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condici\u00f3n:Nuevo<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:LTD8.O<\/li>\n<li>Rated Loading Capacity(kg):800Kg<\/li>\n<li>Hoisting Speed:9.0m\/min<\/li>\n<li>Loder Weight:800kg<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Power:1.8kw<\/li>\n<li>Voltage:380V<\/li>\n<li>Rotational speed:1420r\/min<\/li>\n<li>Fequency:50Hz<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Haiti, Bucharest, Mauritania, Chile etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminum Lift Suspended Work Platform in Rio de Janeiro, Mature-Tech Zlp500 Suspended Working Platforms in UAE<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale102.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Safety Lock of suspended work platforms<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:Success-Success<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Product:Suspended Working Platform<\/li>\n<li>Rated load:500kg  630kg  800kg 1000kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Platform Size(Lwh):6000(1+2+3m)*720*1300<\/li>\n<li>Power:1.5KW*2, 1.8KW*2<\/li>\n<li>Voltage:110V,220V,240V,400V,415V,440V are available<\/li>\n<li>Certification:CE, ISO,GOST<\/li>\n<li>Counterweight:1000kg<\/li>\n<li>Material:Alloy Steel\/Hot dipping\/steel<\/li>\n<li>Warranty:12 Months<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Kuala Lumpur, Harare, Mauritania, Haiti etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Scaffold Platform For Construction, Mature-Tech Zlp500 Suspended Working Platforms in UAE<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale25.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">zlp 500 suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:ZLP-500 suspended platform<\/li>\n<li>keywords:suspended platform zlp500<\/li>\n<li>material:aluminum\/steel\/galvanized<\/li>\n<li>Voltage:220v\/380v\/480v<\/li>\n<li>frequency:50Hz\/60Hz<\/li>\n<li>Electric cable:100m<\/li>\n<li>wire rope:8.6mm<\/li>\n<li>lifting height:100m<\/li>\n<li>Certificates:CE, ISO, GOST<\/li>\n<li>how many year exported:more than 8 years<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Chile, Luanda, UAE, Bucharest etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mature-Tech Powered Access Platforms in Chile, Aluminum Lift Suspended Work Platform in Rio de Janeiro<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Construction platform ZLP630 windows cleaning machine Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:FTH Model Number:ZLP630 ZLP-630 Construction platform:Quality:CE, GOST, ISO Equiped <\/p>","protected":false},"author":1,"featured_media":157,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[12354,12352,12351,12355,12350,12353],"class_list":["post-2855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aluminum-lift-suspended-work-platform-in-rio-de-janeiro","tag-ltd-series-suspended-platform-hoist-in-hyderabad","tag-mature-tech-powered-access-platforms-in-chile","tag-mature-tech-zlp500-suspended-working-platforms-in-uae","tag-scaffold-platform-for-construction","tag-zlp-630-suspended-platforms-in-luanda"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=2855"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/157"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=2855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=2855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=2855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}