{"id":2808,"date":"2017-06-01T22:40:56","date_gmt":"2017-06-01T22:40:56","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/work-platform-lifts-hanging-platform-powered-by-1-8kw.html"},"modified":"2017-06-01T22:40:56","modified_gmt":"2017-06-01T22:40:56","slug":"work-platform-lifts-hanging-platform-powered-by-1-8kw","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/work-platform-lifts-hanging-platform-powered-by-1-8kw.html","title":{"rendered":"Work Platform Lifts Hanging Platform Powered by 1.8KW"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale257.jpg\" alt=\"Work Platform Lifts Hanging Platform Powered by 1.8KW\" \/><br \/>\nImage of Work Platform Lifts Hanging Platform Powered by 1.8KW<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:JH-Success<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Product:Low Price Suspended Platform Success for Sales<\/li>\n<li>Rated load:500kg  630kg  800kg 1000kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Platform Size(Lwh):6000(1+2+3m)*720*1300<\/li>\n<li>Power:1.5KW*2, 1.8KW*2<\/li>\n<li>Voltage:110V,220V,240V,400V,415V,440V are available<\/li>\n<li>Certification:CE, ISO,GOST<\/li>\n<li>Counterweight:1000kg<\/li>\n<li>Material:Alloy Steel\/Hot dipping\/steel<\/li>\n<li>Warranty:12 Months<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pY2p0aEh4bnZCTzg\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale249.jpg\" alt=\"Work Platform Lifts Hanging Platform Powered by 1.8KW\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale185.jpg\" alt=\"Work Platform Lifts Hanging Platform Powered by 1.8KW\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale70.jpg\" alt=\"Work Platform Lifts Hanging Platform Powered by 1.8KW Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale79.jpg\" alt=\"Work Platform Lifts Hanging Platform Powered by 1.8KW Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale153.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">CE Passed ZLP Series Lift Scaffolding\/ Suspended Platform\/ Cradle\/ Gondola\/ Electric Scaffolding<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:ZLP150<\/li>\n<li>Material: acero, aleaci\u00f3n de aluminio<\/li>\n<li>Color: rojo, amarillo, azul, etc.<\/li>\n<li>Surface treatment:Powder coating, Hot galvanization<\/li>\n<li>Longitud: 2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Lifing Mechanism:Gear<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Power:1.5kw, 1.8kw, 2kw<\/li>\n<li>Rated Loading Capacity:150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 200 m<\/li>\n<li>Voltage:Lift Scaffolding\/ Suspended Platform accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Agra, Georgia, Makassar etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Portable Lift Platform in Agra, Articulated Suspended Working Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale93.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction platform ZLP630 chimney cleaning<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP800<\/li>\n<li>ZLP-630 Construction platform:Quality Certification:CE, GOST, ISO<\/li>\n<li>Hoist Voltage;:380V\/50HZ (can adjust for your condition)<\/li>\n<li>Lifting Speed::8~10m\/min<\/li>\n<li>Cable::3*2.5+2*1.5<\/li>\n<li>Hoist Power::1.5KW*2<\/li>\n<li>Lifting Height::100m<\/li>\n<li>Platform Dimension::6.0*0.72*1.3m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Mozambique, Yekaterinburg etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Work Suspended Platform in Georgia, New Self Propelled Suspended Platform in Makassar<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale44.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">high quality electric power LTD 630kg lift hoist for suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condici\u00f3n:Nuevo<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:LTD6.3<\/li>\n<li>Usage:Construction Hoist<\/li>\n<li>Power Source:Electric<\/li>\n<li>Sling Type:Wire Rope<\/li>\n<li>Maximum Lifting Weight:800kg<\/li>\n<li>Maximum Lifting Height:100m<\/li>\n<li>Lift Speed:9.0m\/min<\/li>\n<li>Certification:ISO CE<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<li>After-sales Service Provided:No overseas service provided<\/li>\n<li>Voltage:380v(requirement)<\/li>\n<li>Power:1.8kw<\/li>\n<li>Rotation speed:1420 r\/min<\/li>\n<li>Braking moment:15Nm<\/li>\n<li>Frequency:50 HZ<\/li>\n<li>Size:35cm*30cm*62cm<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bhopal, Rome, Brescia, Agra etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Window Cleaning in Mozambique, Electric Control Box Of Suspended Platform in Yekaterinburg<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale183.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Success brand zlp 630 Window Cleaning Gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:JH-Success<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>Nombre: plataforma suspendida<\/li>\n<li>Surface treatment:Paint Spraying<\/li>\n<li>Load capacity:630kg<\/li>\n<li>Height:100m<\/li>\n<li>Speed:8~10m\/min<\/li>\n<li>Hoist:1.5kw x2<\/li>\n<li>Galvanized steel wir rope:8.3mm<\/li>\n<li>Safe lock:Anti-title<\/li>\n<li>Suspension Mechanism:out reach 1.3-1.7m<\/li>\n<li>Counter weight:1000kgs<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ju\u00e1rez, Cape Town, Brescia, Bhopal etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Articulated Suspended Working Platform, Electric Control Box Of Suspended Platform in Yekaterinburg<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale139.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP400 power lifting 2m-12m electric suspended platform cradle<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:HJ-SUP-712<\/li>\n<li>Capacidad de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: acero galvanizado\/aluminio<\/li>\n<li>Tratamiento de superficie: galvanizado; HDG o pulverizaci\u00f3n de pl\u00e1stico<\/li>\n<li>Longitud de la plataforma: 2 m-12 m; OEM<\/li>\n<li>Potencia del motor el\u00e9ctrico: 1,5 KW*2; 1,8 KW*2; 2,2 KW*2; 3,0 KW*2<\/li>\n<li>Voltaje: 380 V\/50 Hz\/trif\u00e1sico 220 V\/50 Hz\/monof\u00e1sico<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 200 m<\/li>\n<li>Color: azul, naranja, rojo, plateado o personalizado.<\/li>\n<li>Aplicaci\u00f3n: Construcci\u00f3n de edificios, pintura, limpieza de ventanas.<\/li>\n<li>Certificaci\u00f3n: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Agra, Makassar, Yekaterinburg, Rome etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Portable Lift Platform in Agra, Suspended Platform Window Cleaning in Mozambique<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Work Platform Lifts Hanging Platform Powered by 1.8KW Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:JH-Success Model Number:ZLP500\/630\/800\/1000 Product:Low Price Suspended Platform <\/p>","protected":false},"author":1,"featured_media":233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[4175,12137,12135,12133,12136,12134],"class_list":["post-2808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-articulated-suspended-working-platform","tag-electric-control-box-of-suspended-platform-in-yekaterinburg","tag-new-self-propelled-suspended-platform-in-makassar","tag-portable-lift-platform-in-agra","tag-suspended-platform-window-cleaning-in-mozambique","tag-work-suspended-platform-in-georgia"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=2808"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/233"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=2808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=2808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=2808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}