{"id":2720,"date":"2017-06-01T09:27:02","date_gmt":"2017-06-01T09:27:02","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/jack-to-lift-appliancesleader-gn50-aluminum-suspended-working-platformmachine-cleaning-glass-towers.html"},"modified":"2017-06-01T09:27:02","modified_gmt":"2017-06-01T09:27:02","slug":"jack-to-lift-appliancesleader-gn50-aluminum-suspended-working-platformmachine-cleaning-glass-towers","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/jack-to-lift-appliancesleader-gn50-aluminum-suspended-working-platformmachine-cleaning-glass-towers.html","title":{"rendered":"Jack to lift appliances\/LEADER GN50 aluminum suspended working platform\/Machine cleaning glass towers"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale120.jpg\" alt=\"Jack to lift appliances\/LEADER GN50 aluminum suspended working platform\/Machine cleaning glass towers\" \/><br \/>\nImage of Jack to lift appliances\/LEADER GN50 aluminum suspended working platform\/Machine cleaning glass towers<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Condici\u00f3n:Nuevo<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:Jiu Hong<\/li>\n<li>N\u00famero de modelo: ZLP<\/li>\n<li>Capacidad de carga nominal (kg): 630 kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 300 m<\/li>\n<li>Forma de la plataforma: forma larga, abanico, c\u00edrculo, forma de U\u2026<\/li>\n<li>Material de la plataforma: acero o aleaci\u00f3n A<\/li>\n<li>Capacidad: desde 250 kg hasta 1000 kg<\/li>\n<li>Carga nominal: 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Longitud de la plataforma: 1 m - 7,5 m<\/li>\n<li>Buena calidad: certificado CE, Gost e ISO aprobado.<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pX3lRLXZIcmE5dUU\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale92.jpg\" alt=\"Jack to lift appliances\/LEADER GN50 aluminum suspended working platform\/Machine cleaning glass towers\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale141.jpg\" alt=\"Jack to lift appliances\/LEADER GN50 aluminum suspended working platform\/Machine cleaning glass towers\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale27.jpg\" alt=\"Jack to lift appliances\/LEADER GN50 aluminum suspended working platform\/Machine cleaning glass towers Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale17.jpg\" alt=\"Jack to lift appliances\/LEADER GN50 aluminum suspended working platform\/Machine cleaning glass towers Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale105.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">CE Marked Suspended Platform (ZLP Rope Suspended Platform)<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP800<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Material: acero, aleaci\u00f3n de aluminio<\/li>\n<li>Color: rojo, amarillo, azul, etc.<\/li>\n<li>Surface treatment:Powder coating, Hot galvanization<\/li>\n<li>Longitud: 2m, 2,5m, 3m, 5m, 6m, 7,5m, etc.<\/li>\n<li>Lifing Mechanism:Gear<\/li>\n<li>Lift Drive\/Actuation:Electric Motor<\/li>\n<li>Power:1.5kw, 1.8kw, 2kw<\/li>\n<li>Rated Loading Capacity:150kg, 250kg, 500kg, 630kg, 800kg, 1000kg<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 200 m<\/li>\n<li>Voltage:Suspended Platform (Rope Suspended Platform) accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Amman, Colombia, Kharkiv etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp800 Steel Rope Suspended Platform in Amman, Mode Electric Hoist For Suspended Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale22.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction 2017 new price high quality Aerial Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP800<\/li>\n<li>Lift Mechanism:ltd63<\/li>\n<li>Lift Drive \/ Actuation:Other<\/li>\n<li>Rated Loading Capacity:800kg<\/li>\n<li>Max. Lifting Height:100m<\/li>\n<li>Overall Dimensions:6*0.69m<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Safety lock:anti-tilted<\/li>\n<li>wire rope:4*31w+NF-8.3<\/li>\n<li>Heavy hammer:10kg per pieces<\/li>\n<li>Concrete counter-weight:25kg\/piece<\/li>\n<li>Condition:100% New<\/li>\n<li>Power Supply:380V\/50Hz<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Russia, Zamboanga etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Motor Lifting Suspended Platform in Colombia, Platform Lifts in Kharkiv<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale88.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">OEM Manufacturer Supply Electric Suspended Scaffolding Work Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:HJ-SUP194<\/li>\n<li>Product name:OEM Manufacturer Supply Electric Suspended Scaffolding Work Platform<\/li>\n<li>Surface Protection: Painting and Galvanize<\/li>\n<li>Keywords:zlp series suspend platforms<\/li>\n<li>Color: Red , Yellow , Other<\/li>\n<li>Certification: ISO , CE , GOST proved<\/li>\n<li>Type:construction platforms<\/li>\n<li>Certificate:ISO , CE , GOST proved<\/li>\n<li>Market:global, over 30contries<\/li>\n<li>Item:suspend platforms<\/li>\n<li>place of origin:Shanghai, China (Mainland)<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Varanasi, Barcelona, C\u00f3rdoba, Amman etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Arc-Shaped Building Suspended Platform in Russia, Zlp1000 Suspended Working Platform in Zamboanga<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale58.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Special suspended platform ,Suspended platform, Single Person Work Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>Lift Mechanism:steel wire rope<\/li>\n<li>Lift Drive \/ Actuation:Hoist<\/li>\n<li>Power:1.5kw*2<\/li>\n<li>Rated Loading Capacity:630kg<\/li>\n<li>Min. Lifting Height:10m<\/li>\n<li>Max. Lifting Height:100m<\/li>\n<li>Table Size:6(1+2+3)*0.72*1.3m,7.5(2.5*3)*0.72*1.3m<\/li>\n<li>Overall Dimensions:1850mm*1000mm*950mm<\/li>\n<li>Weight:850kg<\/li>\n<li>Certification:CE ISO<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Application:clean walls decorat maintain<\/li>\n<li>Name:Suspended platform<\/li>\n<li>Altura de elevaci\u00f3n: 100 m<\/li>\n<li>Velocidad de elevaci\u00f3n: 8~10 m\/min<\/li>\n<li>cable:100m<\/li>\n<li>Voltage:220v\/380v\/50hz<\/li>\n<li>Color:Red sliver<\/li>\n<li>Material:Steel Aluminum<\/li>\n<li>Keywords:cradle<\/li>\n<li>Feature:Easy Operation safety convenience<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Puebla, Turkmenistan, C\u00f3rdoba, Varanasi etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mode Electric Hoist For Suspended Platform, Zlp1000 Suspended Working Platform in Zamboanga<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale123.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Working Platform For Building Maintenance Units(BMU)<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:Success, Success<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>Material:Steel<\/li>\n<li>Type:ZLP630<\/li>\n<li>Platform Length:6m<\/li>\n<li>Rated Load(kg):630kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Useage:Working Platform For Building Maintenance Units<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Amman, Kharkiv, Zamboanga, Barcelona etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp800 Steel Rope Suspended Platform in Amman, Arc-Shaped Building Suspended Platform in Russia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Jack to lift appliances\/LEADER GN50 aluminum suspended working platform\/Machine cleaning glass towers Quick Details: Condition:New Place of Origin:Shanghai, China (Mainland) Brand Name:Jiu Hong <\/p>","protected":false},"author":1,"featured_media":163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11688,4996,11686,11687,11689,11685],"class_list":["post-2720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-arc-shaped-building-suspended-platform-in-russia","tag-mode-electric-hoist-for-suspended-platform","tag-motor-lifting-suspended-platform-in-colombia","tag-platform-lifts-in-kharkiv","tag-zlp1000-suspended-working-platform-in-zamboanga","tag-zlp800-steel-rope-suspended-platform-in-amman"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=2720"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/163"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=2720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=2720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=2720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}