{"id":2537,"date":"2017-05-31T04:07:56","date_gmt":"2017-05-31T04:07:56","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/temporary-suspended-access-platforms-weight-500kg.html"},"modified":"2017-05-31T04:07:56","modified_gmt":"2017-05-31T04:07:56","slug":"temporary-suspended-access-platforms-weight-500kg","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/temporary-suspended-access-platforms-weight-500kg.html","title":{"rendered":"Temporary Suspended Access Platforms weight 500kg"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale193.jpg\" alt=\"Temporary Suspended Access Platforms weight 500kg\" \/><br \/>\nImage of Temporary Suspended Access Platforms weight 500kg<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:Success-Success<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Product:Temporary Suspended Access Platforms weight 500kg<\/li>\n<li>Rated load:500kg  630kg  800kg 1000kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Platform Size(Lwh):6000(1+2+3m)*720*1300<\/li>\n<li>Power:1.5KW*2, 1.8KW*2<\/li>\n<li>Voltage:110V,220V,240V,400V,415V,440V are available<\/li>\n<li>Certification:CE, ISO,GOST<\/li>\n<li>Counterweight:1000kg<\/li>\n<li>Material:Alloy Steel\/Hot dipping\/steel<\/li>\n<li>Warranty:12 Months<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pRUtxc3FBTWFZQkU\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale232.jpg\" alt=\"Temporary Suspended Access Platforms weight 500kg\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale9.jpg\" alt=\"Temporary Suspended Access Platforms weight 500kg\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale102.jpg\" alt=\"Temporary Suspended Access Platforms weight 500kg Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale71.jpg\" alt=\"Temporary Suspended Access Platforms weight 500kg Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale172.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">800KG-1000KG electric suspended scaffold\/suspended platform\/cradle\/gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>color:red and  silver gray<\/li>\n<li>shape:Customize according to customer requirements<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bahrain, Indonesia, Malta etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Walking Platform in Bahrain, Gondola Scaffold<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale106.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction building lifting suspended platform, powered sky scaffolding<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Capacidad de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: acero galvanizado\/aluminio<\/li>\n<li>Tratamiento de superficie: galvanizado; HDG o pulverizaci\u00f3n de pl\u00e1stico<\/li>\n<li>Longitud de la plataforma: 2 m-12 m; OEM<\/li>\n<li>Potencia del motor el\u00e9ctrico: 1,5 KW*2; 1,8 KW*2; 2,2 KW*2; 3,0 KW*2<\/li>\n<li>Voltaje: 380 V\/50 Hz\/trif\u00e1sico 220 V\/50 Hz\/monof\u00e1sico<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 200 m<\/li>\n<li>Color: azul, naranja, rojo, plateado o personalizado.<\/li>\n<li>Aplicaci\u00f3n: Construcci\u00f3n de edificios, pintura, limpieza de ventanas.<\/li>\n<li>Certificaci\u00f3n: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Nagpur, Senegal etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Platform Access in Indonesia, Wire Rope Platform in Malta<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale246.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Low Cost zlp 630kg-800kg electric suspended scaffold\/suspended platform\/cradle\/gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:suspended platform cradle gondola sky climber scaffold<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Kalyan-Dombivali, Charleroi, Mali, Bahrain etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Working Platform Gondola in Nagpur, Suspended Scaffolding Work Platform in Senegal<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale208.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Rope Suspended Platform Window Cleaning Gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:HJ-SUP333<\/li>\n<li>Product name:Rope Suspended Platform Window Cleaning Gondola<\/li>\n<li>Surface Protection: Painting and Galvanize<\/li>\n<li>Color: Red , Yellow , Other<\/li>\n<li>Certification: ISO , CE , GOST proved<\/li>\n<li>Market: Global ,over 30contries<\/li>\n<li>Warranty period:1 year<\/li>\n<li>speed: 9.6m\/min<\/li>\n<li>capacity: 630kg<\/li>\n<li>the length of paltform:6m<\/li>\n<li>lifting height: 100m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Panama, Accra, Mali, Kalyan-Dombivali etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Gondola Scaffold, Suspended Scaffolding Work Platform in Senegal<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale221.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP500 Electric Construction\/ Building\/ external wall Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Carga nominal: 500 kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8~10 m\/min<\/li>\n<li>Altura de elevaci\u00f3n: 100 m<\/li>\n<li>Cable: 100 m<\/li>\n<li>Contrapeso: 500 kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bahrain, Malta, Senegal, Charleroi etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Walking Platform in Bahrain, Suspended Working Platform Gondola in Nagpur<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Temporary Suspended Access Platforms weight 500kg Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success-Success Model Number:ZLP500\/630\/800\/1000 Product:Temporary Suspended Access Platforms weight 500kg <\/p>","protected":false},"author":1,"featured_media":133,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[4540,10781,10784,10783,10780,10782],"class_list":["post-2537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-gondola-scaffold","tag-platform-access-in-indonesia","tag-suspended-scaffolding-work-platform-in-senegal","tag-suspended-working-platform-gondola-in-nagpur","tag-walking-platform-in-bahrain","tag-wire-rope-platform-in-malta"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=2537"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/133"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=2537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=2537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=2537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}