{"id":2153,"date":"2017-05-25T09:48:05","date_gmt":"2017-05-25T09:48:05","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/ce-passed-zlp-series-mast-climbersuspended-platformelectric-scaffolding.html"},"modified":"2017-05-25T09:48:05","modified_gmt":"2017-05-25T09:48:05","slug":"ce-passed-zlp-series-mast-climbersuspended-platformelectric-scaffolding","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/ce-passed-zlp-series-mast-climbersuspended-platformelectric-scaffolding.html","title":{"rendered":"CE passed ZLP Series mast climber\/Suspended platform\/Electric scaffolding"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale39.jpg\" alt=\"CE passed ZLP Series mast climber\/Suspended platform\/Electric scaffolding\" \/><br \/>\nImage of CE passed ZLP Series mast climber\/Suspended platform\/Electric scaffolding<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Condici\u00f3n:Nuevo<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca: FTH<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>Rated Loading Capacity(kg):630<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Max Lifting Height:100<\/li>\n<li>Dimension(L*W*H):6000*720*1300mm<\/li>\n<li>Loder Weight:630kg<\/li>\n<li>After-sales Service Provided:Overseas service center available<\/li>\n<li>Platform:corrosion-resistant<\/li>\n<li>factory:10 years manufacturing experience<\/li>\n<li>Dimension:adjustable<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pdmRDWG5jdnZWY28\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale72.jpg\" alt=\"CE passed ZLP Series mast climber\/Suspended platform\/Electric scaffolding\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale8.jpg\" alt=\"CE passed ZLP Series mast climber\/Suspended platform\/Electric scaffolding\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale97.jpg\" alt=\"CE passed ZLP Series mast climber\/Suspended platform\/Electric scaffolding Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale33.jpg\" alt=\"CE passed ZLP Series mast climber\/Suspended platform\/Electric scaffolding Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale43.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Aluminum Alloy Single Working Gondola, Window Cleaning Platform Cradle 300kg Load<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Place of Origin:China (Mainland)<\/li>\n<li>Brand Name: Window Cleaning Suspended Platform<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Name:Aluminum Alloy Single Working Gondola<\/li>\n<li>Cradle Platform Application:Building maintainence, cleaning,painting<\/li>\n<li>Roof Fixing:1,suspension with counter 2, parapet clamp<\/li>\n<li>Platform Color:Red,Silver,Hot Galvanized<\/li>\n<li>Safety device:safety lock, safe rope etc<\/li>\n<li>Motive Power:Electric Hoist<\/li>\n<li>Platform Shape:cuboid or special design<\/li>\n<li>Platform standard: CE, GOST, ISO<\/li>\n<li>Platform Material:Steel or Aluminum Alloy<\/li>\n<li>Platform Body:free assembled by modular plate<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Abu Dhabi, Estonia, Khartoum etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Boom Lift Work Platform in Abu Dhabi, Mature-Tech Aerial Work Platforms For Sale<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale155.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Easy To Move iso ce gost zlp 800 construction suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:iso ce gost zlp 800 construction suspended platform<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Padang, Saudi Arabia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aluminum Lift Fitting Platform in Estonia, Temporary Suspended Platform Hoist in Khartoum<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale132.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High-quality electric gondola with wheel<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:JINFEI TIANHONG<\/li>\n<li>N\u00famero de modelo: ZLP<\/li>\n<li>Nombre: plataforma suspendida<\/li>\n<li>material:steel<\/li>\n<li>certificate:CE,ISO,GOST<\/li>\n<li>lift weight:200&#8211;1000kg<\/li>\n<li>lift speed:10m\/min<\/li>\n<li>height:100m<\/li>\n<li>voltage:380v,could adjust<\/li>\n<li>length:1&#8212;12m,<\/li>\n<li>price:factory price<\/li>\n<li>factory:Shanghai,china<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Haiti, Israel, Mongolia, Abu Dhabi etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Inspection Suspended Platform in Padang, Zlp-630 Suspended Platforms in Saudi Arabia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale238.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Safe Rope Hanging Suspended Working Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>Rated Loading Capacity:630kg<\/li>\n<li>Colour:Red,Can be Customized<\/li>\n<li>Motor Power:1.5KW*2<\/li>\n<li>Platform Dimension:6000*0.72*1300<\/li>\n<li>Voltaje: 220 V\/380 V\/415 V-trif\u00e1sico\/50 Hz\/60 Hz<\/li>\n<li>Steel Rope Diamter:8.3mm<\/li>\n<li>Lifting Height:100m-120m<\/li>\n<li>Model:ZLP630 Suspended Working Platform<\/li>\n<li>Locking Cable Angel:3-8&deg;<\/li>\n<li>Overhang Length of Front Beam:1.3-1.5m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Nezahualc\u00f3yotl, Dakar, Mongolia, Haiti etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Mature-Tech Aerial Work Platforms For Sale, Zlp-630 Suspended Platforms in Saudi Arabia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale4.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP800 motorized gondola, China factory, CE\/ GOST standard<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:jinfei tianhong<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Shape:like a cradle<\/li>\n<li>Color:silver gray<\/li>\n<li>Name:motorized gondola<\/li>\n<li>Platform Material:steel or aluminum alloy<\/li>\n<li>Usage:as a safe platform for people&#39;s high rise working<\/li>\n<li>Application:building painting, cleaning, maintainence<\/li>\n<li>Platform Color:Red\/ Light grey\/ or as require<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Abu Dhabi, Khartoum, Saudi Arabia, Israel etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Boom Lift Work Platform in Abu Dhabi, Inspection Suspended Platform in Padang<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of CE passed ZLP Series mast climber\/Suspended platform\/Electric scaffolding Quick Details: Condition:New Place of Origin:Shanghai, China (Mainland) Brand Name:FTH Model Number:ZLP630 Rated Loading Capacity(kg):630 <\/p>","protected":false},"author":1,"featured_media":78,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[8943,8942,8945,7734,8944,8946],"class_list":["post-2153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aluminum-lift-fitting-platform-in-estonia","tag-boom-lift-work-platform-in-abu-dhabi","tag-inspection-suspended-platform-in-padang","tag-mature-tech-aerial-work-platforms-for-sale","tag-temporary-suspended-platform-hoist-in-khartoum","tag-zlp-630-suspended-platforms-in-saudi-arabia"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=2153"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/2153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/78"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=2153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=2153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=2153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}