{"id":1930,"date":"2017-05-24T01:05:10","date_gmt":"2017-05-24T01:05:10","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/suspended-platform-spare-parts-ltd630-hoist.html"},"modified":"2017-05-24T01:05:10","modified_gmt":"2017-05-24T01:05:10","slug":"suspended-platform-spare-parts-ltd630-hoist","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/suspended-platform-spare-parts-ltd630-hoist.html","title":{"rendered":"suspended platform spare parts LTD630 HOIST"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale70.jpg\" alt=\"suspended platform spare parts LTD630 HOIST\" \/><br \/>\nImage of suspended platform spare parts LTD630 HOIST<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:Success-Success<\/li>\n<li>Model Number:LTD630 HOIST<\/li>\n<li>Nombre: plataforma suspendida<\/li>\n<li>Surface treatment:Paint Spraying<\/li>\n<li>Load capacity:630kg<\/li>\n<li>Height:100m<\/li>\n<li>Speed:8~10m\/min<\/li>\n<li>Hoist:1.5kw x2<\/li>\n<li>Galvanized steel wir rope:8.3mm<\/li>\n<li>Safe lock:Anti-title<\/li>\n<li>Suspension Mechanism:out reach 1.3-1.7m<\/li>\n<li>Counter weight:1000kgs<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pUHhwSHJhbDd1MUU\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale131.jpg\" alt=\"suspended platform spare parts LTD630 HOIST\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale176.jpg\" alt=\"suspended platform spare parts LTD630 HOIST\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale8.jpg\" alt=\"suspended platform spare parts LTD630 HOIST Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale64.jpg\" alt=\"suspended platform spare parts LTD630 HOIST Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale97.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">2017 China ZLP series Success brand aerial platform manufacturers<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP<\/li>\n<li>Name:Success brand aerial platform manufacturers<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bari, Istanbul, Managua etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Stanley Work Platform in Bari, Chimney Suspended Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale2.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">china window cleaning equipment with wheel<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:JINFEI TIANHONG<\/li>\n<li>N\u00famero de modelo: ZLP<\/li>\n<li>Nombre: plataforma suspendida<\/li>\n<li>material:steel<\/li>\n<li>certificate:CE,ISO,GOST<\/li>\n<li>lift weight:200&#8211;1000kg<\/li>\n<li>lift speed:10m\/min<\/li>\n<li>height:100m<\/li>\n<li>voltage:380v,could adjust<\/li>\n<li>length:1&#8212;12m,<\/li>\n<li>price:factory price<\/li>\n<li>factory:Shanghai,china<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Philadelphia, Tanzania etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Lift Platform in Istanbul, Maximum 4 In 1 Work Platform in Managua<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale192.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Parts suspended platform with Hoist\/Electric Hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condici\u00f3n:Nuevo<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:LTD8.O<\/li>\n<li>Rated Loading Capacity(kg):800Kg<\/li>\n<li>Hoisting Speed:9.0m\/min<\/li>\n<li>Loder Weight:800kg<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Power:1.8kw<\/li>\n<li>Voltage:380V<\/li>\n<li>Rotational speed:1420r\/min<\/li>\n<li>Fequency:50Hz<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Nashik, Minsk, Port-au-Prince, Bari etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Hoist Mini Electric Hoist in Philadelphia, Mobile Scissor Lift in Tanzania<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale250.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Suspended Platform ZLP630,ZLP250,ZLP500,ZLP800,ZLP1000<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:China FTH<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Calgary, Oran, Port-au-Prince, Nashik etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Chimney Suspended Platform, Mobile Scissor Lift in Tanzania<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale118.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP630\/ZLP800 Powered suspended platform\/Cradle\/Building cleaning machine<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>Lift Mechanism:steel wire rope<\/li>\n<li>Lift Drive \/ Actuation:Hoist<\/li>\n<li>Power:1.5kw*2<\/li>\n<li>Rated Loading Capacity:630kg<\/li>\n<li>Min. Lifting Height:10m<\/li>\n<li>Max. Lifting Height:100m<\/li>\n<li>Table Size:6(1+2+3)*0.72*1.3m,7.5(2.5*3)*0.72*1.3m<\/li>\n<li>Overall Dimensions:1850mm*1000mm*950mm<\/li>\n<li>Weight:850kg<\/li>\n<li>Certification:CE ISO<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Application:clean walls decorat maintain<\/li>\n<li>Name:Suspended platform<\/li>\n<li>Altura de elevaci\u00f3n: 100 m<\/li>\n<li>Velocidad de elevaci\u00f3n: 8~10 m\/min<\/li>\n<li>cable:100m<\/li>\n<li>Voltage:220v\/380v\/50hz<\/li>\n<li>Color:Red sliver<\/li>\n<li>Material:Steel Aluminum<\/li>\n<li>Keywords:cradle<\/li>\n<li>Feature:Easy Operation safety convenience<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bari, Managua, Tanzania, Minsk etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Stanley Work Platform in Bari, Suspended Platform Hoist Mini Electric Hoist in Philadelphia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of suspended platform spare parts LTD630 HOIST Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success-Success Model Number:LTD630 HOIST Name:suspended platform Surface treatment:Paint Spraying <\/p>","protected":false},"author":1,"featured_media":20,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[868,7876,7877,7879,7875,7878],"class_list":["post-1930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-chimney-suspended-platform","tag-lift-platform-in-istanbul","tag-maximum-4-in-1-work-platform-in-managua","tag-mobile-scissor-lift-in-tanzania","tag-stanley-work-platform-in-bari","tag-suspended-platform-hoist-mini-electric-hoist-in-philadelphia"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/1930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=1930"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/1930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/20"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=1930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=1930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=1930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}