{"id":1886,"date":"2017-05-24T10:36:52","date_gmt":"2017-05-24T10:36:52","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/aluminium-scaffolding-safe-zlp-suspended-platform.html"},"modified":"2017-05-24T10:36:52","modified_gmt":"2017-05-24T10:36:52","slug":"aluminium-scaffolding-safe-zlp-suspended-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/aluminium-scaffolding-safe-zlp-suspended-platform.html","title":{"rendered":"Andamio de aluminio Safe ZLP Plataforma suspendida"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale141.jpg\" alt=\"Andamio de aluminio Safe ZLP Plataforma suspendida\" \/><br \/>\nImage of Aluminium Scaffolding Safe ZLP Suspended Platform<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:Success-ZLP-119<\/li>\n<li>Mecanismo de elevaci\u00f3n: cremallera y pi\u00f1\u00f3n<\/li>\n<li>Accionamiento\/actuaci\u00f3n del ascensor: motor el\u00e9ctrico<\/li>\n<li>Potencia: 50 Hz<\/li>\n<li>Capacidad de carga nominal: 250-1000 kg<\/li>\n<li>Altura m\u00ednima de elevaci\u00f3n: 100 m<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 150 m<\/li>\n<li>Tama\u00f1o de la mesa: 1+2+3m \/ 3*2,5m<\/li>\n<li>Dimensiones generales: 6 m \/ 7 m<\/li>\n<li>Peso: 1000 kg<\/li>\n<li>Certificaci\u00f3n: CE, GOST e ISO<\/li>\n<li>Garant\u00eda: un a\u00f1o<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Suspended Platform:Aluminium Scaffolding Safe ZLP Suspended Platform<\/li>\n<li>Color: rojo o seg\u00fan las necesidades del cliente.<\/li>\n<li>Potencia: 220 V o 380 V, etc.<\/li>\n<li>Material: aleaci\u00f3n A o acero.<\/li>\n<li>Website:www.bjfth.com<\/li>\n<li>N\u00famero de modelo: Plataforma suspendida serie ZLP<\/li>\n<li>Longitud de la plataforma: 1-7,5 m<\/li>\n<li>Mercados principales: Australia, Sur de Asia, Este, Brasil, Sud\u00e1frica y Emiratos \u00c1rabes Unidos<\/li>\n<li>Carga nominal: 630 kg\/800 kg\/1000 kg<\/li>\n<li>Altura de trabajo: 30-200 m<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pa1dvZTFLNjMyUGs\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale166.jpg\" alt=\"Andamio de aluminio Safe ZLP Plataforma suspendida\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale198.jpg\" alt=\"Andamio de aluminio Safe ZLP Plataforma suspendida\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale65.jpg\" alt=\"Aluminium Scaffolding Safe ZLP Suspended Platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale66.jpg\" alt=\"Aluminium Scaffolding Safe ZLP Suspended Platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale131.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">CE passed ZLP630 Aluminum\/steel electric Gondola\/Cradle(Best quality )<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:ZLP630 ZLP800 ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name: suspended platform<\/li>\n<li>Carga nominal: 630 kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Dimension:6000(1+2+3m)*720*1300<\/li>\n<li>Lifting Height:100 m<\/li>\n<li>Power:1.5KW*2<\/li>\n<li>Voltage:380V\/50Hz<\/li>\n<li>Color:red or customer required<\/li>\n<li>20&#39;ft container:9sets<\/li>\n<li>Material:Alloy Steel hot-galvanize<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Cambodia, Finland, Lagos etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hand Pedal Suspended Gondola Platform 800 Kg in Cambodia, Scaffolding Working Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale68.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">China exterior window cleaning platform\/ suspended platform (ce\/iso standard)<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:suspended platform cradle gondola sky climber scaffold<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Penang, Tabriz etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hybrid Access Platforms in Finland, Lift Electric Suspended Scaffolding Platform in Lagos<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale27.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Hot Selling Lift Elevated Work Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:HJ-SUP061<\/li>\n<li>Product name:Hot Selling Lift Elevated Work Suspended Platform<\/li>\n<li>Surface Protection: Painting and Galvanize<\/li>\n<li>Keywords:Lift Elevated Work Suspended Platform<\/li>\n<li>Color: Red , Yellow , Other<\/li>\n<li>Certification: ISO , CE , GOST proved<\/li>\n<li>Type:construction platforms<\/li>\n<li>Certificate:ISO , CE , GOST proved<\/li>\n<li>Market:global, over 30contries<\/li>\n<li>Item:suspend platforms<\/li>\n<li>place of origin:Shanghai, China (Mainland)<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Germany, Bruges, Mozambique, Cambodia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Wire Rope Platform in Penang, Lift Window Cleaning Platform in Tabriz<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale101.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Success ZLP300 High rise construction swing stage power suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Capacidad de carga: 500 kg; 630 kg; 800 kg; 1000 kg<\/li>\n<li>Material: acero galvanizado\/aluminio<\/li>\n<li>Tratamiento de superficie: galvanizado; HDG o pulverizaci\u00f3n de pl\u00e1stico<\/li>\n<li>Longitud de la plataforma: 2 m-12 m; OEM<\/li>\n<li>Potencia del motor el\u00e9ctrico: 1,5 KW*2; 1,8 KW*2; 2,2 KW*2; 3,0 KW*2<\/li>\n<li>Voltaje: 380 V\/50 Hz\/trif\u00e1sico 220 V\/50 Hz\/monof\u00e1sico<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 200 m<\/li>\n<li>Color: azul, naranja, rojo, plateado o personalizado.<\/li>\n<li>Aplicaci\u00f3n: Construcci\u00f3n de edificios, pintura, limpieza de ventanas.<\/li>\n<li>Certificaci\u00f3n: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Houston, Benin, Mozambique, Germany etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Scaffolding Working Platform, Lift Window Cleaning Platform in Tabriz<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale118.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP series rope suspended platform with SQS CE authentication<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Product name:ZLP working platform<\/li>\n<li>Material:Aluminum Alloy or steel<\/li>\n<li>Voltage:110\/220\/380\/415 Optional<\/li>\n<li>Rated load:500\/630\/800\/1000kg<\/li>\n<li>Usage:People&#39;s High Rise Building Maintaining Work<\/li>\n<li>Type:Suspended Working Platform Equipment<\/li>\n<li>Application:Tall Building Maintenance<\/li>\n<li>Color:Black\\gray\\red or customize<\/li>\n<li>Certificate:CE ISO SQS GOST<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Cambodia, Lagos, Tabriz, Bruges etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hand Pedal Suspended Gondola Platform 800 Kg in Cambodia, Wire Rope Platform in Penang<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Imagen de la plataforma suspendida segura ZLP para andamios de aluminio. Detalles r\u00e1pidos: Lugar de origen: Shangh\u00e1i, China (Continental). Nombre de la marca: Success. N\u00famero de modelo: Success-ZLP-119. Mecanismo de elevaci\u00f3n: Accionamiento de elevaci\u00f3n de pi\u00f1\u00f3n y cremallera. <\/p>","protected":false},"author":1,"featured_media":33,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7645,7646,7647,7649,7644,7648],"class_list":["post-1886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-hand-pedal-suspended-gondola-platform-800-kg-in-cambodia","tag-hybrid-access-platforms-in-finland","tag-lift-electric-suspended-scaffolding-platform-in-lagos","tag-lift-window-cleaning-platform-in-tabriz","tag-scaffolding-working-platform","tag-wire-rope-platform-in-penang"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/1886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=1886"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/1886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/33"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=1886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=1886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=1886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}