{"id":1343,"date":"2017-05-21T11:28:19","date_gmt":"2017-05-21T11:28:19","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/hot-sale-building-cleaning-machine.html"},"modified":"2017-05-21T11:28:19","modified_gmt":"2017-05-21T11:28:19","slug":"hot-sale-building-cleaning-machine","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/hot-sale-building-cleaning-machine.html","title":{"rendered":"Hot sale building cleaning machine"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale86.jpg\" alt=\"Hot sale building cleaning machine\" \/><br \/>\nImage of Hot sale building cleaning machine<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:building cleaning machine<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pUDJaa2NSeXdBbVE\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale2.jpg\" alt=\"Hot sale building cleaning machine\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale174.jpg\" alt=\"Hot sale building cleaning machine\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale44.jpg\" alt=\"Hot sale building cleaning machine Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale48.jpg\" alt=\"Hot sale building cleaning machine Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale6.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">2017 China ZLP series Economical platform lifter<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP<\/li>\n<li>Name:Economical platform lifter<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Botswana, Djibouti, Le\u00f3n etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Window Cleaning Suspended Platform With Hoist in Botswana, Scaffold Suspend Platforms<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale252.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Easy To Move climbing and decorating suspended access platform\/swing stage zlp1000<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:climbing and decorating suspended access platform\/swing stage zlp1000<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Naypyidaw, Thailand etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Articulated Suspended Working Platform in Djibouti, Aluminum Lift Suspended Platform in Le\u00f3n<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale189.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High quality modular platform made from durable materials<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Nombre: plataforma suspendida<\/li>\n<li>Rated load:500kg  630kg  800kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Dimension:6000(1+2+3m)*720*1300<\/li>\n<li>Lifting Height:100 m<\/li>\n<li>Power:1.5KW*2<\/li>\n<li>Voltage:380V\/50Hz<\/li>\n<li>Color:Required<\/li>\n<li>20&#39;ft container:9sets<\/li>\n<li>Material:Aluminum Alloy\/hot dipping\/steel<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Indonesia, Sofia, Medell\u00edn, Botswana etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Max Load 800kg Suspended Ajustable Work Platform in Naypyidaw, Mast Working Platform in Thailand<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale99.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Southeast Asia Motorized Electric Gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:HJ-SUP023<\/li>\n<li>Product name:Southeast Asia Motorized Electric Gondola<\/li>\n<li>Surface Protection: Painting and Galvanize<\/li>\n<li>Keywords:Motorized Electric Gondola<\/li>\n<li>Color: Red , Yellow , Other<\/li>\n<li>Certification: ISO , CE , GOST proved<\/li>\n<li>Type:construction platforms<\/li>\n<li>Certificate:ISO , CE , GOST proved<\/li>\n<li>Market:global, over 30contries<\/li>\n<li>Item:suspend platforms<\/li>\n<li>place of origin:Shanghai, China (Mainland)<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Calgary, Douala, Medell\u00edn, Indonesia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Scaffold Suspend Platforms, Mast Working Platform in Thailand<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale47.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP630 Electric Scaffolding Gondola For Installation Glass Curtain Walls<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>Rated Loading Capacity:630kg<\/li>\n<li>Colour:Red,Can be Customized<\/li>\n<li>Motor Power:1.5KW*2<\/li>\n<li>Platform Dimension:6000*0.72*1300<\/li>\n<li>Voltaje: 220 V\/380 V\/415 V-trif\u00e1sico\/50 Hz\/60 Hz<\/li>\n<li>Steel Rope Diamter:8.3mm<\/li>\n<li>Lifting Height:100m-120m<\/li>\n<li>Model:ZLP630 Suspended Working Platform<\/li>\n<li>Locking Cable Angel:3-8&deg;<\/li>\n<li>Overhang Length of Front Beam:1.3-1.5m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Botswana, Le\u00f3n, Thailand, Sofia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Window Cleaning Suspended Platform With Hoist in Botswana, Max Load 800kg Suspended Ajustable Work Platform in Naypyidaw<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Hot sale building cleaning machine Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000 After-sales Service Provided:Engineers available to service machinery <\/p>","protected":false},"author":1,"featured_media":8,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5667,5666,5669,5668,5664,5665],"class_list":["post-1343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-aluminum-lift-suspended-platform-in-leon","tag-articulated-suspended-working-platform-in-djibouti","tag-mast-working-platform-in-thailand","tag-max-load-800kg-suspended-ajustable-work-platform-in-naypyidaw","tag-scaffold-suspend-platforms","tag-window-cleaning-suspended-platform-with-hoist-in-botswana"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/1343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=1343"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/1343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/8"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=1343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=1343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=1343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}