{"id":1190,"date":"2017-05-19T09:16:51","date_gmt":"2017-05-19T09:16:51","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/2016-china-zlp-series-mature-tech-window-cleaning-platform.html"},"modified":"2017-05-19T09:16:51","modified_gmt":"2017-05-19T09:16:51","slug":"2016-china-zlp-series-mature-tech-window-cleaning-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/2016-china-zlp-series-mature-tech-window-cleaning-platform.html","title":{"rendered":"2016 China ZLP series Mature-tech window cleaning platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale213.jpg\" alt=\"2016 China ZLP series Mature-tech window cleaning platform\" \/><br \/>\nImage of 2016 China ZLP series Mature-tech window cleaning platform<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP<\/li>\n<li>Name:Mature-tech window cleaning platform<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pYlYwbkR1VUcxZnM\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale246.jpg\" alt=\"2016 China ZLP series Mature-tech window cleaning platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale270.jpg\" alt=\"2016 China ZLP series Mature-tech window cleaning platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale93.jpg\" alt=\"2016 China ZLP series Mature-tech window cleaning platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale109.jpg\" alt=\"2016 China ZLP series Mature-tech window cleaning platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale191.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">250 to 1000kg Success brand ZLP Series Suspended scaffolding platform with CE ISO Certificate<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:ZLP500\/ZLP630\/ZLP800<\/li>\n<li>Lift Mechanism:Lift Chain<\/li>\n<li>Accionamiento\/actuaci\u00f3n del ascensor: motor el\u00e9ctrico<\/li>\n<li>Power:1.5kw*2\/1.8kw*2<\/li>\n<li>Rated Loading Capacity:250kg-1000kg<\/li>\n<li>Altura m\u00ednima de elevaci\u00f3n: 0 m<\/li>\n<li>Max. Lifting Height:100m<\/li>\n<li>Table Size:6000*720*1300mm\/7500*720*1300mm<\/li>\n<li>Overall Dimensions:requirement<\/li>\n<li>Peso: 2000 kg<\/li>\n<li>Certification:CE,ISO,GOST .<\/li>\n<li>Warranty:1Year<\/li>\n<li>After-sales Service Provided:No overseas service provided<\/li>\n<li>Color:Silvery or as per requirement<\/li>\n<li>Counterweight:1000kg<\/li>\n<li>Voltage:380v\/50hz<\/li>\n<li>Cable:100M<\/li>\n<li>Lifing speed:8-10m\/min<\/li>\n<li>Usage:wall cleaning equipment scaffolding<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>certificate:CE ISO<\/li>\n<li>steel wire rope:8.3 or 9.1<\/li>\n<li>weight of hoist:50kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Amritsar, Hyderabad, Leeds etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Lift Access Platforms in Amritsar, Crane Loading Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale77.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">FACTORY Easy facade suspended platform for high buildings<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca: Success-CHINA<\/li>\n<li>Model Number:ZLP630\/ZLP800<\/li>\n<li>Usage:Building facade or glass cleaning<\/li>\n<li>Model:ZLP630\/ZLP800  facade suspended platform<\/li>\n<li>Certificados: ISO, GOST, CE<\/li>\n<li>Power Source:Electricity<\/li>\n<li>Drive Type:Wire rope hoisting<\/li>\n<li>Application:Tall Building Maintenance<\/li>\n<li>Origin:China<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Lifting Height and Cable Length:100m<\/li>\n<li>Voltage:380V \/220V\/410V  or according to  customer need<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Sao Paulo, Wellington etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Max Load Capacity 800kg Hoist Suspended Platform in Hyderabad, Durable Window Cleaning Platform in Leeds<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale50.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">International Certificates Suspended Platform FACTORY ZLP1000, ZLP800, ZLP630, ZLP500, ZLP250<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca: Success-CHINA<\/li>\n<li>N\u00famero de modelo: ZLP<\/li>\n<li>Voltage:380V or according to  customer need<\/li>\n<li>Counterweight:1000KG<\/li>\n<li>20&#39;ft container:9 sets<\/li>\n<li>Velocidad de elevaci\u00f3n: 8-10 m\/min<\/li>\n<li>Altura de elevaci\u00f3n: 100 m<\/li>\n<li>Cable de plataforma: 100 m<\/li>\n<li>Usage:Suspended Platform FACTORY ZLP1000, ZLP800, ZLP630, ZLP500, ZLP250<\/li>\n<li>Certificados: ISO, GOST, CE<\/li>\n<li>Material: acero o aleaci\u00f3n de aluminio.<\/li>\n<li>Power:1.5kw, 1.8kw, 2.2kw<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Gwalior, Paris, Oman, Amritsar etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp Suspended Platform Hoist in Sao Paulo, Lift Working Platform in Wellington<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale153.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Success brand zlp 630 high quality building maintenance unite<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:JH-Success<\/li>\n<li>N\u00famero de modelo: ZLP630<\/li>\n<li>Nombre: plataforma suspendida<\/li>\n<li>Surface treatment:Paint Spraying<\/li>\n<li>Load capacity:630kg<\/li>\n<li>Height:100m<\/li>\n<li>Speed:8~10m\/min<\/li>\n<li>Hoist:1.5kw x2<\/li>\n<li>Galvanized steel wir rope:8.3mm<\/li>\n<li>Safe lock:Anti-title<\/li>\n<li>Suspension Mechanism:out reach 1.3-1.7m<\/li>\n<li>Counter weight:1000kgs<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Peru, Yemen, Oman, Gwalior etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Crane Loading Platform, Lift Working Platform in Wellington<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale30.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP630 Facade Cleaning Temporary Suspended Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Place of Origin:China (Mainland)<\/li>\n<li>Brand Name:Suspended Platform Cradle Gondola<\/li>\n<li>N\u00famero de modelo: ZLP500\/630\/800\/1000<\/li>\n<li>Name:Suspended Rope Platform OR Working Platform<\/li>\n<li>Cradle Platform Application:Building maintainence, cleaning,painting<\/li>\n<li>Roof Fixing:1,suspension with counter 2, parapet clamp<\/li>\n<li>Platform Color:Red,Silver,Hot Galvanized<\/li>\n<li>Safety device:safety lock, safe rope etc<\/li>\n<li>Motive Power:Electric Hoist<\/li>\n<li>Platform Shape:cuboid or special design<\/li>\n<li>Platform standard: CE, GOST, ISO<\/li>\n<li>Platform Material:Steel or Aluminum Alloy<\/li>\n<li>Platform Body:free assembled by modular plate<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Amritsar, Leeds, Wellington, Paris etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Lift Access Platforms in Amritsar, Zlp Suspended Platform Hoist in Sao Paulo<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of 2016 China ZLP series Mature-tech window cleaning platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP Name:Mature-tech window cleaning platform <\/p>","protected":false},"author":1,"featured_media":31,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[4919,4922,4924,4921,4920,4923],"class_list":["post-1190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-crane-loading-platform","tag-durable-window-cleaning-platform-in-leeds","tag-lift-working-platform-in-wellington","tag-max-load-capacity-800kg-hoist-suspended-platform-in-hyderabad","tag-suspended-lift-access-platforms-in-amritsar","tag-zlp-suspended-platform-hoist-in-sao-paulo"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/1190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=1190"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/1190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/31"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=1190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=1190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=1190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}