{"id":1011,"date":"2017-05-18T04:12:06","date_gmt":"2017-05-18T04:12:06","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/advanced-construction-work-platform-zlp-outdoor-swing-basket-facade-cleaning-equipment.html"},"modified":"2017-05-18T04:12:06","modified_gmt":"2017-05-18T04:12:06","slug":"advanced-construction-work-platform-zlp-outdoor-swing-basket-facade-cleaning-equipment","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/es\/advanced-construction-work-platform-zlp-outdoor-swing-basket-facade-cleaning-equipment.html","title":{"rendered":"Advanced construction work platform zlp outdoor swing basket facade cleaning equipment"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale249.jpg\" alt=\"Advanced construction work platform zlp outdoor swing basket facade cleaning equipment\" \/><br \/>\nImage of Advanced construction work platform zlp outdoor swing basket facade cleaning equipment<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Name:suspended platform cradle gondola sky climber scaffold<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pOE1HMlQ2UUI3SGs\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale170.jpg\" alt=\"Advanced construction work platform zlp outdoor swing basket facade cleaning equipment\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale121.jpg\" alt=\"Advanced construction work platform zlp outdoor swing basket facade cleaning equipment\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Accesorios relacionados Mostrar: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale7.jpg\" alt=\"Advanced construction work platform zlp outdoor swing basket facade cleaning equipment Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale9.jpg\" alt=\"Advanced construction work platform zlp outdoor swing basket facade cleaning equipment Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale231.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">1000KG gondola lift station near banski prolaz sinj croatia<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: ZLP<\/li>\n<li>Name:gondola lift station near banski prolaz sinj croatia<\/li>\n<li>Color: opcional<\/li>\n<li>Alimentaci\u00f3n (V): 220, 380, 415, 440<\/li>\n<li>Dispositivo de seguridad: 7 elementos<\/li>\n<li>Material: acero o aluminio<\/li>\n<li>Tratamiento de superficie: pulverizaci\u00f3n de pintura o galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Pieza libre: suministro<\/li>\n<li>Cable de acero: galvanizado por inmersi\u00f3n en caliente<\/li>\n<li>Polipasto: Fabricado en aluminio fundido a presi\u00f3n.<\/li>\n<li>Certificado: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Abu Dhabi, Hiroshima, Lilongwe etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hanging Staging in Abu Dhabi, Zlp 500 Suspended Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale202.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">China Supplier Aluminum ZLP630 Hoist suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca: JH<\/li>\n<li>Model Number:JH-ZLP-206<\/li>\n<li>Mecanismo de elevaci\u00f3n: cremallera y pi\u00f1\u00f3n<\/li>\n<li>Accionamiento\/actuaci\u00f3n del ascensor: motor el\u00e9ctrico<\/li>\n<li>Power:50HZ\/60HZ<\/li>\n<li>Capacidad de carga nominal: 250-1000 kg<\/li>\n<li>Min. Lifting Height:50m<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 200 m<\/li>\n<li>Tama\u00f1o de la mesa: 1+2+3m \/ 3*2,5m<\/li>\n<li>Dimensiones generales: 6 m \/ 7 m<\/li>\n<li>Peso: 1000 kg<\/li>\n<li>Certificaci\u00f3n: CE, GOST e ISO<\/li>\n<li>Warranty:12 Months<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Suspended Platform:China Supplier Aluminum ZLP630 Hoist suspended platform<\/li>\n<li>Color: rojo o seg\u00fan las necesidades del cliente.<\/li>\n<li>Potencia: 220 V o 380 V, etc.<\/li>\n<li>Material: aleaci\u00f3n A o acero.<\/li>\n<li>Website:www.bjfth.com<\/li>\n<li>N\u00famero de modelo: Plataforma suspendida serie ZLP<\/li>\n<li>Longitud de la plataforma: 1-7,5 m<\/li>\n<li>Mercados principales: Australia, Sur de Asia, Este, Brasil, Sud\u00e1frica y Emiratos \u00c1rabes Unidos<\/li>\n<li>Carga nominal: 630 kg\/800 kg\/1000 kg<\/li>\n<li>Altura de trabajo: 30-200 m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Peru, Trinidad and Tobago etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Bmu Cradle Platform in Hiroshima, Small Work Platform in Lilongwe<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale184.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High Quality Electric Suspended Working Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>Model Number:HJ-SUP172<\/li>\n<li>Product name:High Quality Electric Suspended Working Platform<\/li>\n<li>Surface Protection: Painting and Galvanize<\/li>\n<li>Keywords:Electric Suspended Working Platform<\/li>\n<li>Color: Red , Yellow , Other<\/li>\n<li>Certification: ISO , CE , GOST proved<\/li>\n<li>Type:construction platforms<\/li>\n<li>Certificate:ISO , CE , GOST proved<\/li>\n<li>Market:global, over 30contries<\/li>\n<li>Item:suspend platforms<\/li>\n<li>place of origin:Shanghai, China (Mainland)<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Gambia, Kota, Maceio, Abu Dhabi etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: 800kg Electric Aluminum Suspended Platform in Peru, Swing Scaffolding in Trinidad and Tobago<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale168.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">steel wire rope suspended platform \/ cradle \/ gondola<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca: JH<\/li>\n<li>N\u00famero de modelo: ZLP<\/li>\n<li>Key word:gondola<\/li>\n<li>color:red<\/li>\n<li>voltage:380v<\/li>\n<li>length:7.5m<\/li>\n<li>warranty:one year<\/li>\n<li>material:steel or aluminum<\/li>\n<li>certificate:CE GOST ISO<\/li>\n<li>special platform:can be supplied<\/li>\n<li>rated load:800kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: New York, Douala, Maceio, Gambia etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp 500 Suspended Platform, Swing Scaffolding in Trinidad and Tobago<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale210.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP Single person suspended platform\/construction platform\/cradle<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Brand Name:Jinfei Tianhong<\/li>\n<li>Model Number:ZLP series<\/li>\n<li>function:Aerial work platform<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Abu Dhabi, Lilongwe, Trinidad and Tobago, Kota etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Hanging Staging in Abu Dhabi, 800kg Electric Aluminum Suspended Platform in Peru<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Advanced construction work platform zlp outdoor swing basket facade cleaning equipment Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP250,ZLP500,ZLP630,ZLP800,ZLP1000 After-sales <\/p>","protected":false},"author":1,"featured_media":123,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3964,3962,3961,3963,3965,3960],"class_list":["post-1011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-800kg-electric-aluminum-suspended-platform-in-peru","tag-bmu-cradle-platform-in-hiroshima","tag-hanging-staging-in-abu-dhabi","tag-small-work-platform-in-lilongwe","tag-swing-scaffolding-in-trinidad-and-tobago","tag-zlp-500-suspended-platform"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/1011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/comments?post=1011"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/posts\/1011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media\/123"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/media?parent=1011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/categories?post=1011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/es\/wp-json\/wp\/v2\/tags?post=1011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}