{"id":1554,"date":"2017-05-22T01:37:33","date_gmt":"2017-05-22T01:37:33","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/zlp-series-window-cleaning-suspended-platform.html"},"modified":"2017-05-22T01:37:33","modified_gmt":"2017-05-22T01:37:33","slug":"zlp-series-window-cleaning-suspended-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/de\/zlp-series-window-cleaning-suspended-platform.html","title":{"rendered":"zlp series window cleaning suspended platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale206.jpg\" alt=\"zlp series window cleaning suspended platform\" \/><br \/>\nImage of zlp series window cleaning suspended platform<\/p>\n<h3 class=\"alpha-title\">Schnelle Details: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Herkunftsort: Shanghai, China (Festland)<\/li>\n<li>Markenname: JH<\/li>\n<li>Modellnummer: ZLP800<\/li>\n<li>Name: H\u00e4ngende Plattform<\/li>\n<li>Modell: ZLP800<\/li>\n<li>Marke: Erfolg<\/li>\n<li>Material: Aluminium<\/li>\n<li>Plattformgr\u00f6\u00dfe: 7,5 x 0,72 x 1,2 m<\/li>\n<li>Arbeitsh\u00f6he: 100m<\/li>\n<li>Stahldrahtseil: 9,1 mm<\/li>\n<li>Kabel: 3*2,5 + 2*1,5<\/li>\n<li>Aufh\u00e4ngungsmechanismus: Feuerverzinkt<\/li>\n<li>Gegengewicht: 1000kg<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u00c4hnliches Video: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pbHI2RXJ0OUM1czQ\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Beschreibung: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale83.jpg\" alt=\"zlp series window cleaning suspended platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale48.jpg\" alt=\"zlp series window cleaning suspended platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Zugeh\u00f6riges Zubeh\u00f6r anzeigen: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale80.jpg\" alt=\"zlp series window cleaning suspended platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale59.jpg\" alt=\"zlp series window cleaning suspended platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Eine Nachricht hinterlassen: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Das k\u00f6nnte dir auch gefallen:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale70.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">CE\/ ISO\/ GOST approved Aerial Lift Equipment, Brand New<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Herkunftsort: Shanghai, China (Festland)<\/li>\n<li>Markenname: Erfolg<\/li>\n<li>Modellnummer: ZLP800<\/li>\n<li>Andere Modelle::ZLP1000, ZLP630, ZLP500<\/li>\n<li>Name:Aerial Lift Equipment<\/li>\n<li>Application:building maintenance<\/li>\n<li>Roof fixing:1,suspension with counter 2, parapet clamp<\/li>\n<li>Platform Body:free assembled by modular<\/li>\n<li>Plattformmaterial: Stahl oder Aluminiumlegierung<\/li>\n<li>Platform color:red\/ silver\/ special make<\/li>\n<li>Shape:cuboid or special design<\/li>\n<li>Motive Power:Electric Hoist<\/li>\n<li>Safety device:safety lock, life line, brake etc<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Brazil, Cuba, Kanpur etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: 4 In 1 Work Platform in Brazil, Elevator Suspended Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Eine Nachricht hinterlassen<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale74.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">China suspended platform spare parts<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Herkunftsort: Shanghai, China (Festland)<\/li>\n<li>Markenname: Erfolg<\/li>\n<li>Modellnummer: ZLP250, ZLP500, ZLP630, ZLP800, ZLP1000<\/li>\n<li>Angebotener Kundendienst: Techniker stehen f\u00fcr die Wartung von Maschinen im Ausland zur Verf\u00fcgung<\/li>\n<li>Name:suspended platform spare parts<\/li>\n<li>Farbe: optional<\/li>\n<li>Stromversorgung (V): 220,380,415,440<\/li>\n<li>Sicherheitsvorrichtung:7 Artikel<\/li>\n<li>Material: Stahl oder Aluminium<\/li>\n<li>Oberfl\u00e4chenbehandlung: Lackieren oder Feuerverzinken<\/li>\n<li>Freies Teil: Versorgung<\/li>\n<li>Stahlseil: Feuerverzinkung<\/li>\n<li>Hebezeug: Aus Aluminium-Druckguss<\/li>\n<li>Zertifikat: CE, ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Russia, Yokohama etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Powered Scaffolding Platform in Cuba, Remote Control Suspended Platform in Kanpur<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Eine Nachricht hinterlassen<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale36.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High Rise Window Cleaning Equipment,ZLP630 Load 630kg Building Maintenance Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Herkunftsort: Shanghai, China (Festland)<\/li>\n<li>Brand Name:Suspended Platform, ZLP  Suspended Platform<\/li>\n<li>Model Number:Suspended Platform<\/li>\n<li>Suspended Platform:ZLP 630 Suspended Platform<\/li>\n<li>Material:Steel Suspended Platform<\/li>\n<li>Type:ZLP630<\/li>\n<li>Platform Length:6m<\/li>\n<li>Rated Load(kg):630kg<\/li>\n<li>Hubgeschwindigkeit: 8-10 m\/min<\/li>\n<li>Useage:ZLP Suspended Platform<\/li>\n<li>Delivery Time:7 days- Suspended Platform<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Germany, Hamburg, Niger, Brazil etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp1000a Steel Suspend Platforms in Russia, Elevated Work Platform Safety in Yokohama<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Eine Nachricht hinterlassen<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale69.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Scaffolding Platform, Scaffolding Machine,Suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Herkunftsort: Shanghai, China (Festland)<\/li>\n<li>Markenname: Erfolg<\/li>\n<li>Modellnummer: ZLP250 ZLP500 ZLP630 ZLP800 ZLP1000<\/li>\n<li>Rated load:1000kg<\/li>\n<li>Hubgeschwindigkeit: 8 ~ 10 m\/min<\/li>\n<li>Hubh\u00f6he: 100m<\/li>\n<li>Kabel: 100 m<\/li>\n<li>Counterweught:1000kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bangkok, Cairo, Niger, Germany etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Elevator Suspended Platform, Elevated Work Platform Safety in Yokohama<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Eine Nachricht hinterlassen<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale33.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP630 Electric Crane Basket Suspended Working Platform Cradle Suspension Crane Basket<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Herkunftsort: Shanghai, China (Festland)<\/li>\n<li>Markenname: Erfolg<\/li>\n<li>Model Number:ZLP 630<\/li>\n<li>Material: Stahl, Aluminiumlegierung<\/li>\n<li>Farbe: Rot, Gelb, Blau usw.<\/li>\n<li>Oberfl\u00e4chenbehandlung: Pulverbeschichtung, Feuerverzinkung<\/li>\n<li>L\u00e4nge: 2 m, 2,5 m, 3 m, 5 m, 6 m, 7,5 m usw<\/li>\n<li>Hebemechanismus: Zahnrad<\/li>\n<li>Hubantrieb\/Bet\u00e4tigung: Elektromotor<\/li>\n<li>Leistung: 1,5 kW, 1,8 kW, 2 kW<\/li>\n<li>Nenntragf\u00e4higkeit: 150 kg, 250 kg, 500 kg, 630 kg, 800 kg, 1000 kg<\/li>\n<li>Max. Hubh\u00f6he: 200 m<\/li>\n<li>Voltage:Crane Basket Suspended Working Platform accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Brazil, Kanpur, Yokohama, Hamburg etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: 4 In 1 Work Platform in Brazil, Zlp1000a Steel Suspend Platforms in Russia<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Eine Nachricht hinterlassen<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of zlp series window cleaning suspended platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:JH Model Number:ZLP800 Name:Suspended Platform Model:ZLP800 Brand:Success Material:Aluminum Platform <\/p>","protected":false},"author":1,"featured_media":15,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6406,6410,6405,6407,6408,6409],"class_list":["post-1554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-4-in-1-work-platform-in-brazil","tag-elevated-work-platform-safety-in-yokohama","tag-elevator-suspended-platform","tag-powered-scaffolding-platform-in-cuba","tag-remote-control-suspended-platform-in-kanpur","tag-zlp1000a-steel-suspend-platforms-in-russia"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/de\/wp-json\/wp\/v2\/posts\/1554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/de\/wp-json\/wp\/v2\/comments?post=1554"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/de\/wp-json\/wp\/v2\/posts\/1554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/de\/wp-json\/wp\/v2\/media\/15"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/de\/wp-json\/wp\/v2\/media?parent=1554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/de\/wp-json\/wp\/v2\/categories?post=1554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/de\/wp-json\/wp\/v2\/tags?post=1554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}