{"id":2240,"date":"2017-05-26T19:26:57","date_gmt":"2017-05-26T19:26:57","guid":{"rendered":"https:\/\/www.ketabkhun.com\/platform\/electric-aerial-suspended-platform.html"},"modified":"2017-05-26T19:26:57","modified_gmt":"2017-05-26T19:26:57","slug":"electric-aerial-suspended-platform","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/platform\/ar\/electric-aerial-suspended-platform.html","title":{"rendered":"Electric Aerial Suspended Platform"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale140.jpg\" alt=\"Electric Aerial Suspended Platform\" \/><br \/>\nImage of Electric Aerial Suspended Platform<\/p>\n<h3 class=\"alpha-title\">\u062a\u0641\u0627\u0635\u064a\u0644 \u0633\u0631\u064a\u0639\u0629: <\/h3>\n<ul class=\"alpha-ali\">\n<li>\u0645\u0643\u0627\u0646 \u0627\u0644\u0645\u0646\u0634\u0623: \u0634\u0646\u063a\u0647\u0627\u064a\u060c \u0627\u0644\u0635\u064a\u0646 (\u0627\u0644\u0628\u0631 \u0627\u0644\u0631\u0626\u064a\u0633\u064a)<\/li>\n<li>\u0627\u0633\u0645 \u0627\u0644\u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629: \u0627\u0644\u0646\u062c\u0627\u062d<\/li>\n<li>\u0631\u0642\u0645 \u0627\u0644\u0645\u0648\u062f\u064a\u0644: ZLP500\/630\/800\/1000<\/li>\n<li>\u0627\u0644\u0643\u0627\u0628\u0644: 3*2.5+2*1.5<\/li>\n<li>\u0633\u0631\u0639\u0629 \u0627\u0644\u0631\u0641\u0639: 8-10 \u0645\/\u062f\u0642\u064a\u0642\u0629<\/li>\n<li>\u0627\u0644\u0645\u0648\u0627\u062f: \u0627\u0644\u0641\u0648\u0644\u0627\u0630 \u0623\u0648 \u0633\u0628\u0627\u0626\u0643 \u0627\u0644\u0623\u0644\u0648\u0645\u0646\u064a\u0648\u0645<\/li>\n<li>\u0627\u0644\u0634\u0647\u0627\u062f\u0627\u062a: ISO\u060c GOST\u060c CE<\/li>\n<li>Name: Electric Aerial Suspended Platform<\/li>\n<li>Platform Cable:100m<\/li>\n<li>Original:China<\/li>\n<li>Application:ZLP Boom Lift\/ Electric Aerial Suspended Platform<\/li>\n<li>Voltage:220V\/380V\/415V<\/li>\n<li>Color:Red or silver<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0641\u064a\u062f\u064a\u0648 \u0630\u0627\u062a \u0635\u0644\u0629: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pLXMwMGZBU1ZfdVE\/preview\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0648\u0635\u0641: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale106.jpg\" alt=\"Electric Aerial Suspended Platform\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale11.jpg\" alt=\"Electric Aerial Suspended Platform\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u0639\u0631\u0636 \u0627\u0644\u0645\u0644\u062d\u0642\u0627\u062a \u0630\u0627\u062a \u0627\u0644\u0635\u0644\u0629: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale62.jpg\" alt=\"Electric Aerial Suspended Platform Related Accessories Show\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/platform\/img\/Cheap_Suspended_Platform_Accessories_Price_For_Sale28.jpg\" alt=\"Electric Aerial Suspended Platform Related Accessories Show\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">\u062a\u0631\u0643 \u0631\u0633\u0627\u0644\u0629: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">\u0642\u062f \u064a\u0639\u062c\u0628\u0643 \u0623\u064a\u0636\u064b\u0627:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale2.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">(CE,ISO) Suspended Scaffolding\/ Suspending Platform\/ Construction Working Platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u0643\u0627\u0646 \u0627\u0644\u0645\u0646\u0634\u0623: \u0634\u0646\u063a\u0647\u0627\u064a\u060c \u0627\u0644\u0635\u064a\u0646 (\u0627\u0644\u0628\u0631 \u0627\u0644\u0631\u0626\u064a\u0633\u064a)<\/li>\n<li>\u0627\u0633\u0645 \u0627\u0644\u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629: \u0627\u0644\u0646\u062c\u0627\u062d<\/li>\n<li>Model Number:ZLP150<\/li>\n<li>\u062e\u062f\u0645\u0629 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0628\u064a\u0639 \u0627\u0644\u0645\u0642\u062f\u0645\u0629: \u0645\u0647\u0646\u062f\u0633\u0648\u0646 \u0645\u062a\u0627\u062d\u0648\u0646 \u0644\u062e\u062f\u0645\u0629 \u0627\u0644\u0622\u0644\u0627\u062a \u0641\u064a \u0627\u0644\u062e\u0627\u0631\u062c<\/li>\n<li>\u0627\u0644\u0645\u0648\u0627\u062f: \u0627\u0644\u0641\u0648\u0644\u0627\u0630\u060c \u0633\u0628\u0627\u0626\u0643 \u0627\u0644\u0623\u0644\u0648\u0645\u0646\u064a\u0648\u0645<\/li>\n<li>\u0627\u0644\u0644\u0648\u0646: \u0623\u062d\u0645\u0631\u060c \u0623\u0635\u0641\u0631\u060c \u0623\u0632\u0631\u0642\u060c \u0625\u0644\u062e.<\/li>\n<li>\u0645\u0639\u0627\u0644\u062c\u0629 \u0627\u0644\u0633\u0637\u062d: \u0637\u0644\u0627\u0621 \u0627\u0644\u0645\u0633\u062d\u0648\u0642\u060c \u0627\u0644\u062c\u0644\u0641\u0646\u0629 \u0627\u0644\u0633\u0627\u062e\u0646\u0629<\/li>\n<li>\u0627\u0644\u0637\u0648\u0644: 2 \u0645\u060c 2.5 \u0645\u060c 3 \u0645\u060c 5 \u0645\u060c 6 \u0645\u060c 7.5 \u0645\u060c \u0625\u0644\u062e<\/li>\n<li>\u0622\u0644\u064a\u0629 \u0627\u0644\u0631\u0641\u0639: \u062a\u0631\u0633<\/li>\n<li>\u0645\u062d\u0631\u0643 \u0627\u0644\u0631\u0641\u0639\/\u0627\u0644\u062a\u0634\u063a\u064a\u0644: \u0645\u062d\u0631\u0643 \u0643\u0647\u0631\u0628\u0627\u0626\u064a<\/li>\n<li>\u0627\u0644\u0637\u0627\u0642\u0629: 1.5 \u0643\u064a\u0644\u0648 \u0648\u0627\u062a\u060c 1.8 \u0643\u064a\u0644\u0648 \u0648\u0627\u062a\u060c 2 \u0643\u064a\u0644\u0648 \u0648\u0627\u062a<\/li>\n<li>\u0633\u0639\u0629 \u0627\u0644\u062a\u062d\u0645\u064a\u0644 \u0627\u0644\u0645\u0642\u062f\u0631\u0629: 150 \u0643\u062c\u0645\u060c 250 \u0643\u062c\u0645\u060c 500 \u0643\u062c\u0645\u060c 630 \u0643\u062c\u0645\u060c 800 \u0643\u062c\u0645\u060c 1000 \u0643\u062c\u0645<\/li>\n<li>\u0623\u0642\u0635\u0649 \u0627\u0631\u062a\u0641\u0627\u0639 \u0644\u0644\u0631\u0641\u0639: \u0662\u0660\u0660 \u0645\u062a\u0631<\/li>\n<li>Voltage:Suspended Scaffolding\/ Suspending Platform accept different voltage<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ashgabat, Ghaziabad, Maputo etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Access Suspended Platforms Inc in Ashgabat, Zlp 630 Cheap Gondola Hoist Suspended Platform<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u062a\u0631\u0643 \u0631\u0633\u0627\u0644\u0629<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale199.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">China Success brand ZLP suspened platform\/suspended rope platform\/rope suspended platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0627\u0644\u062d\u0627\u0644\u0629:\u062c\u062f\u064a\u062f<\/li>\n<li>\u0645\u0643\u0627\u0646 \u0627\u0644\u0645\u0646\u0634\u0623: \u0634\u0646\u063a\u0647\u0627\u064a\u060c \u0627\u0644\u0635\u064a\u0646 (\u0627\u0644\u0628\u0631 \u0627\u0644\u0631\u0626\u064a\u0633\u064a)<\/li>\n<li>\u0627\u0633\u0645 \u0627\u0644\u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629: \u0627\u0644\u0646\u062c\u0627\u062d<\/li>\n<li>\u0631\u0642\u0645 \u0627\u0644\u0645\u0648\u062f\u064a\u0644:ZLP<\/li>\n<li>Usage:Other<\/li>\n<li>Power Source:Electric<\/li>\n<li>Sling Type:Wire Rope<\/li>\n<li>Maximum Lifting Weight:1000KG<\/li>\n<li>Maximum Lifting Height:300M<\/li>\n<li>Lift Speed:10M\/MIN<\/li>\n<li>Certification:CE,ISO,GOST<\/li>\n<li>Warranty:ONE YEAR<\/li>\n<li>After-sales Service Provided:Overseas service center available<\/li>\n<li>Name:susended platform<\/li>\n<li>color:red<\/li>\n<li>lifting weight:1000kg<\/li>\n<li>\u0627\u0631\u062a\u0641\u0627\u0639 \u0627\u0644\u0631\u0641\u0639: 100 \u0645\u062a\u0631<\/li>\n<li>\u0633\u0631\u0639\u0629 \u0627\u0644\u0631\u0641\u0639: 10 \u0645\/\u062f\u0642\u064a\u0642\u0629<\/li>\n<li>\u0627\u0644\u062c\u0647\u062f: 380 \u0641\u0648\u0644\u062a\u060c \u064a\u0645\u0643\u0646 \u062a\u0639\u062f\u064a\u0644\u0647<\/li>\n<li>\u0627\u0644\u0633\u0639\u0631: \u0633\u0639\u0631 \u0627\u0644\u0645\u0635\u0646\u0639<\/li>\n<li>quality:welcome by customers from world<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: San Diego, Senegal etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Aerial Lift Equipment in Ghaziabad, Aluminum Platform in Maputo<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u062a\u0631\u0643 \u0631\u0633\u0627\u0644\u0629<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale232.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">\u062a\u0648\u0641\u064a\u0631 \u062c\u0646\u062f\u0648\u0644 \u0645\u0639\u0644\u0642 \u0644\u0635\u064a\u0627\u0646\u0629 \u0627\u0644\u062c\u0633\u0631 \u0627\u0644\u0623\u0635\u0644\u064a<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u0643\u0627\u0646 \u0627\u0644\u0645\u0646\u0634\u0623: \u0634\u0646\u063a\u0647\u0627\u064a\u060c \u0627\u0644\u0635\u064a\u0646 (\u0627\u0644\u0628\u0631 \u0627\u0644\u0631\u0626\u064a\u0633\u064a)<\/li>\n<li>\u0627\u0633\u0645 \u0627\u0644\u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629: \u0627\u0644\u0646\u062c\u0627\u062d<\/li>\n<li>\u0631\u0642\u0645 \u0627\u0644\u0645\u0648\u062f\u064a\u0644: ZLP250\u060c ZLP500\u060c ZLP630\u060c ZLP800\u060c ZLP1000<\/li>\n<li>\u062e\u062f\u0645\u0629 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0628\u064a\u0639 \u0627\u0644\u0645\u0642\u062f\u0645\u0629: \u0645\u0647\u0646\u062f\u0633\u0648\u0646 \u0645\u062a\u0627\u062d\u0648\u0646 \u0644\u062e\u062f\u0645\u0629 \u0627\u0644\u0622\u0644\u0627\u062a \u0641\u064a \u0627\u0644\u062e\u0627\u0631\u062c<\/li>\n<li>Name:bridge maintenance suspended gondola<\/li>\n<li>\u0627\u0644\u0644\u0648\u0646:\u0627\u062e\u062a\u064a\u0627\u0631\u064a<\/li>\n<li>\u0645\u0635\u062f\u0631 \u0627\u0644\u0637\u0627\u0642\u0629 (\u0641\u0648\u0644\u062a): 220\u060c380\u060c415\u060c440<\/li>\n<li>\u062c\u0647\u0627\u0632 \u0627\u0644\u0633\u0644\u0627\u0645\u0629: 7 \u0639\u0646\u0627\u0635\u0631<\/li>\n<li>\u0627\u0644\u0645\u0648\u0627\u062f: \u0627\u0644\u0641\u0648\u0644\u0627\u0630 \u0623\u0648 \u0627\u0644\u0623\u0644\u0648\u0645\u0646\u064a\u0648\u0645<\/li>\n<li>\u0645\u0639\u0627\u0644\u062c\u0629 \u0627\u0644\u0633\u0637\u062d: \u0631\u0634 \u0627\u0644\u0637\u0644\u0627\u0621 \u0623\u0648 \u0627\u0644\u062c\u0644\u0641\u0646\u0629 \u0628\u0627\u0644\u063a\u0645\u0633 \u0627\u0644\u0633\u0627\u062e\u0646<\/li>\n<li>\u062c\u0632\u0621 \u0645\u062c\u0627\u0646\u064a:\u0627\u0644\u062a\u0648\u0631\u064a\u062f<\/li>\n<li>\u062d\u0628\u0644 \u0641\u0648\u0644\u0627\u0630\u064a: \u062c\u0644\u0641\u0646\u0629 \u0628\u0627\u0644\u063a\u0645\u0633 \u0627\u0644\u0633\u0627\u062e\u0646<\/li>\n<li>\u0627\u0644\u0631\u0627\u0641\u0639\u0629: \u0645\u0635\u0646\u0648\u0639\u0629 \u0645\u0646 \u0627\u0644\u0623\u0644\u0648\u0645\u0646\u064a\u0648\u0645 \u0627\u0644\u0645\u0635\u0628\u0648\u0628<\/li>\n<li>\u0627\u0644\u0634\u0647\u0627\u062f\u0629: CE\u060c ISO9001-2008<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bogor, Kazakhstan, Morocco, Ashgabat etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Suspended Platform Parts in San Diego, Zlp800 Steel Material Lift Suspended Platform in Senegal<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u062a\u0631\u0643 \u0631\u0633\u0627\u0644\u0629<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale144.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Success factory zlp 630\/ 800 suspended lift scaffolding platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u0643\u0627\u0646 \u0627\u0644\u0645\u0646\u0634\u0623: \u0634\u0646\u063a\u0647\u0627\u064a\u060c \u0627\u0644\u0635\u064a\u0646 (\u0627\u0644\u0628\u0631 \u0627\u0644\u0631\u0626\u064a\u0633\u064a)<\/li>\n<li>\u0627\u0633\u0645 \u0627\u0644\u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629: \u0627\u0644\u0646\u062c\u0627\u062d<\/li>\n<li>Model Number:HJ-SUP-382<\/li>\n<li>\u0642\u062f\u0631\u0629 \u0627\u0644\u062a\u062d\u0645\u064a\u0644: 500 \u0643\u062c\u0645\u061b 630 \u0643\u062c\u0645\u061b 800 \u0643\u062c\u0645\u061b 1000 \u0643\u062c\u0645<\/li>\n<li>\u0627\u0644\u0645\u0648\u0627\u062f: \u0627\u0644\u0641\u0648\u0644\u0627\u0630 \u0627\u0644\u0645\u062c\u0644\u0641\u0646\/\u0627\u0644\u0623\u0644\u0648\u0645\u0646\u064a\u0648\u0645<\/li>\n<li>\u0645\u0639\u0627\u0644\u062c\u0629 \u0627\u0644\u0633\u0637\u062d: \u0645\u062c\u0644\u0641\u0646\u061b \u0631\u0634 HDG \u0623\u0648 \u0627\u0644\u0628\u0644\u0627\u0633\u062a\u064a\u0643<\/li>\n<li>\u0637\u0648\u0644 \u0627\u0644\u0645\u0646\u0635\u0629: 2 \u0645-12 \u0645\u061b OEM<\/li>\n<li>\u0642\u0648\u0629 \u0627\u0644\u0645\u062d\u0631\u0643 \u0627\u0644\u0643\u0647\u0631\u0628\u0627\u0626\u064a: 1.5 \u0643\u064a\u0644\u0648 \u0648\u0627\u0637*2\u061b 1.8 \u0643\u064a\u0644\u0648 \u0648\u0627\u0637*2\u061b 2.2 \u0643\u064a\u0644\u0648 \u0648\u0627\u0637*2\u061b 3.0 \u0643\u064a\u0644\u0648 \u0648\u0627\u0637*2<\/li>\n<li>Lifting Speed:9.3M\/min<\/li>\n<li>\u0627\u0644\u062c\u0647\u062f: 380 \u0641\u0648\u0644\u062a\/50 \u0647\u0631\u062a\u0632\/\u062b\u0644\u0627\u062b\u064a \u0627\u0644\u0637\u0648\u0631 220 \u0641\u0648\u0644\u062a\/50 \u0647\u0631\u062a\u0632\/\u0623\u062d\u0627\u062f\u064a \u0627\u0644\u0637\u0648\u0631<\/li>\n<li>\u0623\u0642\u0635\u0649 \u0627\u0631\u062a\u0641\u0627\u0639 \u0644\u0644\u0631\u0641\u0639: 200 \u0645\u062a\u0631<\/li>\n<li>\u0627\u0644\u062a\u0637\u0628\u064a\u0642: \u0628\u0646\u0627\u0621 \u0627\u0644\u0645\u0628\u0627\u0646\u064a\u061b \u0627\u0644\u0637\u0644\u0627\u0621\u060c \u062a\u0646\u0638\u064a\u0641 \u0627\u0644\u0646\u0648\u0627\u0641\u0630<\/li>\n<li>\u0627\u0644\u0634\u0647\u0627\u062f\u0629: ISO9001\/CE\/TUV<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Bangkok, Bamako, Morocco, Bogor etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Zlp 630 Cheap Gondola Hoist Suspended Platform, Zlp800 Steel Material Lift Suspended Platform in Senegal<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u062a\u0631\u0643 \u0631\u0633\u0627\u0644\u0629<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/platform\/wp-content\/uploads\/Cheap_Suspended_Platform_Price_For_Sale139.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">ZLP facade cradle Electric Construction\/Suspended Platform\/ Cradle\/ Gondola\/ Swing Stage\/ Climber\/ Scaffold<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>\u0645\u0643\u0627\u0646 \u0627\u0644\u0645\u0646\u0634\u0623: \u0634\u0646\u063a\u0647\u0627\u064a\u060c \u0627\u0644\u0635\u064a\u0646 (\u0627\u0644\u0628\u0631 \u0627\u0644\u0631\u0626\u064a\u0633\u064a)<\/li>\n<li>\u0627\u0633\u0645 \u0627\u0644\u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629: \u0627\u0644\u0646\u062c\u0627\u062d<\/li>\n<li>\u0631\u0642\u0645 \u0627\u0644\u0645\u0648\u062f\u064a\u0644:ZLP<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Export to: Ashgabat, Maputo, Senegal, Kazakhstan etc.<\/div>\n<div class=\"alpha-text1\">Related Keywords: Access Suspended Platforms Inc in Ashgabat, Suspended Platform Parts in San Diego<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">\u062a\u0631\u0643 \u0631\u0633\u0627\u0644\u0629<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Electric Aerial Suspended Platform Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:ZLP500\/630\/800\/1000 Cable:3*2.5+2*1.5 Lifting Speed:8-10m\/min Material:steel or aluminum alloy Certificates:ISO, <\/p>","protected":false},"author":1,"featured_media":9,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[9325,9326,9327,9328,5063,9329],"class_list":["post-2240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suspended-platform","tag-access-suspended-platforms-inc-in-ashgabat","tag-aerial-lift-equipment-in-ghaziabad","tag-aluminum-platform-in-maputo","tag-suspended-platform-parts-in-san-diego","tag-zlp-630-cheap-gondola-hoist-suspended-platform","tag-zlp800-steel-material-lift-suspended-platform-in-senegal"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/platform\/ar\/wp-json\/wp\/v2\/posts\/2240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/platform\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/platform\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/ar\/wp-json\/wp\/v2\/comments?post=2240"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/platform\/ar\/wp-json\/wp\/v2\/posts\/2240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/ar\/wp-json\/wp\/v2\/media\/9"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/platform\/ar\/wp-json\/wp\/v2\/media?parent=2240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/ar\/wp-json\/wp\/v2\/categories?post=2240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/platform\/ar\/wp-json\/wp\/v2\/tags?post=2240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}