{"id":4176,"date":"2017-06-06T04:14:20","date_gmt":"2017-06-06T04:14:20","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/harvester-metal-double-gear.html"},"modified":"2017-06-06T04:14:20","modified_gmt":"2017-06-06T04:14:20","slug":"harvester-metal-double-gear","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/pt\/harvester-metal-double-gear.html","title":{"rendered":"harvester metal double gear"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale467.jpg\" alt=\"harvester metal double gear\" \/><br \/>\nImage of harvester metal double gear<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Forma: Espor\u00e3o<\/li>\n<li>Local de origem: Sucesso, China (continente), Sucesso, China (continente)<\/li>\n<li>N\u00famero do modelo: personalizado<\/li>\n<li>Marca: OEM<\/li>\n<li>Material: A\u00e7o, A\u00e7o, A\u00e7o C45<\/li>\n<li>forma: Engrenagem de cremalheira, quadrada<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Palavras-chave:Engrenagem<\/li>\n<li>Processamento: Fresagem<\/li>\n<li>embalagem: de acordo com a solicita\u00e7\u00e3o do cliente<\/li>\n<li>Perfil do dente: conforme solicita\u00e7\u00e3o<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pRHhTb29ucmZLZHM\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale371.jpg\" alt=\"harvester metal double gear\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale10.jpg\" alt=\"harvester metal double gear\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale459.jpg\" alt=\"harvester metal double gear\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale43.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Rack and Pinion Construction Hoist Accessories M8 M6<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Sucesso N\u00ba: M8 M6 M5 M4<\/li>\n<li>Aplica\u00e7\u00e3o: Uso na constru\u00e7\u00e3o<\/li>\n<li>Tipo de eslinga: cabo de a\u00e7o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Instala\u00e7\u00e3o: Montado<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>N\u00famero de sucesso: M1-M10<\/li>\n<li>Dispositivo de seguran\u00e7a para elevador: Motor<\/li>\n<li>Dispositivo de seguran\u00e7a do elevador: Redutor<\/li>\n<li>N\u00famero de dentes: 15 dentes padr\u00e3o<\/li>\n<li>De: Sucesso<\/li>\n<li>Origem: Xangai<\/li>\n<li>Type: Tower Crane<\/li>\n<li>Tower Crane Type: Under Slewing Cranes<\/li>\n<li>Forma da Viga Principal: Viga Dupla<\/li>\n<li>Tipo de movimento: Orbital<\/li>\n<li>Certification: ISO9001: 2000, CE<\/li>\n<li>Marca: Sucesso<\/li>\n<li>Elevador de constru\u00e7\u00e3o: Cremalheira<\/li>\n<li>Dispositivo de seguran\u00e7a para elevadores de constru\u00e7\u00e3o: Dispositivo de seguran\u00e7a<\/li>\n<li>Dispositivo de eleva\u00e7\u00e3o: talha el\u00e9trica<\/li>\n<li>Caracter\u00edsticas: Cremalheira com maior<\/li>\n<li>Especifica\u00e7\u00e3o: cerca de 7 a 15 dias ap\u00f3s o recebimento do pagamento<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: China Gear Rack Stamping For Sliding Gate in Bangkok, M8 Rack Price<\/div>\n<div class=\"alpha-text1\">Export to: Bangkok, Islamabad, Kampala etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale348.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Good market and good quality heavy construction machine &#8212; construction hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200, SC150\/150, SCA200\/200<\/li>\n<li>Capacidade de carga nominal (kg): 1000kg-2000kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 0-33 m\/min, 0-55 m\/min<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 250 m<\/li>\n<li>Dimens\u00e3o (C*L*A): 3,0*1,3(1,5)*2,2<\/li>\n<li>Peso do carregador: 2000 kg<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Type:heavy construction machine<\/li>\n<li>Tens\u00e3o-frequ\u00eancia: 380-50 Hz (pode ser ajustada conforme a necessidade do cliente)<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 33 m\/min, 0-33 m\/min, 0-55 m\/min<\/li>\n<li>Capacidade nominal: 1000Kg \u2013 2000Kg<\/li>\n<li>Pot\u00eancia do motor: 11 kW * 2, 11 kW * 3, 15 kW * 2, 12 kW * 2, 13 kW * 2<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9000, CE, GOST, Padr\u00e3o Coreano<\/li>\n<li>Se\u00e7\u00e3o do mastro: 650*650*1508(mm) peso: 145Kg<\/li>\n<li>Tipo de acionamento: Engrenagem e cremalheira<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Acabamento de cozimento, Galvaniza\u00e7\u00e3o, Pintura<\/li>\n<li>Garantia: 1 ano<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Aluminum Steel Spur Gear Rack in Islamabad, Baoda Gear Rack in Kampala<\/div>\n<div class=\"alpha-text1\">Export to: Papua New Guinea, Turin etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale173.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">delrin spur gears<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Tipo: Pe\u00e7as de Elevador<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: M8\/M5\/M6<\/li>\n<li>Dimens\u00e3o: 650*650*1505<\/li>\n<li>material: a\u00e7o estrutural A3<\/li>\n<li>estoque:Rico<\/li>\n<li>Tubo: 3\u00d73\/16 pol.<\/li>\n<li>\u00c2ngulos dobrados: 1\/4 pol.<\/li>\n<li>Aparelhos: 7\/8 pol.<\/li>\n<li>Material do rack: a\u00e7o estrutural A3<\/li>\n<li>tipo: pe\u00e7as de elevador de guindaste de torre<\/li>\n<li>elevador de torre: pe\u00e7as do elevador<\/li>\n<li>se\u00e7\u00e3o do mastro: pe\u00e7as do elevador<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Gear Rack Maker Module 5 8 10 in Papua New Guinea, Gear Rack For Sliding Driveway Gate in Turin<\/div>\n<div class=\"alpha-text1\">Export to: Srinagar, Madagascar, Morocco, Bangkok etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale410.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">gear rack and pinion price for construction hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Place of Origin:China (Mainland)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:RACK-99<\/li>\n<li>Material: C45<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>cor:preto<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: M8 Rack Price, Gear Rack For Sliding Driveway Gate in Turin<\/div>\n<div class=\"alpha-text1\">Export to: Lahore, Yemen, Morocco, Srinagar etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale411.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">High Quality C45 Material Worm and Worm Gear and Worm<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: RBBOB001<\/li>\n<li>Application: Textile Machinery, Garment Machinery, Conveyer Equipment, Packaging Machinery, Electric Cars, Motorcycle, Food Machinery, Marine, Mining Equipment, Agricultural Machinery, Car, Reducer<\/li>\n<li>Head: Single Head<\/li>\n<li>Type: Worm and Wormwheel<\/li>\n<li>Success Number: No Success<\/li>\n<li>Tipo de dente: reto\/espiral\/esquadria<\/li>\n<li>Test Equipment: Projector<\/li>\n<li>Dureza: Endurecido<\/li>\n<li>M\u00e9todo de fabrica\u00e7\u00e3o: Engrenagem fundida<\/li>\n<li>Pacote de transporte: Pacote de madeira, dispon\u00edvel para transporte mar\u00edtimo e a\u00e9reo<\/li>\n<li>Origem: China<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Spiral Line: Right-Handed Rotation<\/li>\n<li>Reference Surface: Conical Surface<\/li>\n<li>Local de origem: China<\/li>\n<li>Precision: G5 &#8211; G6<\/li>\n<li>Pressure Angle: 20\/40\/50\/60 Customized<\/li>\n<li>Material: A\u00e7o inoxid\u00e1vel<\/li>\n<li>Manipula\u00e7\u00e3o de Maneira: Manipula\u00e7\u00e3o For\u00e7ada<\/li>\n<li>De: Sucesso<\/li>\n<li>Especifica\u00e7\u00e3o: M1-M20<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: China Gear Rack Stamping For Sliding Gate in Bangkok, Gear Rack Maker Module 5 8 10 in Papua New Guinea<\/div>\n<div class=\"alpha-text1\">Export to: Bangkok, Kampala, Turin, Madagascar etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of harvester metal double gear Quick Details: Shape:Spur Place of Origin:Success, China (Mainland), Success, China (Mainland) Model Number:Customized Brand Name:oem Material:Steel, Steel, Steel C45 <\/p>","protected":false},"author":1,"featured_media":284,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14484,14485,14483,14487,14486,1417],"class_list":["post-4176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-aluminum-steel-spur-gear-rack-in-islamabad","tag-baoda-gear-rack-in-kampala","tag-china-gear-rack-stamping-for-sliding-gate-in-bangkok","tag-gear-rack-for-sliding-driveway-gate-in-turin","tag-gear-rack-maker-module-5-8-10-in-papua-new-guinea","tag-m8-rack-price"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/4176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/comments?post=4176"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/4176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media\/284"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media?parent=4176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/categories?post=4176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/tags?post=4176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}