{"id":2952,"date":"2017-05-25T20:16:13","date_gmt":"2017-05-25T20:16:13","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/tower-crane-joystickcrane-anemometerzoomlion-hoistelevator-roller-guide.html"},"modified":"2017-05-25T20:16:13","modified_gmt":"2017-05-25T20:16:13","slug":"tower-crane-joystickcrane-anemometerzoomlion-hoistelevator-roller-guide","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/pt\/tower-crane-joystickcrane-anemometerzoomlion-hoistelevator-roller-guide.html","title":{"rendered":"tower crane joystick,crane anemometer,zoomlion hoist,elevator roller guide"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale215.jpg\" alt=\"tower crane joystick,crane anemometer,zoomlion hoist,elevator roller guide\" \/><br \/>\nImage of tower crane joystick,crane anemometer,zoomlion hoist,elevator roller guide<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Brand Name:shipping container lift<\/li>\n<li>Model Number:shipping container liftM4<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo<\/li>\n<li>Peso m\u00e1ximo de eleva\u00e7\u00e3o: 1T-20T<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150M<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 36M\/MIN<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001:2008<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Tower Crane Type:shipping container lift<\/li>\n<li>SC200\/200::shipping container lift<\/li>\n<li>Tipo de movimenta\u00e7\u00e3o: cremalheira e engrenagem<\/li>\n<li>Forma da Viga Principal: Viga Dupla<\/li>\n<li>Gaiola: Gaiola dupla (com opera\u00e7\u00e3o<\/li>\n<li>Main Electrical System:Schneider shipping container lift<\/li>\n<li>Instala\u00e7\u00e3o:Montado<\/li>\n<li>Comprimento ajust\u00e1vel da amarra\u00e7\u00e3o de parede e quantidade: 2,8-3,2 m 1 pe\u00e7a\/5 mastros<\/li>\n<li>Cage Dimension:3*1.5*2.2m,3*1.3*2.2m shipping container lift<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pamJlUFBFTHM0MGc\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale89.jpg\" alt=\"tower crane joystick,crane anemometer,zoomlion hoist,elevator roller guide\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale96.jpg\" alt=\"tower crane joystick,crane anemometer,zoomlion hoist,elevator roller guide\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale434.jpg\" alt=\"tower crane joystick,crane anemometer,zoomlion hoist,elevator roller guide\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale108.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction Hoist Accessories M8 M6 Rack China Suppliers<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Sucesso N\u00ba: M8 M6 M5 M4<\/li>\n<li>N\u00famero de sucesso: M1-M10<\/li>\n<li>Dispositivo de seguran\u00e7a para elevador: Motor<\/li>\n<li>Dispositivo de seguran\u00e7a do elevador: Redutor<\/li>\n<li>N\u00famero de dentes: 15 dentes padr\u00e3o<\/li>\n<li>De: Sucesso<\/li>\n<li>Especifica\u00e7\u00e3o: cerca de 7 a 15 dias ap\u00f3s o recebimento do pagamento<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<li>Marca: Sucesso<\/li>\n<li>Elevador de constru\u00e7\u00e3o: Cremalheira<\/li>\n<li>Dispositivo de seguran\u00e7a para elevadores de constru\u00e7\u00e3o: Dispositivo de seguran\u00e7a<\/li>\n<li>Dispositivo de eleva\u00e7\u00e3o: talha el\u00e9trica<\/li>\n<li>Caracter\u00edsticas: Cremalheira com maior<\/li>\n<li>Pacote de transporte: caixa de madeira<\/li>\n<li>Origem: Xangai<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Rack And Pinions in Bahrain, Starter Drive Pinion<\/div>\n<div class=\"alpha-text1\">Export to: Bahrain, Istanbul, Luxembourg etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale94.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">SC200\/200 SC200\/200 VF regulation builders hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200, SC150\/150, SCA200\/200<\/li>\n<li>Capacidade de carga nominal (kg): 1000kg-2000kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 0-33 m\/min, 0-55 m\/min<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 250 m<\/li>\n<li>Dimens\u00e3o (C*L*A): 3,0*1,3(1,5)*2,2<\/li>\n<li>Peso do carregador: 2000 kg<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Type:SC200\/200 VF regulation builders hoist<\/li>\n<li>Tens\u00e3o-frequ\u00eancia: 380-50 Hz (pode ser ajustada conforme a necessidade do cliente)<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 33 m\/min, 0-33 m\/min, 0-55 m\/min<\/li>\n<li>Capacidade nominal: 1000Kg \u2013 2000Kg<\/li>\n<li>Pot\u00eancia do motor: 11 kW * 2, 11 kW * 3, 15 kW * 2, 12 kW * 2, 13 kW * 2<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9000, CE, GOST, Padr\u00e3o Coreano<\/li>\n<li>Se\u00e7\u00e3o do mastro: 650*650*1508(mm) peso: 145Kg<\/li>\n<li>Tipo de acionamento: Engrenagem e cremalheira<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Acabamento de cozimento, Galvaniza\u00e7\u00e3o, Pintura<\/li>\n<li>Garantia: 1 ano<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: C45 Steel Gear Rack in Istanbul, Steel Material Gear Rack And Pinion in Luxembourg<\/div>\n<div class=\"alpha-text1\">Export to: Multan, Zapopan etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale141.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">elevador de constru\u00e7\u00e3o\/elevador de constru\u00e7\u00e3o\/elevador de materiais<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: Elevador de materiais de constru\u00e7\u00e3o<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo<\/li>\n<li>Peso m\u00e1ximo de eleva\u00e7\u00e3o: 20 toneladas<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 100 m<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 22 m\/min<\/li>\n<li>Certifica\u00e7\u00e3o: iso, sgs, ce<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Forma da Viga Principal: Viga Dupla<\/li>\n<li>Tipo de movimenta\u00e7\u00e3o: cremalheira e engrenagem<\/li>\n<li>Tipo de guindaste de torre: guindaste de constru\u00e7\u00e3o<\/li>\n<li>Instala\u00e7\u00e3o:Montado<\/li>\n<li>Aplica\u00e7\u00e3o: Uso na constru\u00e7\u00e3o<\/li>\n<li>Gaiola: Gaiola dupla (com cabine de opera\u00e7\u00e3o ou sem cabine)<\/li>\n<li>Dimens\u00e3o da gaiola: 3*1,5*2,2m,3*1,3*2,2m,3,2*1,5*2,2m (vari\u00e1vel)<\/li>\n<li>Comprimento e quantidade ajust\u00e1veis da amarra\u00e7\u00e3o de parede: 2,8-3,2 m 1 pe\u00e7a\/5 mastros (podem ser ajustados)<\/li>\n<li>Sistema el\u00e9trico principal: Schneider (pode ser equipado com sensor de falha PLC)<\/li>\n<li>elevador de constru\u00e7\u00e3o: Elevadores de materiais de constru\u00e7\u00e3o<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: M1.5 M2 M3 Gear Rack in Multan, Delrin Spur Gears in Zapopan<\/div>\n<div class=\"alpha-text1\">Export to: Aurangabad, Berlin, Mozambique, Bahrain etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale86.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Hoist Gear Rack,Construction lifting worm gear reducer Gearbox<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira, Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:RB16040120, Gear Rack for Sliding Gate Operator<\/li>\n<li>Marca: GJJ, BAODA, Success<\/li>\n<li>Material: A\u00e7o, A\u00e7o, C45, G60 Cremalheira para Operador de Port\u00e3o Deslizante<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o, fresagem<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Certificado de qualidade: ISO9000:2008<\/li>\n<li>Dentes helicoidais: Cremalheira para operador de port\u00e3o deslizante<\/li>\n<li>Engrenagem: 15 dentes<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Zincagem a quente<\/li>\n<li>\u00c2ngulo de press\u00e3o: 20 ou como desenhos<\/li>\n<li>Perfil do dente: Cremalheira para operador de port\u00e3o deslizante<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Starter Drive Pinion, Delrin Spur Gears in Zapopan<\/div>\n<div class=\"alpha-text1\">Export to: Chicago, Lagos, Mozambique, Aurangabad etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale250.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Flexible Gear Racks (m10\/m8\/m6\/m5) Drive Pinion Gear<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: PA800<\/li>\n<li>Aplica\u00e7\u00e3o: M\u00e1quinas de eleva\u00e7\u00e3o<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Textura: G60<\/li>\n<li>Cor: Preto<\/li>\n<li>Dispositivo de seguran\u00e7a para elevador: Motor<\/li>\n<li>Dispositivo de seguran\u00e7a do elevador: Redutor<\/li>\n<li>N\u00famero de dentes: 15 dentes padr\u00e3o<\/li>\n<li>Pacote de transporte: caixa de madeira<\/li>\n<li>Origem: Xangai<\/li>\n<li>Tipo: Engrenagem de cremalheira<\/li>\n<li>Certifica\u00e7\u00e3o: CE, ISO9001: 2000<\/li>\n<li>N\u00famero de sucesso: M8<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Elevador de constru\u00e7\u00e3o: Cremalheira<\/li>\n<li>Dispositivo de seguran\u00e7a para elevadores de constru\u00e7\u00e3o: Dispositivo de seguran\u00e7a<\/li>\n<li>Dispositivo de eleva\u00e7\u00e3o: talha el\u00e9trica<\/li>\n<li>De: Sucesso<\/li>\n<li>Especifica\u00e7\u00e3o: cerca de 7 a 15 dias ap\u00f3s o recebimento do pagamento T\/T<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Rack And Pinions in Bahrain, M1.5 M2 M3 Gear Rack in Multan<\/div>\n<div class=\"alpha-text1\">Export to: Bahrain, Luxembourg, Zapopan, Berlin etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of tower crane joystick,crane anemometer,zoomlion hoist,elevator roller guide Quick Details: Condition:New Place of Origin:Shanghai, China (Mainland) Brand Name:shipping container lift Model Number:shipping container liftM4 <\/p>","protected":false},"author":1,"featured_media":359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[9049,9052,9051,9048,6589,9050],"class_list":["post-2952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-c45-steel-gear-rack-in-istanbul","tag-delrin-spur-gears-in-zapopan","tag-m1-5-m2-m3-gear-rack-in-multan","tag-rack-and-pinions-in-bahrain","tag-starter-drive-pinion","tag-steel-material-gear-rack-and-pinion-in-luxembourg"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/comments?post=2952"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media\/359"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media?parent=2952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/categories?post=2952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/tags?post=2952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}