{"id":2908,"date":"2017-05-25T11:43:11","date_gmt":"2017-05-25T11:43:11","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/hoist-2-tons-invertor-construction-hoist.html"},"modified":"2017-05-25T11:43:11","modified_gmt":"2017-05-25T11:43:11","slug":"hoist-2-tons-invertor-construction-hoist","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/pt\/hoist-2-tons-invertor-construction-hoist.html","title":{"rendered":"hoist 2 tons Invertor Construction hoist"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale11.jpg\" alt=\"hoist 2 tons Invertor Construction hoist\" \/><br \/>\nImage of hoist 2 tons Invertor Construction hoist<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200, SC100\/100<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cremalheira<\/li>\n<li>Peso m\u00e1ximo de eleva\u00e7\u00e3o: 2*2000kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 250M<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 0-63 m\/min<\/li>\n<li>Certifica\u00e7\u00e3o: CE SGS ISO9001:2008<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Dimens\u00e3o da gaiola: 3*1,5*2,4<\/li>\n<li>Forma da Viga Principal: Viga Dupla<\/li>\n<li>Tipo de movimenta\u00e7\u00e3o: cremalheira e engrenagem<\/li>\n<li>Gaiola: Gaiola dupla\/gaiola simples<\/li>\n<li>Dimens\u00e3o da se\u00e7\u00e3o do mastro: 800*800*1508\/650*650*1508<\/li>\n<li>n\u00famero de passageiros: 2*16<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pOTZvcU1LR1BkNUk\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale233.jpg\" alt=\"hoist 2 tons Invertor Construction hoist\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale79.jpg\" alt=\"hoist 2 tons Invertor Construction hoist\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale479.jpg\" alt=\"hoist 2 tons Invertor Construction hoist\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale432.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction Hoist Gear Rack Autogate Gear Rack<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Sucesso N\u00ba: M1 M2 M3 M4 M5 M6 M7 M8 M9 M10<\/li>\n<li>Aplica\u00e7\u00e3o: Uso na constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Cor: Preto<\/li>\n<li>Processamento: Fresamento CNC e Hobbing<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Weight: About 23.8 Kg<\/li>\n<li>Origem: Xangai<\/li>\n<li>Tipo: Plataforma Elevat\u00f3ria<\/li>\n<li>Tipo de eslinga: cabo de a\u00e7o<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001: 2000<\/li>\n<li>Forma: Engrenagem de cremalheira<\/li>\n<li>Molde: M8<\/li>\n<li>Material: A\u00e7o<\/li>\n<li>Usage: Lifts<\/li>\n<li>Name: Construction Hoist Gear Rack<\/li>\n<li>Especifica\u00e7\u00e3o: SGS<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Pinion Gear in Chicago, G60 Steel Gear Rack<\/div>\n<div class=\"alpha-text1\">Export to: Chicago, Egypt, Mexico etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale198.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">SC200\/200 construction lift<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Type:Elevators, construction hoist for Passenger and materials<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200<\/li>\n<li>Usage:Residential Elevators, Special for high rise building to lift Cargo &amp; Passenger<\/li>\n<li>Tipo de acionamento: cremalheira e pinh\u00e3o<\/li>\n<li>Tipo de elevador: Elevadores de mercadorias<\/li>\n<li>Tipo de acionamento: cremalheira e engrenagem<\/li>\n<li>Sistema el\u00e9trico principal: Schneider<\/li>\n<li>Certificado de qualidade: ISO9000:2008, CE<\/li>\n<li>Servi\u00e7o: Instala\u00e7\u00e3o, comissionamento, manuten\u00e7\u00e3o, treinamento operacional<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Acabamento em forno, Zincagem a quente<\/li>\n<li>Cor: Vermelho\/laranja\/azul\/sua exig\u00eancia<\/li>\n<li>Pot\u00eancia do motor: 3*11kw, 2*11kw, 2*15kw, 2*13kw<\/li>\n<li>Voltagem\/Frequ\u00eancia: 380v\/50hz Pode ser alterado conforme sua necessidade<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Gear Rack For Construction in Egypt, Black Treatment Gear Rack in Mexico<\/div>\n<div class=\"alpha-text1\">Export to: Quito, Venezuela etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale346.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">SC200 Construction tools hoist winch electric lifts<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200<\/li>\n<li>Rated Loading Capacity(kg):4t<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 0-63 m\/min<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150m\/250m<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Padr\u00e3o da se\u00e7\u00e3o do mastro: 1,508*0,65*0,65m\/1,508*0,8*0,8m<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001, CE, SGS, BV, Padr\u00e3o Internacional da Coreia<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150m, 250m<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 0-33m\/min-55m\/min-63m\/min<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de opera\u00e7\u00e3o acionada: Cremalheira e engrenagem<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Acabamento de cozimento, Galvaniza\u00e7\u00e3o<\/li>\n<li>Pot\u00eancia do motor: 11kw, 13kw, 15kw<\/li>\n<li>Padr\u00e3o da gaiola: 3*1,3\/1,5*2,2m<\/li>\n<li>Cor: Vermelho\/Azul\/Laranja (pode ser personalizado de acordo com sua necessidade)<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: M1 Construction Hoist Gear Rack in Quito, Supplier Rack M2 M3 M4 M5 M6 M8 M10 For Gear Rack in Venezuela<\/div>\n<div class=\"alpha-text1\">Export to: Navi Mumbai, Prague, St. Louis, Chicago etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale464.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Standard metal rack and pinion gears with high<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Tipo: Pe\u00e7as de Elevador<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: M8\/M5\/M6<\/li>\n<li>Dimens\u00e3o: 650*650*1505<\/li>\n<li>material: a\u00e7o estrutural A3<\/li>\n<li>estoque:Rico<\/li>\n<li>Tubo: 3\u00d73\/16 pol.<\/li>\n<li>\u00c2ngulos dobrados: 1\/4 pol.<\/li>\n<li>Aparelhos: 7\/8 pol.<\/li>\n<li>Material do rack: a\u00e7o estrutural A3<\/li>\n<li>tipo: pe\u00e7as de elevador de guindaste de torre<\/li>\n<li>elevador de torre: pe\u00e7as do elevador<\/li>\n<li>se\u00e7\u00e3o do mastro: pe\u00e7as do elevador<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: G60 Steel Gear Rack, Supplier Rack M2 M3 M4 M5 M6 M8 M10 For Gear Rack in Venezuela<\/div>\n<div class=\"alpha-text1\">Export to: Saint Petersburg, Timor-Leste, St. Louis, Navi Mumbai etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale114.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Customized Brass Worm Gear and Shaft Worm Wheel<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: 11kw\/15KW\/18KW<\/li>\n<li>Application: Textile Machinery, Garment Machinery, Conveyer Equipment, Packaging Machinery, Electric Cars, Motorcycle, Food Machinery, Marine, Mining Equipment, Agricultural Machinery, Car, Reducer<\/li>\n<li>Head: Multiple-Head<\/li>\n<li>Type: Worm and Wormwheel<\/li>\n<li>Local de origem: China<\/li>\n<li>Precision: G5 &#8211; G6<\/li>\n<li>Pressure Angle: 20\/40\/50\/60 Customized<\/li>\n<li>Material: A\u00e7o inoxid\u00e1vel<\/li>\n<li>Manipula\u00e7\u00e3o de Maneira: Manipula\u00e7\u00e3o For\u00e7ada<\/li>\n<li>Pacote de transporte: Pacote de madeira, dispon\u00edvel para transporte mar\u00edtimo e a\u00e9reo<\/li>\n<li>Origem: China<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Spiral Line: Right-Handed Rotation<\/li>\n<li>Reference Surface: Toroidal Surface<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Success Number: No Success<\/li>\n<li>Tipo de dente: reto\/espiral\/esquadria<\/li>\n<li>Test Equipment: Projector<\/li>\n<li>Dureza: Endurecido<\/li>\n<li>De: Sucesso<\/li>\n<li>Especifica\u00e7\u00e3o: M1-M20<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Pinion Gear in Chicago, M1 Construction Hoist Gear Rack in Quito<\/div>\n<div class=\"alpha-text1\">Export to: Chicago, Mexico, Venezuela, Prague etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of hoist 2 tons Invertor Construction hoist Quick Details: Condition:New Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:SC200\/200,SC100\/100 Usage:Construction Hoist Power Source:Electric Sling <\/p>","protected":false},"author":1,"featured_media":118,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[8844,2226,8843,8845,8842,8846],"class_list":["post-2908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-black-treatment-gear-rack-in-mexico","tag-g60-steel-gear-rack","tag-gear-rack-for-construction-in-egypt","tag-m1-construction-hoist-gear-rack-in-quito","tag-pinion-gear-in-chicago","tag-supplier-rack-m2-m3-m4-m5-m6-m8-m10-for-gear-rack-in-venezuela"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/comments?post=2908"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media\/118"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media?parent=2908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/categories?post=2908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/tags?post=2908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}