{"id":2874,"date":"2017-05-25T22:53:29","date_gmt":"2017-05-25T22:53:29","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/gjj-electric-powered-sc200-sc200200-construction-hoist.html"},"modified":"2017-05-25T22:53:29","modified_gmt":"2017-05-25T22:53:29","slug":"gjj-electric-powered-sc200-sc200200-construction-hoist","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/pt\/gjj-electric-powered-sc200-sc200200-construction-hoist.html","title":{"rendered":"GJJ Electric Powered SC200, SC200\/200 Construction Hoist"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale388.jpg\" alt=\"GJJ Electric Powered SC200, SC200\/200 Construction Hoist\" \/><br \/>\nImage of GJJ Electric Powered SC200, SC200\/200 Construction Hoist<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200, SC100\/100<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cremalheira<\/li>\n<li>Peso m\u00e1ximo de eleva\u00e7\u00e3o: 2*2000kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 250M<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 0-63 m\/min<\/li>\n<li>Certifica\u00e7\u00e3o: CE SGS ISO9001:2008<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Dimens\u00e3o da gaiola: 3*1,5*2,4<\/li>\n<li>Forma da Viga Principal: Viga Dupla<\/li>\n<li>Tipo de movimenta\u00e7\u00e3o: cremalheira e engrenagem<\/li>\n<li>Gaiola: Gaiola dupla\/gaiola simples<\/li>\n<li>Dimens\u00e3o da se\u00e7\u00e3o do mastro: 800*800*1508\/650*650*1508<\/li>\n<li>n\u00famero de passageiros: 2*16<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pOV9EVUV5cWd2R0k\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale34.jpg\" alt=\"GJJ Electric Powered SC200, SC200\/200 Construction Hoist\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale226.jpg\" alt=\"GJJ Electric Powered SC200, SC200\/200 Construction Hoist\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale190.jpg\" alt=\"GJJ Electric Powered SC200, SC200\/200 Construction Hoist\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale19.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction Hoist Spare Parts Bolt<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Tipo: Plataforma Elevat\u00f3ria<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Warranty: 1year<\/li>\n<li>Porto de Carregamento: Xangai<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Origem: Xangai<\/li>\n<li>Aplica\u00e7\u00e3o: Uso na constru\u00e7\u00e3o<\/li>\n<li>Marca: Sucesso<\/li>\n<li>Color: Silver<\/li>\n<li>Tipo de eslinga: cabo de a\u00e7o<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001: 2000<\/li>\n<li>Especifica\u00e7\u00e3o: SGS<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Precision Rack Gears in Adelaide, Electric Motor Gear Rack<\/div>\n<div class=\"alpha-text1\">Export to: Adelaide, Dominican Republic, \u0130zmir etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale285.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">China made building lift price<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: Elevador de constru\u00e7\u00e3o SC200\/200<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo<\/li>\n<li>Peso m\u00e1ximo de eleva\u00e7\u00e3o: 2000 kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 250 m<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 33 m\/min<\/li>\n<li>Certifica\u00e7\u00e3o: CE, ISO, GOST<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Type:Construction building lift for Passenger and materials<\/li>\n<li>Certificado: CE, ISO, GOST<\/li>\n<li>Tipo de acionamento: Engrenagem e cremalheira<\/li>\n<li>Sistema el\u00e9trico principal: Schneider<\/li>\n<li>Pot\u00eancia do motor: 3*11kw, 2*13kw, 2*11kw, 2*15kw<\/li>\n<li>Voltagem\/Frequ\u00eancia: 380v\/50Hz<\/li>\n<li>Cor: Vermelho\/laranja\/azul<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: M1 Construction Hoist Gear Rack in Dominican Republic, G60 Gear Rack in \u0130zmir<\/div>\n<div class=\"alpha-text1\">Export to: Oman, Vietnam etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale133.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Ce Approval Success Passenger and Material Hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca: Elevador de constru\u00e7\u00e3o\/elevador de materiais de constru\u00e7\u00e3o\/elevador\/material de constru\u00e7\u00e3o<\/li>\n<li>Model Number:Construction elevator CE Aprroved<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo<\/li>\n<li>Peso m\u00e1ximo de eleva\u00e7\u00e3o: 1T-20T<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150M<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 36M\/MIN<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001:2008<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Tower Crane Type:2 ton construction hoist<\/li>\n<li>SC200\/200::2 ton construction hoist<\/li>\n<li>Tipo de movimenta\u00e7\u00e3o: cremalheira e engrenagem<\/li>\n<li>Forma da Viga Principal: Viga Dupla<\/li>\n<li>Gaiola: Gaiola dupla (com opera\u00e7\u00e3o<\/li>\n<li>Main Electrical System:Schneider 2 ton construction hoist<\/li>\n<li>Installation:Assembled 2 ton construction hoist<\/li>\n<li>Comprimento ajust\u00e1vel da amarra\u00e7\u00e3o de parede e quantidade: 2,8-3,2 m 1 pe\u00e7a\/5 mastros<\/li>\n<li>Dimens\u00e3o da gaiola: 3*1,5*2,2 m, 3*1,3*2,2 m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Starter Clutch Gear in Oman, Tooth Gear Rack in Vietnam<\/div>\n<div class=\"alpha-text1\">Export to: Kalyan-Dombivali, Birmingham, Adelaide, Adelaide etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale476.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">construction hoist motor used for lifter,plastic rack and pinion gears<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:RB15060101<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Place of origin:china<\/li>\n<li>Private label:available<\/li>\n<li>Power:11KW, 15KW, 18KW<\/li>\n<li>Brand name:Success<\/li>\n<li>Model number:Success motor<\/li>\n<li>Usage:Construction hoist<\/li>\n<li>Source:Eletric<\/li>\n<li>Sling type:Cable<\/li>\n<li>Lifting weight:2T and more<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Electric Motor Gear Rack, Tooth Gear Rack in Vietnam<\/div>\n<div class=\"alpha-text1\">Export to: Senegal, Durban, Adelaide, Kalyan-Dombivali etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale42.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">All Kinds of Racks for Construction Building Hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Sucesso N\u00ba: M5\/M8\/M10<\/li>\n<li>Dureza: Superf\u00edcie do dente endurecida<\/li>\n<li>M\u00e9todo de fabrica\u00e7\u00e3o: Engrenagem fundida<\/li>\n<li>Material: A\u00e7o inoxid\u00e1vel<\/li>\n<li>Sucesso: M5, M8, M10<\/li>\n<li>Tipo de eslinga: cremalheira<\/li>\n<li>Pacote de transporte: caixa de madeira<\/li>\n<li>Origem: China<\/li>\n<li>Application: Motor, Electric Cars, Motorcycle, Machinery, Marine, Toy, Agricultural Machinery, Car, Construction Hoist<\/li>\n<li>Posi\u00e7\u00e3o da engrenagem: Engrenagem externa<\/li>\n<li>Formato da por\u00e7\u00e3o dentada: Engrenagem reta<\/li>\n<li>Tipo: Cremalheira de engrenagens<\/li>\n<li>Tamanho: 40*60*1508,50*50*1508<\/li>\n<li>De: Sucesso<\/li>\n<li>Especifica\u00e7\u00e3o: M5, M8, M10<\/li>\n<li>C\u00f3digo SH: 8431390000<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Precision Rack Gears in Adelaide, Starter Clutch Gear in Oman<\/div>\n<div class=\"alpha-text1\">Export to: Adelaide, \u0130zmir, Vietnam, Birmingham etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of GJJ Electric Powered SC200, SC200\/200 Construction Hoist Quick Details: Condition:New Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:SC200\/200,SC100\/100 Usage:Construction Hoist Power Source:Electric <\/p>","protected":false},"author":1,"featured_media":230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3312,8678,8677,8676,8679,8680],"class_list":["post-2874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-electric-motor-gear-rack","tag-g60-gear-rack-in-izmir","tag-m1-construction-hoist-gear-rack-in-dominican-republic","tag-precision-rack-gears-in-adelaide","tag-starter-clutch-gear-in-oman","tag-tooth-gear-rack-in-vietnam"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/comments?post=2874"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media\/230"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media?parent=2874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/categories?post=2874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/tags?post=2874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}